

{"id":6076,"date":"2023-09-29T09:31:16","date_gmt":"2023-09-29T12:31:16","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/social\/aviso-de-licitacao-publica-pregao-eletronico-no-24-2023\/"},"modified":"2023-09-29T09:31:16","modified_gmt":"2023-09-29T12:31:16","slug":"aviso-de-licitacao-publica-pregao-eletronico-no-24-2023","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/social\/aviso-de-licitacao-publica-pregao-eletronico-no-24-2023\/","title":{"rendered":"AVISO DE LICITA\u00c7\u00c3O P\u00daBLICA PREG\u00c3O ELETR\u00d4NICO N\u00ba 24\/2023"},"content":{"rendered":"<p align=\"center\"><strong>AVISO DE JULGAMENTO DE LICITA&Ccedil;&Atilde;O<\/strong><br \/>\n<strong>PREG&Atilde;O ELETR&Ocirc;NICO N&ordm; 24\/2023 &#8211; SEDS<\/strong><\/p>\n<p>A Ger&ecirc;ncia de Compras Governamentais da Secretaria de Estado de Desenvolvimento Social &#8211; SEDS torna p&uacute;blico aos interessados que o PREG&Atilde;O ELETR&Ocirc;NICO N&deg; 24\/2023 &#8211; SEDS, Processo N&ordm; 202310319001449, referente &agrave; aquisi&ccedil;&atilde;o de bens m&oacute;veis para equipar alojamentos dos servidores lotados nas unidades socioeducativas do Estado de Goi&aacute;s, foi HOMOLOGADO &agrave;s empresas: SM DA SILVA- SOLU&Ccedil;&Otilde;ES para o LOTE 01, no valor total de R$ 145.999,23, e A EMBAIXADORA COMERCIAL E SERVI&Ccedil;OS LTDA. para o lote 02, no valor total de R$ R$ 27.000,00. Com rela&ccedil;&atilde;o ao Lote 03 a sess&atilde;o foi deserta.<\/p>\n<p align=\"center\">Goi&acirc;nia, 27 de novembro de 2023.<br \/>\nThiago Mendon&ccedil;a Valad&atilde;o<br \/>\nPregoeiro<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Objeto:<\/strong>&nbsp;Aquisi&ccedil;&atilde;o de bens m&oacute;veis para equipar alojamentos dos servidores lotados nas unidades socioeducativas por for&ccedil;a de A&ccedil;&atilde;o Civil P&uacute;blica.&nbsp;Processo: 5096041-03.2016.8.09.005.<\/p>\n<p><!--more--><\/p>\n<p><strong>Processo n&ordm;<\/strong>.: 202310319001449<\/p>\n<p><strong>Modalidade \/ Forma<\/strong>: Preg&atilde;o Eletr&ocirc;nico.<\/p>\n<p><strong>Participa&ccedil;&atilde;o:<\/strong> Mista &#8211; Lote com disputa para ampla participa&ccedil;&atilde;o com cota reservada para Micro Empresa, EPP ou as assim consideradas nos termos do art. 3&ordm;, da Lei Complementar N&ordm; 123\/2006 (nos termos do Art. 9 da Lei Estadual 17.928\/2012), e Lote para disputa exclusiva para participa&ccedil;&atilde;o de Micro Empresa, EPP ou as assim consideradas nos termos do art. 3&ordm;, da Lei Complementar N&ordm; 123\/2006.<\/p>\n<p><strong>Crit&eacute;rio de Julgamento:<\/strong> Menor Pre&ccedil;o por Lote.<\/p>\n<p><strong>Data e hor&aacute;rio da sess&atilde;o de abertura<\/strong>:&nbsp;16 de outubro de 2023, &agrave;s 09:00 horas (hor&aacute;rio de Bras&iacute;lia).<\/p>\n<p><strong>Local (s&iacute;tio)<\/strong>: <a href=\"http:\/\/www.comprasnet.go.gov.br\">www.comprasnet.go.gov.br<\/a>.<\/p>\n<p><strong>Fonte:<\/strong> Recurso Estadual.<\/p>\n<p><strong>Edital:<\/strong>&nbsp;Poder&aacute; ser obtido no s&iacute;tio da Secretaria Estadual de Desenvolvimento Social <a href=\"http:\/\/www.comprasnet.go.gov.br\">www.social.go.gov.br<\/a> ou no s&iacute;tio <a href=\"http:\/\/www.comprasnet.go.gov.br\">www.comprasnet.go.gov.br<\/a>.<\/p>\n<p><strong>Email da Ger&ecirc;ncia de Compras Governamentais:<\/strong>&nbsp;<a href=\"mailto:licitacao.seds@goias.gov.br\">licitacao.seds@goias.gov.br<\/a><\/p>\n<p>Goi&acirc;nia\/GO, 29&nbsp;de setembro de 2023.<\/p>\n<p><a href=\"http:\/\/goias.gov.br\/social\/wp-content\/uploads\/sites\/24\/2023\/09\/2023_24_edital-4d9.pdf\" id=\"\" style=\"\" target=\"\" title=\"\" rel=\"noopener\">CLIQUE AQUI PARA TER ACESSO AO EDITAL DO&nbsp;PREG&Atilde;O ELETR&Ocirc;NICO N&ordm; 24\/2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVISO DE JULGAMENTO DE LICITA&Ccedil;&Atilde;O PREG&Atilde;O ELETR&Ocirc;NICO N&ordm; 24\/2023 &#8211; SEDS A Ger&ecirc;ncia de Compras Governamentais da Secretaria de Estado de Desenvolvimento Social &#8211; SEDS torna p&uacute;blico aos interessados que o PREG&Atilde;O ELETR&Ocirc;NICO N&deg; 24\/2023 &#8211; SEDS, Processo N&ordm; 202310319001449, referente &agrave; aquisi&ccedil;&atilde;o de bens m&oacute;veis para equipar alojamentos dos servidores lotados nas unidades socioeducativas [&hellip;]<\/p>\n","protected":false},"author":273,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-6076","post","type-post","status-publish","format-standard","hentry","category-licitacoes-e-contratos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"renanrigo","author_link":"https:\/\/goias.gov.br\/social\/author\/renanrigo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/social\/categoria\/licitacoes-e-contratos\/\" rel=\"category tag\">Licita\u00e7\u00f5es e Contratos<\/a>","rttpg_excerpt":"AVISO DE JULGAMENTO DE LICITA&Ccedil;&Atilde;O PREG&Atilde;O ELETR&Ocirc;NICO N&ordm; 24\/2023 &#8211; SEDS A Ger&ecirc;ncia de Compras Governamentais da Secretaria de Estado de Desenvolvimento Social &#8211; SEDS torna p&uacute;blico aos interessados que o PREG&Atilde;O ELETR&Ocirc;NICO N&deg; 24\/2023 &#8211; SEDS, Processo N&ordm; 202310319001449, referente &agrave; aquisi&ccedil;&atilde;o de bens m&oacute;veis para equipar alojamentos dos servidores lotados nas unidades socioeducativas&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/posts\/6076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/users\/273"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/comments?post=6076"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/posts\/6076\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/media?parent=6076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/categories?post=6076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/social\/wp-json\/wp\/v2\/tags?post=6076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}