{"id":93256,"date":"2023-12-14T08:50:20","date_gmt":"2023-12-14T11:50:20","guid":{"rendered":"https:\/\/www.seguranca.go.gov.br\/?p=93256"},"modified":"2023-12-14T08:50:20","modified_gmt":"2023-12-14T11:50:20","slug":"termo-de-homologacao-e-adjudicacao-da-tomada-de-precos-no-02-2023-pmgo","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/seguranca\/termo-de-homologacao-e-adjudicacao-da-tomada-de-precos-no-02-2023-pmgo\/","title":{"rendered":"TERMO DE HOMOLOGA\u00c7\u00c3O E ADJUDICA\u00c7\u00c3O DA  TOMADA DE PRE\u00c7OS N\u00ba 02\/2023 &#8211; PMGO"},"content":{"rendered":"<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">O Comandante-Geral da PMGO, no exerc\u00edcio da compet\u00eancia conferida pela Lei Estadual n\u00ba 8.125 de 18 de junho de 1976 e o Secret\u00e1rio de Estado da Seguran\u00e7a P\u00fablica de Goi\u00e1s, no exerc\u00edcio da compet\u00eancia conferida pelo Decreto Estadual n\u00ba 9.690 de 06 de julho de 2020, no uso de suas atribui\u00e7\u00f5es legais e em cumprimento ao disposto no Art. 43, inciso VI da Lei Federal n\u00ba 8.666, de 21 de Junho de 1993, tendo em vista o Processo Administrativo n\u00ba 202300002099344, HOMOLOGA a Tomada de Pre\u00e7os n\u00ba 02\/2023\/PMGO, referente \u00e0 Contrata\u00e7\u00e3o de empresa especializada na realiza\u00e7\u00e3o de obras e servi\u00e7os t\u00e9cnicos de engenharia visando \u00e0 constru\u00e7\u00e3o da sede da 9\u00aa Companhia Independente de Pol\u00edcia Militar &#8211; 9\u00aa CIPM\/CPE &#8211; 16\u00ba CRPM no munic\u00edpio de Trindade\/GO, ADJUDICANDO-O \u00e0 empresa LKA ENGENHARIA LTDA, CNPJ n\u00ba: 40.343.100\/0001-35, no valor total de R$ 1.193.000,00 (um milh\u00e3o, cento e noventa e tr\u00eas mil reais), conforme atas de reuni\u00e3o da Comiss\u00e3o Permanente de Licita\u00e7\u00e3o da PMGO, a saber, Ata de abertura dos envelope de habilita\u00e7\u00e3o (53089811), Ata do resultado de habilita\u00e7\u00e3o (53589218), Ata de abertura dos envelopes contendo as Propostas (54213982), Ata de Julgamento e Classifica\u00e7\u00e3o da Proposta de Pre\u00e7os (54315755), Declara\u00e7\u00e3o do vencedor (54736457) e demais documentos acostados aos autos.<\/span><\/span><\/p>\n<p class=\"western\" align=\"right\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">Goi\u00e2nia, aos 12 dias do m\u00eas de dezembro de 2023.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">ANDR\u00c9 HENRIQUE AVELAR DE SOUSA \u2013 CORONEL PM<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">Comandante-Geral da PMGO<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">RENATO BRUM DOS SANTOS<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\"><span style=\"font-family: Arial, sans-serif\"><span style=\"font-size: medium\">Secret\u00e1rio de Estado da Seguran\u00e7a P\u00fablica<\/span><\/span><\/p>\n<p style=\"text-align: left\" align=\"center\">ARQUIVOS PDF:<\/p>\n<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/goias.gov.br\/seguranca\/wp-content\/uploads\/sites\/56\/2023\/12\/02.-termo-de-homologacao-tomada-de-precos-no-02-2023-construcao-da-sede-da-9a-cipm-cpe-16o-crpm-doe.pdf\" target=\"_blank\" rel=\"noopener\">Termo de Homologa\u00e7\u00e3o &#8211; Tomada de Pre\u00e7os n\u00ba 02-2023 &#8211; Constru\u00e7\u00e3o da sede da 9\u00aa CIPM-CPE &#8211; 16\u00ba CRPM &#8211; DOE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Comandante-Geral da PMGO, no exerc\u00edcio da compet\u00eancia conferida pela Lei Estadual n\u00ba 8.125 de 18 de junho de 1976 e o Secret\u00e1rio de Estado da Seguran\u00e7a P\u00fablica de Goi\u00e1s, no exerc\u00edcio da compet\u00eancia conferida pelo Decreto Estadual n\u00ba 9.690 de 06 de julho de 2020, no uso de suas atribui\u00e7\u00f5es legais e em cumprimento [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[13,15],"tags":[],"class_list":["post-93256","post","type-post","status-publish","format-standard","hentry","category-editais-pm","category-termo-de-homologacao-pm"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"joanaredator","author_link":"https:\/\/goias.gov.br\/seguranca\/author\/joanaredator\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/seguranca\/categoria\/editais-pm\/\" rel=\"category tag\">Editais PM<\/a> <a href=\"https:\/\/goias.gov.br\/seguranca\/categoria\/termo-de-homologacao-pm\/\" rel=\"category tag\">Termo de Homologa\u00e7\u00e3o<\/a>","rttpg_excerpt":"O Comandante-Geral da PMGO, no exerc\u00edcio da compet\u00eancia conferida pela Lei Estadual n\u00ba 8.125 de 18 de junho de 1976 e o Secret\u00e1rio de Estado da Seguran\u00e7a P\u00fablica de Goi\u00e1s, no exerc\u00edcio da compet\u00eancia conferida pelo Decreto Estadual n\u00ba 9.690 de 06 de julho de 2020, no uso de suas atribui\u00e7\u00f5es legais e em cumprimento&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/93256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/comments?post=93256"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/93256\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/media?parent=93256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/categories?post=93256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/tags?post=93256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}