{"id":266489,"date":"2025-01-28T14:53:12","date_gmt":"2025-01-28T17:53:12","guid":{"rendered":"https:\/\/goias.gov.br\/seguranca\/?p=266489"},"modified":"2025-01-28T14:54:18","modified_gmt":"2025-01-28T17:54:18","slug":"portaria-no-82-25-convoca-pm-da-reserva-para-servico-ativo-subtenente-pm-celio-bonifacio-dos-santos","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/seguranca\/portaria-no-82-25-convoca-pm-da-reserva-para-servico-ativo-subtenente-pm-celio-bonifacio-dos-santos\/","title":{"rendered":"PORTARIA N\u00ba 82-25 &#8211; Convoca PM da Reserva para servi\u00e7o ativo &#8211; Subtenente PM C\u00c9LIO BONIF\u00c1CIO DOS SANTOS"},"content":{"rendered":"<p class=\"Tabela_Texto_Centralizado\" style=\"text-align: center\">PORTARIA N\u00ba\u00a082, DE\u00a024 DE\u00a0janeiro DE\u00a02025<\/p>\n<p class=\"Texto_Ementa\" style=\"text-align: center\">Convoca militar da reserva remunerada para o servi\u00e7o ativo.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\"><b>O SECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA<\/b>, no uso da compet\u00eancia que lhe foi delegada pelo art. 1\u00ba, incisos II, do Decreto estadual n\u00ba 9.382, de 8 de janeiro de 2019; considerando a Lei estadual n\u00ba 8.033, de 2 de dezembro de 1975; em especial o disposto na Lei estadual n\u00ba 20.763, de 30 de janeiro de 2020, regulamentada pelo Decreto n\u00ba 9.681, de 24 de junho de 2020, e o que consta no Processo SEI n\u00ba\u00a0202500006008639, resolve:<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 1\u00ba\u00a0\u00a0Convocar o Policial Militar da Reserva Subtenente QPPM *323* C\u00c9LIO BONIF\u00c1CIO DOS SANTOS, inscrito no CPF n\u00ba\u00a0***.371.021-**,\u00a0para o servi\u00e7o ativo, sendo conveniente o retorno do militar para o servi\u00e7o p\u00fablico, em car\u00e1ter transit\u00f3rio, com o prazo n\u00e3o superior a 2 (dois) anos, admitida prorroga\u00e7\u00e3o por igual per\u00edodo, conforme interesse da Administra\u00e7\u00e3o,\u00a0at\u00e9 que o militar atinja as idades-limite dispostas no art. 6\u00ba da Lei estadual n\u00ba 20.946, de 30 de dezembro de 2020.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 2\u00ba\u00a0 Estipular que o Militar da Reserva Remunerada convocado nos termos desta Portaria, e especialmente em observ\u00e2ncia ao previsto na Lei estadual n\u00ba 20.763, de 2020, regulamentada pelo Decreto n\u00ba 9.681, de 2020, ter\u00e1 os direitos e deveres dos da ativa de igual situa\u00e7\u00e3o hier\u00e1rquica, exceto quanto \u00e0 promo\u00e7\u00e3o, a qual n\u00e3o concorrer\u00e1, submetendo-se \u00e0s regras e aos deveres da disciplina e da hierarquia militar.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 3\u00ba\u00a0 Definir que o Militar convocado por meio desta Portaria far\u00e1 jus \u00e0 indeniza\u00e7\u00e3o de convoca\u00e7\u00e3o mensal em percentual que incidir\u00e1 sobre o que percebe na ativa, nos limites definidos no art. 3\u00ba da Lei estadual n\u00ba 20.763, de 2020, regulamentada pelo Decreto n\u00ba 9.681, de 2020, e esta n\u00e3o integrar\u00e1 a base de c\u00e1lculo para a concess\u00e3o de qualquer vantagem pecuni\u00e1ria\/incorpora\u00e7\u00e3o aos proventos, inclusive para efeito de reforma, transfer\u00eancia\/retorno para a Reserva Remunerada e contribui\u00e7\u00e3o previdenci\u00e1ria do Sistema de Prote\u00e7\u00e3o Social dos Militares.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 4\u00ba\u00a0 Determinar o encaminhamento desta Portaria ao Comando-Geral da Pol\u00edcia Militar do Estado de Goi\u00e1s para conhecimento e demais provid\u00eancias que o caso requer.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 5\u00ba\u00a0 Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o.<\/p>\n<p><a href=\"https:\/\/goias.gov.br\/seguranca\/wp-content\/uploads\/sites\/56\/2025\/01\/PORTARIA-No-82-DE-24-DE-JANEIRO-DE-2025.pdf\">PORTARIA N\u00ba 82, DE 24 DE JANEIRO DE 2025<\/a><\/p>\n<p class=\"Texto_Centralizado\" style=\"text-align: center\">RENATO BRUM DOS SANTOS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PORTARIA N\u00ba\u00a082, DE\u00a024 DE\u00a0janeiro DE\u00a02025 Convoca militar da reserva remunerada para o servi\u00e7o ativo. O SECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA, no uso da compet\u00eancia que lhe foi delegada pelo art. 1\u00ba, incisos II, do Decreto estadual n\u00ba 9.382, de 8 de janeiro de 2019; considerando a Lei estadual n\u00ba 8.033, de 2 de dezembro [&hellip;]<\/p>\n","protected":false},"author":479,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[12],"tags":[],"class_list":["post-266489","post","type-post","status-publish","format-standard","hentry","category-portarias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Robson (SSP\/GO)","author_link":"https:\/\/goias.gov.br\/seguranca\/author\/robsonxavier\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/seguranca\/categoria\/portarias\/\" rel=\"category tag\">Portarias<\/a>","rttpg_excerpt":"PORTARIA N\u00ba\u00a082, DE\u00a024 DE\u00a0janeiro DE\u00a02025 Convoca militar da reserva remunerada para o servi\u00e7o ativo. O SECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA, no uso da compet\u00eancia que lhe foi delegada pelo art. 1\u00ba, incisos II, do Decreto estadual n\u00ba 9.382, de 8 de janeiro de 2019; considerando a Lei estadual n\u00ba 8.033, de 2 de dezembro&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/266489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/users\/479"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/comments?post=266489"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/266489\/revisions"}],"predecessor-version":[{"id":266494,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/266489\/revisions\/266494"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/media?parent=266489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/categories?post=266489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/tags?post=266489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}