{"id":265965,"date":"2025-01-15T10:33:24","date_gmt":"2025-01-15T13:33:24","guid":{"rendered":"https:\/\/goias.gov.br\/seguranca\/?p=265965"},"modified":"2025-01-16T10:35:18","modified_gmt":"2025-01-16T13:35:18","slug":"portaria-no-41-25-designa-gestora-de-termo-de-cooperacao-tecnica-casa-civil-e-ssp-legisla-goias","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/seguranca\/portaria-no-41-25-designa-gestora-de-termo-de-cooperacao-tecnica-casa-civil-e-ssp-legisla-goias\/","title":{"rendered":"PORTARIA N\u00ba 41-25 &#8211; Designa Gestora de Termo de Coopera\u00e7\u00e3o T\u00e9cnica Casa Civil e SSP &#8211; Legisla Goi\u00e1s"},"content":{"rendered":"<p class=\"Tabela_Texto_Centralizado\" style=\"text-align: center\">PORTARIA N\u00ba\u00a041, DE\u00a013 DE\u00a0janeiro DE\u00a02025<\/p>\n<p class=\"Texto_Ementa\" style=\"text-align: center\">Designa gestora de Termo de Coopera\u00e7\u00e3o T\u00e9cnica firmado pela Secretaria de Estado da Seguran\u00e7a P\u00fablica.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\"><strong>O SUBSECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA<\/strong>, nomeado pelo Decreto de 24 de abril de 2024, publicado no Di\u00e1rio Oficial do Estado n\u00ba 24.272, no uso de suas atribui\u00e7\u00f5es legais e da compet\u00eancia conferida pela Portaria n\u00ba 0444, de 7 de maio de 2024, publicada no Di\u00e1rio Oficial do Estado de Goi\u00e1s n\u00ba 24.281, em conformidade com a Lei estadual n\u00ba 17.928, de 27 de dezembro de 2012, com fundamento no Decreto n\u00ba 10.248, de 31 de mar\u00e7o de 2023, em atendimento ao Parecer CASACIVIL\/PROCSET n\u00ba 94\/2024 (SEI n\u00ba\u00a0<span><a id=\"lnkSei71206123\" class=\"ancora_sei\" href=\"https:\/\/sei.go.gov.br\/sei\/controlador.php?acao=protocolo_visualizar&amp;id_protocolo=71206123&amp;id_procedimento_atual=69010472&amp;infra_sistema=100000100&amp;infra_unidade_atual=2896&amp;infra_hash=cf59e5df04c17fb8b64b07e8be427ec7f3bc61b300effa180d95a46e96593af866c8821a63c92302431226c804add4acd01cd8263dbaa1dbcdcdba32fc56c157ad398918073d8f645efeecf8324f457414c1d6aff0e83f05249e1aa6cbb9c054\" target=\"_blank\" rel=\"noopener\">68617631<\/a><\/span>) e considerando o Processo SEI n\u00ba 202400013002115, resolve:<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 1\u00ba\u00a0 Designar, como representante da Secretaria de Estado da Seguran\u00e7a P\u00fablica do Estado de Goi\u00e1s \u2013 SSP, a militar BEATRIZ DE ASSIS FERNANDES RORIZ, inscrita no CPF n\u00ba ***.977.721-**, 1\u00ba Tenente do Quadro de Pessoal da Pol\u00edcia Militar do Estado de Goi\u00e1s, ocupante do cargo de Gerente da Secretaria-Geral da SSP, para atuar como Gestora do Termo de Coopera\u00e7\u00e3o T\u00e9cnica a ser celebrado entre o Estado de Goi\u00e1s, por interm\u00e9dio da Secretaria de Estado da Casa Civil \u2013 CASA CIVIL, e esta Secretaria de Estado da Seguran\u00e7a P\u00fablica \u2013 SSP, cujo objeto \u00e9 a concess\u00e3o tempor\u00e1ria de perfil de acesso \u00e0 plataforma LEGISLA GOI\u00c1S, mediante a disponibiliza\u00e7\u00e3o de usu\u00e1rio e senha restritos ao &#8220;M\u00f3dulo de Atos Infralegais de Administra\u00e7\u00e3o&#8221;, sem a transfer\u00eancia de recursos financeiros e sem incluir o fornecimento ou a cess\u00e3o de equipamentos ou licen\u00e7as de\u00a0<em>softwares<\/em>\u00a0de terceiros eventualmente necess\u00e1rios \u00e0 utiliza\u00e7\u00e3o da referida plataforma pela SSP.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 2\u00ba\u00a0 Designar o militar GILNEI GIOVANNI FURTADO DE QUEIROZ, inscrito no CPF n\u00ba ***.654.201-**, ocupante do cargo de Subtenente do Quadro de Pessoal do Corpo de Bombeiros Militar, para atuar como suplente, substituindo a titular em seus impedimentos ou afastamentos legais.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 3\u00ba\u00a0 Estabelecer que, para a consecu\u00e7\u00e3o do objetivo proposto neste ato, a servidora ora designada dever\u00e1:<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">I \u2013 acompanhar a execu\u00e7\u00e3o e fiscalizar o fiel cumprimento das obriga\u00e7\u00f5es pactuadas no referido Termo de Coopera\u00e7\u00e3o sob sua gest\u00e3o;<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">II \u2013 observar e fazer cumprir o prazo de vig\u00eancia do Termo; e<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">III \u2013 comunicar \u00e0 autoridade competente, com anteced\u00eancia m\u00ednima de 90 (noventa) dias, a data de expira\u00e7\u00e3o da vig\u00eancia do ajuste e a eventual necessidade de prorroga\u00e7\u00e3o.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 4\u00ba\u00a0 Determinar o encaminhamento desta Portaria \u00e0 Superintend\u00eancia de Gest\u00e3o Integrada\/SSP para conhecimento e demais provid\u00eancias que o caso requer.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 5\u00ba\u00a0 Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o.<\/p>\n<p class=\"Texto_Centralizado\"><a href=\"https:\/\/goias.gov.br\/seguranca\/wp-content\/uploads\/sites\/56\/2025\/01\/PORTARIA-No-41-DE-13-DE-JANEIRO-DE-2025.pdf\">PORTARIA N\u00ba 41, DE 13 DE JANEIRO DE 2025<\/a><\/p>\n<p class=\"Texto_Centralizado\" style=\"text-align: center\">GUSTAVO CARLOS FERREIRA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PORTARIA N\u00ba\u00a041, DE\u00a013 DE\u00a0janeiro DE\u00a02025 Designa gestora de Termo de Coopera\u00e7\u00e3o T\u00e9cnica firmado pela Secretaria de Estado da Seguran\u00e7a P\u00fablica. O SUBSECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA, nomeado pelo Decreto de 24 de abril de 2024, publicado no Di\u00e1rio Oficial do Estado n\u00ba 24.272, no uso de suas atribui\u00e7\u00f5es legais e da compet\u00eancia conferida pela [&hellip;]<\/p>\n","protected":false},"author":479,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[12],"tags":[],"class_list":["post-265965","post","type-post","status-publish","format-standard","hentry","category-portarias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Robson (SSP\/GO)","author_link":"https:\/\/goias.gov.br\/seguranca\/author\/robsonxavier\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/seguranca\/categoria\/portarias\/\" rel=\"category tag\">Portarias<\/a>","rttpg_excerpt":"PORTARIA N\u00ba\u00a041, DE\u00a013 DE\u00a0janeiro DE\u00a02025 Designa gestora de Termo de Coopera\u00e7\u00e3o T\u00e9cnica firmado pela Secretaria de Estado da Seguran\u00e7a P\u00fablica. O SUBSECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA, nomeado pelo Decreto de 24 de abril de 2024, publicado no Di\u00e1rio Oficial do Estado n\u00ba 24.272, no uso de suas atribui\u00e7\u00f5es legais e da compet\u00eancia conferida pela&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/265965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/users\/479"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/comments?post=265965"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/265965\/revisions"}],"predecessor-version":[{"id":265968,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/265965\/revisions\/265968"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/media?parent=265965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/categories?post=265965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/tags?post=265965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}