{"id":265826,"date":"2025-01-13T09:40:48","date_gmt":"2025-01-13T12:40:48","guid":{"rendered":"https:\/\/goias.gov.br\/seguranca\/?p=265826"},"modified":"2025-01-14T09:55:40","modified_gmt":"2025-01-14T12:55:40","slug":"portaria-no-34-25-dgfapp-ead-ciclo-1-2025","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/seguranca\/portaria-no-34-25-dgfapp-ead-ciclo-1-2025\/","title":{"rendered":"PORTARIA N\u00ba 34-25 &#8211; DGFAPP &#8211; EAD &#8211; Ciclo 1-2025"},"content":{"rendered":"<p class=\"Tabela_Texto_Centralizado\" style=\"text-align: center\">PORTARIA N\u00ba\u00a034, DE\u00a010 DE\u00a0janeiro DE\u00a02025<\/p>\n<p class=\"Texto_Ementa\">Autoriza e homologa a realiza\u00e7\u00e3o do curso Direitos e Garantias Fundamentais Aplicados \u00e0 Pr\u00e1tica Policial \u2013 DGFAPP, em modalidade de ensino \u00e0 dist\u00e2ncia \u2013 EaD.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\"><b>O SUBSECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA<\/b>, nomeado pelo Decreto de 24 de abril de 2024, publicado no Di\u00e1rio Oficial do Estado n\u00ba 24.272, no uso de suas atribui\u00e7\u00f5es legais, e usando da compet\u00eancia que lhe confere a Portaria n\u00ba 0444, de 7 de maio de 2024, publicada no Di\u00e1rio Oficial do Estado de Goi\u00e1s n\u00ba 24.281, e tendo em vista o Processo SEI n\u00ba 202500016000504, resolve:<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 1\u00ba\u00a0 Autorizar e homologar a realiza\u00e7\u00e3o do Curso DIREITOS E GARANTIAS FUNDAMENTAIS APLICADOS \u00c0 PR\u00c1TICA POLICIAL \u2013 DGFAPP, em modalidade de Ensino \u00e0 Dist\u00e2ncia \u2013 EaD, cuja dura\u00e7\u00e3o ser\u00e1 de 60 (sessenta) horas, com o objetivo de capacita\u00e7\u00e3o de at\u00e9 80 (oitenta) profissionais da Seguran\u00e7a P\u00fablica de Goi\u00e1s.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 2\u00ba\u00a0 Fixar o seguinte curr\u00edculo e carga hor\u00e1ria para o mencionado curso:<\/p>\n<table>\n<thead>\n<tr>\n<td valign=\"top\">\n<p class=\"Tabela_Texto_Centralizado\"><b>DISCIPLINAS<\/b><\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"Tabela_Texto_Centralizado\"><b>C\/H<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<p class=\"Tabela_Texto_Centralizado\">1. Direitos e garantias fundamentais no Constitucionalismo Brasileiro<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"Tabela_Texto_Centralizado\">18h<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<p class=\"Tabela_Texto_Centralizado\">2. Racismo, igualdade de g\u00eanero, a\u00e7\u00f5es afirmativas e a atua\u00e7\u00e3o policial<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"Tabela_Texto_Centralizado\">14h<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">3. Ativismo judicial: Um novo modelo jurisdicional no Brasil<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">14h<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">4. Execu\u00e7\u00e3o penal e os direitos fundamentais<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">14h<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<p class=\"Tabela_Texto_Centralizado\"><b>TOTAL H\/A<\/b><\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"Tabela_Texto_Centralizado\"><b>60 H<\/b><\/p>\n<\/td>\n<\/tr>\n<\/thead>\n<\/table>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 3\u00ba\u00a0 Designar os seguintes servidores para atuar na atividade de magist\u00e9rio como docentes do mencionado curso:<\/p>\n<table>\n<thead>\n<tr>\n<td colspan=\"5\">\n<p class=\"Tabela_Texto_Centralizado\"><b>PROFESSORES<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">\n<p class=\"Tabela_Texto_Centralizado\"><b>Ord.<\/b><\/p>\n<\/td>\n<td rowspan=\"2\">\n<p class=\"Tabela_Texto_Centralizado\"><b>Cargo<\/b><\/p>\n<\/td>\n<td rowspan=\"2\">\n<p class=\"Tabela_Texto_Centralizado\"><b>Nome<\/b><\/p>\n<\/td>\n<td rowspan=\"2\">\n<p class=\"Tabela_Texto_Centralizado\"><b>CPF<\/b><\/p>\n<\/td>\n<td rowspan=\"2\">\n<p class=\"Tabela_Texto_Centralizado\"><b>Titula\u00e7\u00e3o<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">1<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">Agente de Pol\u00edcia Classe Especial PC<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">VIN\u00cdCIUS PINHEIRO VIEIRA DE ALC\u00c2NTARA<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">***.641.621-**<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">Especialista<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">2<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">Escriv\u00e3 de Pol\u00edcia Classe Especial PC<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">JULIANA MAGALH\u00c3ES FARIA FLEURY DE BARROS<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">***.252.971-**<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">Especialista<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"5\">\n<p class=\"Tabela_Texto_Centralizado\">A remunera\u00e7\u00e3o dos docentes ser\u00e1 efetivada de acordo com o art. 7\u00ba desta portaria.<\/p>\n<\/td>\n<\/tr>\n<\/thead>\n<\/table>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 4\u00ba\u00a0 Estabelecer que os alunos sejam matriculados na plataforma de ensino \u00e0 dist\u00e2ncia \u201cMoodle\u201d da Coordenadoria de Ensino \u2013 COE\/SSP e que o curso seja ministrado com a carga hor\u00e1ria de 60 (sessenta) horas, sendo 2 (duas) turmas de at\u00e9 40 (quarenta) alunos, no per\u00edodo de 16 de janeiro de 2025 a 8 de abril de 2025.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 5\u00ba\u00a0 Desligar o aluno que:<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">I \u2013 comportar-se de forma contr\u00e1ria aos princ\u00edpios de conviv\u00eancia pac\u00edfica e harmoniosa, desrespeitando colegas, tutores e administradores do sistema; e<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">II \u2013 deixar de possuir v\u00ednculo com a Secretaria de Estado da Seguran\u00e7a P\u00fablica de Goi\u00e1s \u2013 SSP\/GO, salvo quando autorizado pela Coordenadoria de Ensino da SSP\/GO.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 6\u00ba\u00a0 Avaliar os alunos do curso, considerando-os APROVADOS com nota igual ou superior a 70 (setenta) pontos ou REPROVADOS com nota final inferior a 70 (setenta) pontos.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 7\u00ba\u00a0 Estabelecer que os instrutores ser\u00e3o remunerados de acordo com a Lei n\u00ba 15.949, de 29 de dezembro de 2006 e a Portaria n\u00ba 1.107\/2009\/SSP, salvo quaisquer altera\u00e7\u00f5es legislativas ou administrativas nesse sentido.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Par\u00e1grafo \u00fanico. Os servidores designados far\u00e3o jus \u00e0 remunera\u00e7\u00e3o correspondente \u00e0s horas-aula ministradas durante o desenvolvimento das a\u00e7\u00f5es formativas, no decorrer das atividades letivas do Ciclo EaD 01\/2025, na Plataforma de Ensino da Rede EAD\/SSP\/GO. O valor mensal das horas trabalhadas n\u00e3o poder\u00e1 exceder o limite de R$ 700,00 (setecentos reais), sob pena de perda do valor excedente, salvo disposi\u00e7\u00e3o em contr\u00e1rio.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 8\u00ba\u00a0 Estabelecer que poder\u00e3o ser destinadas at\u00e9 10 (dez) vagas a profissionais da Seguran\u00e7a P\u00fablica pertencentes \u00e0s Institui\u00e7\u00f5es Coirm\u00e3s e Guardas Civis.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 9\u00ba\u00a0 Estabelecer como \u201cAnexo \u00danico\u201d desta Portaria o Plano de Curso \u201cDireitos e Garantias Fundamentais Aplicados \u00e0 Pr\u00e1tica Policial \u2013 DGFAPP\u201d, em modalidade \u00e0 dist\u00e2ncia, plano este que serviu de base para a elabora\u00e7\u00e3o desta Portaria.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 10.\u00a0 Designar a Coordena\u00e7\u00e3o de Ensino \u00e0 dist\u00e2ncia e Extens\u00e3o, da Coordenadoria de Ensino da Secretaria de Estado da Seguran\u00e7a P\u00fablica \u2013 COE\/SSP, para que, dentro de suas compet\u00eancias estabelecidas no artigo 6\u00ba da Portaria n\u00ba 0578\/2022 \u2013 SSP, fa\u00e7a o acompanhamento, a coordena\u00e7\u00e3o, a certifica\u00e7\u00e3o e o controle das atividades letivas desenvolvidas no ambiente virtual de aprendizagem \u2013 AVA, na Rede de Ensino \u00e0 dist\u00e2ncia da SSP\/GO, durante o Ciclo 01\/2025, prestando todo o suporte necess\u00e1rio na plataforma \u201cmoodle\u201d desta Secretaria.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 11.\u00a0 Determinar o encaminhamento desta Portaria \u00e0 Pol\u00edcia Militar, ao Corpo de Bombeiros Militar, \u00e0 Pol\u00edcia Civil, \u00e0 Diretoria-Geral de Pol\u00edcia Penal e \u00e0 Superintend\u00eancia da Pol\u00edcia T\u00e9cnico-Cient\u00edfica, para fins de conhecimento e para que conste nos assentamentos funcionais dos servidores designados como docentes.<\/p>\n<p class=\"Texto_Justificado_Recuo_Primeira_Linha\">Art. 12.\u00a0 Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o.<\/p>\n<p><a href=\"https:\/\/goias.gov.br\/seguranca\/wp-content\/uploads\/sites\/56\/2025\/01\/PORTARIA-No-34-DE-10-DE-JANEIRO-DE-2025.pdf\">PORTARIA N\u00ba 34, DE 10 DE JANEIRO DE 2025<\/a><\/p>\n<p class=\"Texto_Centralizado\" style=\"text-align: center\">GUSTAVO CARLOS FERREIRA<\/p>\n<p class=\"Tabela_Texto_8\">\n<p style=\"text-align: center\"><b>ANEXO \u00daNICO &#8211; PLANO DO CURSO DGFAPP<\/b><\/p>\n<p style=\"text-align: center\">(PORTARIA N\u00ba 34, DE 10 DE JANEIRO DE 2025)<\/p>\n<p style=\"text-align: center\">\n<p style=\"text-align: center\"><b>PLANO DE CURSO<\/b><\/p>\n<p style=\"text-align: center\">Direitos e Garantias Fundamentais Aplicados \u00e0 Pr\u00e1tica Policial \u2013 DGFAPP<\/p>\n<p>&nbsp;<\/p>\n<p>Carga Hor\u00e1ria: 60 horas<\/p>\n<p>Modalidade: \u00e0 dist\u00e2ncia<\/p>\n<p>Objetivos<br \/>\nCapacita\u00e7\u00e3o dos profissionais da Seguran\u00e7a P\u00fablica do Estado de Goi\u00e1s no curso \u201cDireitos e Garantias Fundamentais Aplicados \u00e0 Pr\u00e1tica Policial (DGFAPP)\u201d. O curso visa abordar temas latentes na sociedade, n\u00e3o s\u00f3 na sociedade brasileira, mas global. Para tanto, busca-se compreender o impacto das mudan\u00e7as sociais e consequentes rela\u00e7\u00f5es sociojur\u00eddicas na atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a p\u00fablica; Fomentar, nos agentes de seguran\u00e7a p\u00fablica, compet\u00eancias, habilidades e atitudes que privilegiem a dignidade da pessoa humana em suas atua\u00e7\u00f5es funcionais e que respeitem e valorizem os demais direitos e liberdades fundamentais do cidad\u00e3o, inclusive aqueles privados da liberdade em raz\u00e3o de condena\u00e7\u00e3o criminal; vislumbrar a influ\u00eancia das decis\u00f5es dos tribunais, a partir das \u00f3ticas da judicializa\u00e7\u00e3o dos conflitos, do ativismo judicial e do transconstitucionalismo na atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a; reconhecer a import\u00e2ncia da afirma\u00e7\u00e3o da igualdade racial e de g\u00eanero, e das a\u00e7\u00f5es afirmativas como instrumentos de efetiva\u00e7\u00e3o da dignidade da pessoa humana, conceituando igualdade, racismo, g\u00eanero e a\u00e7\u00f5es afirmativas para que os agentes de seguran\u00e7a p\u00fablica em sua atua\u00e7\u00e3o policial combatam atitudes racistas e dotadas de preconceito que fomentem comportamentos compat\u00edveis com o respeito aos direitos e garantias fundamentais do cidad\u00e3o.<\/p>\n<p>O Manual<br \/>\nO conte\u00fado foi elaborado por equipe da Escola Superior da Pol\u00edcia Civil (ESPC).<\/p>\n<p>O Curso<br \/>\nO curso, cuja modalidade de ensino ser\u00e1 \u00e0 dist\u00e2ncia, ter\u00e1 uma carga hor\u00e1ria de 60 horas e ser\u00e1 dividida em 04 disciplinas (m\u00f3dulos):<\/p>\n<p>1. Direitos e garantias fundamentais no constitucionalismo brasileito;<br \/>\n2. Racismo, igualdade de g\u00eanero, a\u00e7\u00f5es afirmativas e a atua\u00e7\u00e3o policial;<br \/>\n3. Ativismo judicial: Um novo modelo jurisdicional no Brasil;<br \/>\n4. Execu\u00e7\u00e3o penal e os direitos fundamentais.<\/p>\n<p>Cada disciplina ser\u00e1 acompanhada por instrutores da \u00e1rea de Seguran\u00e7a P\u00fablica, com conhecimento sobre o tema, bem como, com experi\u00eancia na doc\u00eancia em modalidade presencial e \u00e0 dist\u00e2ncia.<\/p>\n<p>A log\u00edstica das atividades e o emprego dos conte\u00fados ficar\u00e3o a cargo da Coordenadoria de Ensino \u00e0 Dist\u00e2ncia que j\u00e1 coordenou 15 Unidades de Telecentro no Estado e possui Know How em plataformas de ensino \u00e0 dist\u00e2ncia.<\/p>\n<p>A Avalia\u00e7\u00e3o<br \/>\nA flexibilidade permitida pela EAD respeita o processo de constru\u00e7\u00e3o do conhecimento e o tempo do aluno, o que pode ser potencializado com metodologias que privilegiam e incentivam a descoberta e a busca de conhecimentos, por meio de desafios.<\/p>\n<p>Quando suportada pelas tecnologias, esta busca \u00e9 facilitada pelo acesso \u00e0s informa\u00e7\u00f5es dispon\u00edveis na web e ainda pelas possibilidades de comunica\u00e7\u00e3o s\u00edncronas e ass\u00edncronas, as quais visam \u00e0 intera\u00e7\u00e3o interpessoal, a troca de experi\u00eancias e informa\u00e7\u00f5es favorecendo a amplia\u00e7\u00e3o do conhecimento por meio da ajuda do coletivo.<\/p>\n<p>Diante disso, prop\u00f5e esta concep\u00e7\u00e3o de avalia\u00e7\u00e3o para os cursos na modalidade \u00e0 dist\u00e2ncia, buscando aproveitar os recursos dispon\u00edveis de modo qualitativo e pautado em perspectivas te\u00f3ricas e metodol\u00f3gicas, visando agregar valores e qualidades ao processo de ensino e aprendizagem \u00e0 dist\u00e2ncia.<\/p>\n<p>A avalia\u00e7\u00e3o de car\u00e1ter cont\u00ednuo ser\u00e1 feita por meio da participa\u00e7\u00e3o do aluno nos F\u00f3runs de discuss\u00f5es que ser\u00e3o criados pelo instrutor de cada disciplina durante o curso e ainda por meio de uma Verifica\u00e7\u00e3o Final de Aprendizagem que consistir\u00e1 em 10 quest\u00f5es objetivas e aleat\u00f3rias que tendem a avaliar os conceitos apresentados em cada disciplina do curso que atestar\u00e3o a assimila\u00e7\u00e3o das atividades que ser\u00e3o seguidas em cada ocorr\u00eancia listada no curso.<\/p>\n<p>As avalia\u00e7\u00f5es, que ser\u00e3o realizadas individualmente, ser\u00e3o s\u00ednteses das disciplinas cursadas, que enfocam os temas que o discente j\u00e1 conhece, j\u00e1 estudou ou sobre os quais j\u00e1 refletiu.<\/p>\n<p>A nota ou conceito m\u00ednimo para a aprova\u00e7\u00e3o do curso \u00e9 igual ou superior que sete (7,0) numa escala de zero (0) a dez (10); ou conceito equivalente (APROVADO). A nota final do curso ser\u00e1 composta da seguinte forma: O instrutor avaliar\u00e1 as participa\u00e7\u00f5es nos f\u00f3runs criados em cada disciplina e atribuir\u00e1 at\u00e9 (1,0) ponto por participa\u00e7\u00e3o. Sendo 5 disciplinas, a nota do aluno poder\u00e1 chegar a 5,0 pontos sendo (1,0) por disciplina. O restante da nota (5,0) ser\u00e1 alcan\u00e7ada por meio da Verifica\u00e7\u00e3o Final de Aprendizagem.<\/p>\n<p>Os alunos que n\u00e3o atingirem a nota ou conceito m\u00ednimo para a aprova\u00e7\u00e3o nas disciplinas receber\u00e3o informa\u00e7\u00f5es dos respectivos professores e tutores para procederem a recupera\u00e7\u00e3o.<\/p>\n<p>Para realizar a recupera\u00e7\u00e3o da disciplina, o professor ir\u00e1 propor uma avalia\u00e7\u00e3o, para recupera\u00e7\u00e3o da nota. O aluno ter\u00e1 apenas 1 (uma) possibilidade de recupera\u00e7\u00e3o para realizar as avalia\u00e7\u00f5es e\/ou trabalhos equivalentes.<\/p>\n<p>Nome do Curso: Direitos e Garantias Fundamentais Aplicados \u00e0 Pr\u00e1tica Policial (DGFAPP)<\/p>\n<p>DISCIPLINA 1:<\/p>\n<p>Direitos e garantias fundamentais no Constitucionalismo Brasileiro<\/p>\n<p>Objetivo:<br \/>\nCompreender mais sobre a dignidade da pessoa humana como premissa da atua\u00e7\u00e3o policial e contextualizar a seguran\u00e7a p\u00fablica como direito fundamental no Brasil.<\/p>\n<p>Ementa:<br \/>\nA dignidade da pessoa humana como premissa da atua\u00e7\u00e3o policial; Seguran\u00e7a P\u00fablica como Direito Fundamental no Brasil .Metodologia:<br \/>\nA disciplina ser\u00e1 ministrada na modalidade EAD (virtual) e disponibilizar\u00e1 al\u00e9m de conte\u00fado espec\u00edfico material de apoio no estudo \u00e0 estrutura da Seguran\u00e7a P\u00fablica nacional.<\/p>\n<p>Todo o conte\u00fado deste curso ser\u00e1 disponibilizado na internet e a hospedagem ser\u00e1 no Ambiente Virtual de Aprendizagem da Plataforma Moodle \u2013 gratuito e de uso livre.<\/p>\n<p>O curso contar\u00e1 com uma equipe de monitoria para fazer os atendimentos, por telefone e e-mail das d\u00favidas relacionadas ao uso do AVA. Esses monitores estar\u00e3o \u00e0 disposi\u00e7\u00e3o nos tr\u00eas turnos. E t\u00eam o prazo de 24 horas para o retorno \u00e0s mensagens recebidas.<\/p>\n<p>Carga hor\u00e1ria: 18 horas<\/p>\n<p>Modalidade: Ensino \u00e0 dist\u00e2ncia<\/p>\n<p>Bibliografia B\u00e1sica:<\/p>\n<p>Assembl\u00e9ia Geral da ONU. (1948). Declara\u00e7\u00e3o Universal dos Direitos Humanos. (217 [III] A). Paris.<\/p>\n<p>BARACHO, J. A. de O. Direito Processual Constitucional. Editora F\u00f3rum: Belo Horizonte, 2006.<\/p>\n<p>BARRETO, R. Direitos humanos. Cole\u00e7\u00e3o Sinopses Para concursos, v. 39, 2012.<\/p>\n<p>BARROSO, L. R. Judicializa\u00e7\u00e3o, ativismo judicial e legitimidade democr\u00e1tica. Suffragium &#8211; Revista do Tribunal Regional Eleitoral do Cear\u00e1, Fortaleza, v. 5, n. 8, p. 11-22, jan.\/dez. 2009. Dispon\u00edvel em &lt;https:\/\/bibliotecadigital.tse.jus.br\/&gt; . Acesso em 20 de janeiro de 2022.<\/p>\n<p>_______Contramajorit\u00e1rio, representativo e iluminista: Os pap\u00e9is das cortes constitucionais nas democracias Contempor\u00e2neas. Dispon\u00edvel em &lt;https:\/\/www.conjur.com.br\/dl\/notas-palestra-luis-robertobarroso.pdf&gt; . Acesso em 20 de janeiro de 2022.<\/p>\n<p>BENGOCHEA, J. L. P.; GUIMAR\u00c3ES, L. B.; GOMES, M. L.; ABREU, S. R. DE. A Transi\u00e7\u00e3o De Uma Pol\u00edcia De Controle Para Uma Pol\u00edcia Cidad\u00e3. 2004. Sao Paulo Em Perspectiva.<\/p>\n<p>BRASIL. Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil: promulgada em 5 de outubro de 1988. Juspodvim, 2022.<\/p>\n<p>Decreto-Lei n\u00ba 3.689, de 3 de outubro de 1941. C\u00f3digo de Processo Penal.<\/p>\n<p>______ Minist\u00e9rio da Justi\u00e7a. Programa Nacional de Seguran\u00e7a P\u00fablica com Cidadania (Pronasci). Dispon\u00edvel em: &lt;http:\/\/www.mj.gov.br.pronasci&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>MATRIZ CURRICULAR NACIONAL para a\u00e7\u00f5es formativas dos profissionais da \u00e1rea de seguran\u00e7a p\u00fablica\/ coordena\u00e7\u00e3o: Andr\u00e9a da Silveira Passos..(et AL). Bras\u00edlia: Secretaria Nacional de Seguran\u00e7a P\u00fablica, 2014.<\/p>\n<p>______ Projeto de Lei n\u00ba 476. Cria, diretamente subordinada ao Estado Maior das For\u00e7as Armadas, a Escola Superior de Guerra, e d\u00e1 outras provid\u00eancias. Di\u00e1rio do Congresso Nacional, Se\u00e7\u00e3o 1, 8 jul. 1949, p. 5830.<\/p>\n<p>______Secretaria Nacional de Seguran\u00e7a P\u00fablica. Relat\u00f3rio de Gest\u00e3o. Exerc\u00edcio 2021. Dispon\u00edvel em: &lt;http:\/ \/www.mj.gov.br.senasp&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>______1\u00aa Confer\u00eancia Nacional de Seguran\u00e7a P\u00fablica (Conseg). 2009a. Dispon\u00edvelem: &lt;http:\/\/www.mj.gov.br.conseg&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>______Supremo Tribunal Federal. Anulada decis\u00e3o que obriga filmagem para ingresso em domic\u00edlio de suspeitos. 06 de dezembro de 2021. Dispon\u00edvel em, &lt;https:\/\/www.direitonet.com.br\/noticias&gt;. Acesso em dez de dezembro de 2021.<\/p>\n<p>BRASIL. Relat\u00f3rio\/Comiss\u00e3o Nacional da Verdade. Bras\u00edlia: CNV, 2014. vol. I e II.<\/p>\n<p>CAMPOS, C. A. de A. Estado de Coisas Inconstitucional. 2016. Dispon\u00edvel em: http:\/\/jota.uol.com.br\/jotamundo-estado-de-coisas-inconstitucional&gt;. Consulta em: 01 ago. 2021.<\/p>\n<p>CARVALHO, V. A. de; Vieira, A de C.; Pol\u00edcia Penal no Brasil: realidade, debates e poss\u00edveis reflexos na seguran\u00e7a p\u00fablica. Revista Brasileira de Execu\u00e7\u00e3o Penal<\/p>\n<p>Bras\u00edlia, v. 1, n. 2, p. 273-297, jul.\/dez. 2020.<\/p>\n<p>COMPARATO, F. K. Afirma\u00e7\u00e3o Hist\u00f3rica dos Direitos Humanos. 7\u00aa edi\u00e7\u00e3o, rev., ampl. e atual., S\u00e3o Paulo: Editora Saraiva, 2010, p. 13<\/p>\n<p>______Fundamento dos direitos humanos. Cultura dos direitos humanos. S\u00e3o Paulo: LTR, p. 52-74, 1998. Dispon\u00edvel em &lt;http:\/\/www.iea.usp.br\/artigos&gt;. Acesso em 10 de dezembro de 2021.<\/p>\n<p>COSTA, A.T; LIMA, R. Seguran\u00e7a P\u00fablica. In: Crime, pol\u00edcia e justi\u00e7a no Brasil. 1. ed. S\u00e3o Paulo: Contexto, p. 482-490, 2014.<\/p>\n<p>DALLARI, D. de A. Elementos de teoria geral do Estado. 33. ed. S\u00e3o Paulo: Saraiva, 2016.<\/p>\n<p>DANIN, R. A. A constru\u00e7\u00e3o do racismo institucional Sist\u00eamico e seu reflexo na seguran\u00e7a p\u00fablica brasileira: uma abordagem sociol\u00f3gica. Revista Direitos, trabalho e pol\u00edtica social, CUIAB\u00c1, V. 4, n. 7, p. 141-164, Jul.\/dez. 2018<\/p>\n<p>DE LIMA, R. S., Ratton, J. L., &amp; de Azevedo, R. G. (2012). Crime, pol\u00edcia e justi\u00e7a no Brasil. Editora Contexto. 2014.<\/p>\n<p>DE PLACIDO E SILVA. Vocabul\u00e1rio Jur\u00eddico. Rio de Janeiro, Forense, 1997. Descri\u00e7\u00e3o F\u00edsica: 4 v. Refer\u00eancia: 1997.<\/p>\n<p>FERRAJOLI, Luigi. Direito e Raz\u00e3o: teoria do garantismo penal. 2010<\/p>\n<p>FLORINDO, M. T. Estado, Pol\u00edcia e Sociedade. Estado, Pol\u00edcia e Sociedade: Ensaio sobre a regularidade (e a perman\u00eancia) das pr\u00e1ticas discricion\u00e1rias de atua\u00e7\u00e3o policial. INTRATEXTOS, Rio de Janeiro, 3(1): 167-182, 2011.<\/p>\n<p>FREIRE, M. D. Paradigmas de seguran\u00e7a no Brasil: da ditadura aos nossos dias. Revista Brasileira de Seguran\u00e7a P\u00fablica, Ano 3, edi\u00e7\u00e3o 5, p. 100-114, ago.\/set. 2009.<\/p>\n<p>GOLDSTEIN, Herman. Policiando uma sociedade livre. Tradu\u00e7\u00e3o Marcello Rollemberg. 9\u00b0 ed. S\u00e3o Paulo: Editora Universidade de S\u00e3o Paulo, 2003. S\u00e9rie Policia e Sociedade , n.9. (organiza\u00e7\u00e3o Nancy Candia).<\/p>\n<p>LEITE, P. M. A volta da repress\u00e3o: do sonho ao vandalismo e \u00e0 brutalidade. Revista Isto \u00c9, S\u00e3o Paulo, n. 2274, junho. 2013. p. 38.<\/p>\n<p>LENZA, P. Direito Constitucional-Esquematizado. Saraiva Educa\u00e7\u00e3o SA, 2019.<\/p>\n<p>LOPES, E. Pol\u00edtica e seguran\u00e7a p\u00fablica: uma vontade de sujei\u00e7\u00e3o. Rio de Janeiro: Contraponto, 2009.<\/p>\n<p>MASSON, N. Manual de Direito Constitucional. Salvador. Juspdvim, 2018.<\/p>\n<p>MATOS, J. W. da M. A Constru\u00e7\u00e3o Do Conceito De Seguran\u00e7a P\u00fablica Na Jurisprud\u00eancia Do Supremo Tribunal Federal No S\u00e9culo XXI. 2013.<\/p>\n<p>MAZZUOLI,\u2006 \u2006 V.\u2006 \u2006 de\u2006 \u2006 O. Curso\u2006 \u2006 de\u2006 \u2006 Direito\u2006 \u2006 Internacional\u2006 \u2006 P\u00fablico.\u2006\u2006 4\u00aa ed. S\u00e3o Paulo: Editora Revista dos\u2006 \u2006 Tribunais, 2010, pp. 750-751.<\/p>\n<p>MENDON\u00c7A FILHO, M. C.; Martins, M. C.; Nobre, M. T.; Neves, P. S. da C. Desafios da educa\u00e7\u00e3o para a cidadania. Pol\u00edcia, direitos humanos e educa\u00e7\u00e3o para a cidadania, 2002. Dispon\u00edvel em &lt;https:\/\/www.corteidh.or.cr\/&gt; . Acesso em vinte e cinco de janeiro de 2022.<\/p>\n<p>Moraes, A. de. Constitui\u00e7\u00e3o do Brasil Interpretada. 5. ed. S\u00e3o Paulo: Atlas, 2005.<\/p>\n<p>SANDEL, Michael J. Justi\u00e7a: o que \u00e9 fazer a coisa certa. Editora Jos\u00e9 Olympio, 2020.<\/p>\n<p>SANTIAGO, Nestor Eduardo Araruna; MAIA, Maurilio Casas. O garantismo penal, o encarcerado vulner\u00e1vel e a interven\u00e7\u00e3o da Defensoria P\u00fablica na execu\u00e7\u00e3o penal: custos vulnerabilis. Revista Brasileira de Ci\u00eancias Criminais, S\u00e3o Paulo, v. 152, p. 173-209, 2019.<\/p>\n<p>S\u00c3O PAULO (MUN\u00cdCIPIO). Pol\u00edticas p\u00fablicas e igualdade de g\u00eanero. Secretaria do Governo Municipal. Coordenadoria Especial da Mulher &#8211; SGM. ORG.: Godinho, T.; DA SILVEIRA, M. L.<\/p>\n<p>SAPORI, L. F. Seguran\u00e7a p\u00fablica no Brasil : desafios e perspectivas. Rio de Janeiro: Editora FGV, 2007<\/p>\n<p>T\u00c1VORA, N. ALENCAR, R. R. Curso de Direito Processual Penal. 14.\u00aa Ed. Bahia: Jusposivm: 2019<\/p>\n<p>NEVES, M. Do di\u00e1logo entre as cortes supremas e a Corte Interamericana de Direitos Humanos ao transconstitucionalismo na Am\u00e9rica Latina. Revista de Informa\u00e7\u00e3o Legislativa. Ano 51 N\u00famero 201 jan.\/mar. 2014. Dispon\u00edvel em &lt;https:\/\/www.corteidh.or.cr\/&gt;. Acesso em cinco de janeiro de 2022.<\/p>\n<p>SARLET, W. I.; Dignidade da pessoa humana e direitos fundamentais na Constitui\u00e7\u00e3o da Rep\u00fablica de 1988. Porto Alegre: Livraria do Advogado, 2002, p. 62.<\/p>\n<p>SILVA, J. A. da. A dignidade da pessoa humana como valor supremo da democracia. Revista de Direito Administrativo, v. 212, p. 84-94, abr.\/jun. 1998<\/p>\n<p>OLIVEIRA JUNIOR, A de. Revista Brasileira de Ci\u00eancias Policiais. Bras\u00edlia, v. 2, n. 2, jul\/dez 2011.<\/p>\n<p>DISCIPLINA 2:<\/p>\n<p>Racismo, igualdade de g\u00eanero, a\u00e7\u00f5es afirmativas e a atua\u00e7\u00e3o policial<\/p>\n<p>Objetivo:<br \/>\nConceituar e compreender mais sobre o racismo e atua\u00e7\u00e3o policial, bem como, contextualizar as pluralidades sociais com a seguran\u00e7a p\u00fablica.<\/p>\n<p>Ementa:<br \/>\nRacismo e atua\u00e7\u00e3o policial; Sociedade plural e seguran\u00e7a p\u00fablica.<\/p>\n<p>Metodologia:<\/p>\n<p>Todo o conte\u00fado deste curso ser\u00e1 disponibilizado na internet e a hospedagem ser\u00e1 no Ambiente Virtual de Aprendizagem da Plataforma Moodle \u2013 gratuito e de uso livre. O curso contar\u00e1 com uma equipe de monitoria para fazer os atendimentos, por telefone e e-mail das d\u00favidas relacionadas ao uso do AVA. Esses monitores estar\u00e3o \u00e0 disposi\u00e7\u00e3o nos tr\u00eas turnos. E t\u00eam o prazo de 24 horas para o retorno \u00e0s mensagens recebidas.<\/p>\n<p>Carga Hor\u00e1ria: 14 horas<\/p>\n<p>Modalidade: Ensino \u00e0 dist\u00e2ncia<\/p>\n<p>Bibliografia B\u00e1sica:<\/p>\n<p>Assembl\u00e9ia Geral da ONU. (1948). Declara\u00e7\u00e3o Universal dos Direitos Humanos. (217 [III] A). Paris.<\/p>\n<p>BARACHO, J. A. de O. Direito Processual Constitucional. Editora F\u00f3rum: Belo Horizonte, 2006.<\/p>\n<p>BARRETO, R. Direitos humanos. Cole\u00e7\u00e3o Sinopses Para concursos, v. 39, 2012.<\/p>\n<p>BARROSO, L. R. Judicializa\u00e7\u00e3o, ativismo judicial e legitimidade democr\u00e1tica. Suffragium &#8211; Revista do Tribunal Regional Eleitoral do Cear\u00e1, Fortaleza, v. 5, n. 8, p. 11-22, jan.\/dez. 2009. Dispon\u00edvel em &lt;https:\/\/bibliotecadigital.tse.jus.br\/&gt; . Acesso em 20 de janeiro de 2022.<\/p>\n<p>_______Contramajorit\u00e1rio, representativo e iluminista: Os pap\u00e9is das cortes constitucionais nas democracias Contempor\u00e2neas. Dispon\u00edvel em &lt;https:\/\/www.conjur.com.br\/dl\/notas-palestra-luis-robertobarroso.pdf&gt; . Acesso em 20 de janeiro de 2022.<\/p>\n<p>BENGOCHEA, J. L. P.; GUIMAR\u00c3ES, L. B.; GOMES, M. L.; ABREU, S. R. DE. A Transi\u00e7\u00e3o De Uma Pol\u00edcia De Controle Para Uma Pol\u00edcia Cidad\u00e3. 2004. Sao Paulo Em Perspectiva.<\/p>\n<p>BRASIL. Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil: promulgada em 5 de outubro de 1988. Juspodvim, 2022.<\/p>\n<p>Decreto-Lei n\u00ba 3.689, de 3 de outubro de 1941. C\u00f3digo de Processo Penal.<\/p>\n<p>______ Minist\u00e9rio da Justi\u00e7a. Programa Nacional de Seguran\u00e7a P\u00fablica com Cidadania (Pronasci). Dispon\u00edvel em: &lt;http:\/\/www.mj.gov.br.pronasci&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>MATRIZ CURRICULAR NACIONAL para a\u00e7\u00f5es formativas dos profissionais da \u00e1rea de seguran\u00e7a p\u00fablica\/ coordena\u00e7\u00e3o: Andr\u00e9a da Silveira Passos..(et AL). Bras\u00edlia: Secretaria Nacional de Seguran\u00e7a P\u00fablica, 2014.<\/p>\n<p>______ Projeto de Lei n\u00ba 476. Cria, diretamente subordinada ao Estado Maior das For\u00e7as Armadas, a Escola Superior de Guerra, e d\u00e1 outras provid\u00eancias. Di\u00e1rio do Congresso Nacional, Se\u00e7\u00e3o 1, 8 jul. 1949, p. 5830.<\/p>\n<p>______Secretaria Nacional de Seguran\u00e7a P\u00fablica. Relat\u00f3rio de Gest\u00e3o. Exerc\u00edcio 2021. Dispon\u00edvel em: &lt;http:\/ \/www.mj.gov.br.senasp&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>______1\u00aa Confer\u00eancia Nacional de Seguran\u00e7a P\u00fablica (Conseg). 2009a. Dispon\u00edvelem: &lt;http:\/\/www.mj.gov.br.conseg&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>______Supremo Tribunal Federal. Anulada decis\u00e3o que obriga filmagem para ingresso em domic\u00edlio de suspeitos. 06 de dezembro de 2021. Dispon\u00edvel em, &lt;https:\/\/www.direitonet.com.br\/noticias&gt;. Acesso em dez de dezembro de 2021.<\/p>\n<p>BRASIL. Relat\u00f3rio\/Comiss\u00e3o Nacional da Verdade. Bras\u00edlia: CNV, 2014. vol. I e II.<\/p>\n<p>CAMPOS, C. A. de A. Estado de Coisas Inconstitucional. 2016. Dispon\u00edvel em: http:\/\/jota.uol.com.br\/jotamundo-estado-de-coisas-inconstitucional&gt;. Consulta em: 01 ago. 2021.<\/p>\n<p>CARVALHO, V. A. de; Vieira, A de C.; Pol\u00edcia Penal no Brasil: realidade, debates e poss\u00edveis reflexos na seguran\u00e7a p\u00fablica. Revista Brasileira de Execu\u00e7\u00e3o Penal<\/p>\n<p>Bras\u00edlia, v. 1, n. 2, p. 273-297, jul.\/dez. 2020.<\/p>\n<p>COMPARATO, F. K. Afirma\u00e7\u00e3o Hist\u00f3rica dos Direitos Humanos. 7\u00aa edi\u00e7\u00e3o, rev., ampl. e atual., S\u00e3o Paulo: Editora Saraiva, 2010, p. 13<\/p>\n<p>______Fundamento dos direitos humanos. Cultura dos direitos humanos. S\u00e3o Paulo: LTR, p. 52-74, 1998. Dispon\u00edvel em &lt;http:\/\/www.iea.usp.br\/artigos&gt;. Acesso em 10 de dezembro de 2021.<\/p>\n<p>COSTA, A.T; LIMA, R. Seguran\u00e7a P\u00fablica. In: Crime, pol\u00edcia e justi\u00e7a no Brasil. 1. ed. S\u00e3o Paulo: Contexto, p. 482-490, 2014.<\/p>\n<p>DALLARI, D. de A. Elementos de teoria geral do Estado. 33. ed. S\u00e3o Paulo: Saraiva, 2016.<\/p>\n<p>DANIN, R. A. A constru\u00e7\u00e3o do racismo institucional Sist\u00eamico e seu reflexo na seguran\u00e7a p\u00fablica brasileira: uma abordagem sociol\u00f3gica. Revista Direitos, trabalho e pol\u00edtica social, CUIAB\u00c1, V. 4, n. 7, p. 141-164, Jul.\/dez. 2018<\/p>\n<p>DE LIMA, R. S., Ratton, J. L., &amp; de Azevedo, R. G. (2012). Crime, pol\u00edcia e justi\u00e7a no Brasil. Editora Contexto. 2014.<\/p>\n<p>DE PLACIDO E SILVA. Vocabul\u00e1rio Jur\u00eddico. Rio de Janeiro, Forense, 1997. Descri\u00e7\u00e3o F\u00edsica: 4 v. Refer\u00eancia: 1997.<\/p>\n<p>FERRAJOLI, Luigi. Direito e Raz\u00e3o: teoria do garantismo penal. 2010<\/p>\n<p>FLORINDO, M. T. Estado, Pol\u00edcia e Sociedade. Estado, Pol\u00edcia e Sociedade: Ensaio sobre a regularidade (e a perman\u00eancia) das pr\u00e1ticas discricion\u00e1rias de atua\u00e7\u00e3o policial. INTRATEXTOS, Rio de Janeiro, 3(1): 167-182, 2011.<\/p>\n<p>FREIRE, M. D. Paradigmas de seguran\u00e7a no Brasil: da ditadura aos nossos dias. Revista Brasileira de Seguran\u00e7a P\u00fablica, Ano 3, edi\u00e7\u00e3o 5, p. 100-114, ago.\/set. 2009.<\/p>\n<p>GOLDSTEIN, Herman. Policiando uma sociedade livre. Tradu\u00e7\u00e3o Marcello Rollemberg. 9\u00b0 ed. S\u00e3o Paulo: Editora Universidade de S\u00e3o Paulo, 2003. S\u00e9rie Policia e Sociedade , n.9. (organiza\u00e7\u00e3o Nancy Candia).<\/p>\n<p>LEITE, P. M. A volta da repress\u00e3o: do sonho ao vandalismo e \u00e0 brutalidade. Revista Isto \u00c9, S\u00e3o Paulo, n. 2274, junho. 2013. p. 38.<\/p>\n<p>LENZA, P. Direito Constitucional-Esquematizado. Saraiva Educa\u00e7\u00e3o SA, 2019.<\/p>\n<p>LOPES, E. Pol\u00edtica e seguran\u00e7a p\u00fablica: uma vontade de sujei\u00e7\u00e3o. Rio de Janeiro: Contraponto, 2009.<\/p>\n<p>MASSON, N. Manual de Direito Constitucional. Salvador. Juspdvim, 2018.<\/p>\n<p>MATOS, J. W. da M. A Constru\u00e7\u00e3o Do Conceito De Seguran\u00e7a P\u00fablica Na Jurisprud\u00eancia Do Supremo Tribunal Federal No S\u00e9culo XXI. 2013.<\/p>\n<p>MAZZUOLI,\u2006 \u2006 V.\u2006 \u2006 de\u2006 \u2006 O. Curso\u2006 \u2006 de\u2006 \u2006 Direito\u2006 \u2006 Internacional\u2006 \u2006 P\u00fablico.\u2006\u2006 4\u00aa ed. S\u00e3o Paulo: Editora Revista dos\u2006 \u2006 Tribunais, 2010, pp. 750-751.<\/p>\n<p>MENDON\u00c7A FILHO, M. C.; Martins, M. C.; Nobre, M. T.; Neves, P. S. da C. Desafios da educa\u00e7\u00e3o para a cidadania. Pol\u00edcia, direitos humanos e educa\u00e7\u00e3o para a cidadania, 2002. Dispon\u00edvel em &lt;https:\/\/www.corteidh.or.cr\/&gt; . Acesso em vinte e cinco de janeiro de 2022.<\/p>\n<p>Moraes, A. de. Constitui\u00e7\u00e3o do Brasil Interpretada. 5. ed. S\u00e3o Paulo: Atlas, 2005.<\/p>\n<p>SANDEL, Michael J. Justi\u00e7a: o que \u00e9 fazer a coisa certa. Editora Jos\u00e9 Olympio, 2020.<\/p>\n<p>SANTIAGO, Nestor Eduardo Araruna; MAIA, Maurilio Casas. O garantismo penal, o encarcerado vulner\u00e1vel e a interven\u00e7\u00e3o da Defensoria P\u00fablica na execu\u00e7\u00e3o penal: custos vulnerabilis. Revista Brasileira de Ci\u00eancias Criminais, S\u00e3o Paulo, v. 152, p. 173-209, 2019.<\/p>\n<p>S\u00c3O PAULO (MUN\u00cdCIPIO). Pol\u00edticas p\u00fablicas e igualdade de g\u00eanero. Secretaria do Governo Municipal. Coordenadoria Especial da Mulher &#8211; SGM. ORG.: Godinho, T.; DA SILVEIRA, M. L.<\/p>\n<p>SAPORI, L. F. Seguran\u00e7a p\u00fablica no Brasil : desafios e perspectivas. Rio de Janeiro: Editora FGV, 2007<\/p>\n<p>T\u00c1VORA, N. ALENCAR, R. R. Curso de Direito Processual Penal. 14.\u00aa Ed. Bahia: Jusposivm: 2019<\/p>\n<p>NEVES, M. Do di\u00e1logo entre as cortes supremas e a Corte Interamericana de Direitos Humanos ao transconstitucionalismo na Am\u00e9rica Latina. Revista de Informa\u00e7\u00e3o Legislativa. Ano 51 N\u00famero 201 jan.\/mar. 2014. Dispon\u00edvel em &lt;https:\/\/www.corteidh.or.cr\/&gt;. Acesso em cinco de janeiro de 2022.<\/p>\n<p>SARLET, W. I.; Dignidade da pessoa humana e direitos fundamentais na Constitui\u00e7\u00e3o da Rep\u00fablica de 1988. Porto Alegre: Livraria do Advogado, 2002, p. 62.<\/p>\n<p>SILVA, J. A. da. A dignidade da pessoa humana como valor supremo da democracia. Revista de Direito Administrativo, v. 212, p. 84-94, abr.\/jun. 1998<\/p>\n<p>OLIVEIRA JUNIOR, A de. Revista Brasileira de Ci\u00eancias Policiais. Bras\u00edlia, v. 2, n. 2, jul\/dez 2011.<\/p>\n<p>DISCIPLINA 3:<\/p>\n<p>Ativismo judicial: Um novo modelo jurisdicional no Brasil<\/p>\n<p>Objetivo:<br \/>\nIdentificar e compreender os modelos de ativismo judicial no brasil. Conceituar e analisar o Transconsitucionalismo.<\/p>\n<p>Ementa:<br \/>\nOs tribunais e um novo modelo de atua\u00e7\u00e3o policial; Ativismo Judicial e atua\u00e7\u00e3o policial; Transconstitucionalismo.<\/p>\n<p>Metodologia:<br \/>\nTodo o conte\u00fado deste curso ser\u00e1 disponibilizado na internet e a hospedagem ser\u00e1 no Ambiente Virtual de Aprendizagem da Plataforma Moodle \u2013 gratuito e de uso livre. O curso contar\u00e1 com uma equipe de monitoria para fazer os atendimentos, por telefone e e-mail das d\u00favidas relacionadas ao uso do AVA. Esses monitores estar\u00e3o \u00e0 disposi\u00e7\u00e3o nos tr\u00eas turnos. E t\u00eam o prazo de 24 horas para o retorno \u00e0s mensagens recebidas.<\/p>\n<p>Carga hor\u00e1ria: 14 horas.<\/p>\n<p>Modalidade: Ensino \u00e0 dist\u00e2ncia<\/p>\n<p>Bibliografia B\u00e1sica:<\/p>\n<p>Assembl\u00e9ia Geral da ONU. (1948). Declara\u00e7\u00e3o Universal dos Direitos Humanos. (217 [III] A). Paris.<\/p>\n<p>BARACHO, J. A. de O. Direito Processual Constitucional. Editora F\u00f3rum: Belo Horizonte, 2006.<\/p>\n<p>BARRETO, R. Direitos humanos. Cole\u00e7\u00e3o Sinopses Para concursos, v. 39, 2012.<\/p>\n<p>BARROSO, L. R. Judicializa\u00e7\u00e3o, ativismo judicial e legitimidade democr\u00e1tica. Suffragium &#8211; Revista do Tribunal Regional Eleitoral do Cear\u00e1, Fortaleza, v. 5, n. 8, p. 11-22, jan.\/dez. 2009. Dispon\u00edvel em &lt;https:\/\/bibliotecadigital.tse.jus.br\/&gt; . Acesso em 20 de janeiro de 2022.<\/p>\n<p>_______Contramajorit\u00e1rio, representativo e iluminista: Os pap\u00e9is das cortes constitucionais nas democracias Contempor\u00e2neas. Dispon\u00edvel em &lt;https:\/\/www.conjur.com.br\/dl\/notas-palestra-luis-robertobarroso.pdf&gt; . Acesso em 20 de janeiro de 2022.<\/p>\n<p>BENGOCHEA, J. L. P.; GUIMAR\u00c3ES, L. B.; GOMES, M. L.; ABREU, S. R. DE. A Transi\u00e7\u00e3o De Uma Pol\u00edcia De Controle Para Uma Pol\u00edcia Cidad\u00e3. 2004. Sao Paulo Em Perspectiva.<\/p>\n<p>BRASIL. Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil: promulgada em 5 de outubro de 1988. Juspodvim, 2022.<\/p>\n<p>Decreto-Lei n\u00ba 3.689, de 3 de outubro de 1941. C\u00f3digo de Processo Penal.<\/p>\n<p>______ Minist\u00e9rio da Justi\u00e7a. Programa Nacional de Seguran\u00e7a P\u00fablica com Cidadania (Pronasci). Dispon\u00edvel em: &lt;http:\/\/www.mj.gov.br.pronasci&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>MATRIZ CURRICULAR NACIONAL para a\u00e7\u00f5es formativas dos profissionais da \u00e1rea de seguran\u00e7a p\u00fablica\/ coordena\u00e7\u00e3o: Andr\u00e9a da Silveira Passos..(et AL). Bras\u00edlia: Secretaria Nacional de Seguran\u00e7a P\u00fablica, 2014.<\/p>\n<p>______ Projeto de Lei n\u00ba 476. Cria, diretamente subordinada ao Estado Maior das For\u00e7as Armadas, a Escola Superior de Guerra, e d\u00e1 outras provid\u00eancias. Di\u00e1rio do Congresso Nacional, Se\u00e7\u00e3o 1, 8 jul. 1949, p. 5830.<\/p>\n<p>______Secretaria Nacional de Seguran\u00e7a P\u00fablica. Relat\u00f3rio de Gest\u00e3o. Exerc\u00edcio 2021. Dispon\u00edvel em: &lt;http:\/ \/www.mj.gov.br.senasp&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>______1\u00aa Confer\u00eancia Nacional de Seguran\u00e7a P\u00fablica (Conseg). 2009a. Dispon\u00edvelem: &lt;http:\/\/www.mj.gov.br.conseg&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>______Supremo Tribunal Federal. Anulada decis\u00e3o que obriga filmagem para ingresso em domic\u00edlio de suspeitos. 06 de dezembro de 2021. Dispon\u00edvel em, &lt;https:\/\/www.direitonet.com.br\/noticias&gt;. Acesso em dez de dezembro de 2021.<\/p>\n<p>BRASIL. Relat\u00f3rio\/Comiss\u00e3o Nacional da Verdade. Bras\u00edlia: CNV, 2014. vol. I e II.<\/p>\n<p>CAMPOS, C. A. de A. Estado de Coisas Inconstitucional. 2016. Dispon\u00edvel em: http:\/\/jota.uol.com.br\/jotamundo-estado-de-coisas-inconstitucional&gt;. Consulta em: 01 ago. 2021.<\/p>\n<p>CARVALHO, V. A. de; Vieira, A de C.; Pol\u00edcia Penal no Brasil: realidade, debates e poss\u00edveis reflexos na seguran\u00e7a p\u00fablica. Revista Brasileira de Execu\u00e7\u00e3o Penal<\/p>\n<p>Bras\u00edlia, v. 1, n. 2, p. 273-297, jul.\/dez. 2020.<\/p>\n<p>COMPARATO, F. K. Afirma\u00e7\u00e3o Hist\u00f3rica dos Direitos Humanos. 7\u00aa edi\u00e7\u00e3o, rev., ampl. e atual., S\u00e3o Paulo: Editora Saraiva, 2010, p. 13<\/p>\n<p>______Fundamento dos direitos humanos. Cultura dos direitos humanos. S\u00e3o Paulo: LTR, p. 52-74, 1998. Dispon\u00edvel em &lt;http:\/\/www.iea.usp.br\/artigos&gt;. Acesso em 10 de dezembro de 2021.<\/p>\n<p>COSTA, A.T; LIMA, R. Seguran\u00e7a P\u00fablica. In: Crime, pol\u00edcia e justi\u00e7a no Brasil. 1. ed. S\u00e3o Paulo: Contexto, p. 482-490, 2014.<\/p>\n<p>DALLARI, D. de A. Elementos de teoria geral do Estado. 33. ed. S\u00e3o Paulo: Saraiva, 2016.<\/p>\n<p>DANIN, R. A. A constru\u00e7\u00e3o do racismo institucional Sist\u00eamico e seu reflexo na seguran\u00e7a p\u00fablica brasileira: uma abordagem sociol\u00f3gica. Revista Direitos, trabalho e pol\u00edtica social, CUIAB\u00c1, V. 4, n. 7, p. 141-164, Jul.\/dez. 2018<\/p>\n<p>DE LIMA, R. S., Ratton, J. L., &amp; de Azevedo, R. G. (2012). Crime, pol\u00edcia e justi\u00e7a no Brasil. Editora Contexto. 2014.<\/p>\n<p>DE PLACIDO E SILVA. Vocabul\u00e1rio Jur\u00eddico. Rio de Janeiro, Forense, 1997. Descri\u00e7\u00e3o F\u00edsica: 4 v. Refer\u00eancia: 1997.<\/p>\n<p>FERRAJOLI, Luigi. Direito e Raz\u00e3o: teoria do garantismo penal. 2010<\/p>\n<p>FLORINDO, M. T. Estado, Pol\u00edcia e Sociedade. Estado, Pol\u00edcia e Sociedade: Ensaio sobre a regularidade (e a perman\u00eancia) das pr\u00e1ticas discricion\u00e1rias de atua\u00e7\u00e3o policial. INTRATEXTOS, Rio de Janeiro, 3(1): 167-182, 2011.<\/p>\n<p>FREIRE, M. D. Paradigmas de seguran\u00e7a no Brasil: da ditadura aos nossos dias. Revista Brasileira de Seguran\u00e7a P\u00fablica, Ano 3, edi\u00e7\u00e3o 5, p. 100-114, ago.\/set. 2009.<\/p>\n<p>GOLDSTEIN, Herman. Policiando uma sociedade livre. Tradu\u00e7\u00e3o Marcello Rollemberg. 9\u00b0 ed. S\u00e3o Paulo: Editora Universidade de S\u00e3o Paulo, 2003. S\u00e9rie Policia e Sociedade , n.9. (organiza\u00e7\u00e3o Nancy Candia).<\/p>\n<p>LEITE, P. M. A volta da repress\u00e3o: do sonho ao vandalismo e \u00e0 brutalidade. Revista Isto \u00c9, S\u00e3o Paulo, n. 2274, junho. 2013. p. 38.<\/p>\n<p>LENZA, P. Direito Constitucional-Esquematizado. Saraiva Educa\u00e7\u00e3o SA, 2019.<\/p>\n<p>LOPES, E. Pol\u00edtica e seguran\u00e7a p\u00fablica: uma vontade de sujei\u00e7\u00e3o. Rio de Janeiro: Contraponto, 2009.<\/p>\n<p>MASSON, N. Manual de Direito Constitucional. Salvador. Juspdvim, 2018.<\/p>\n<p>MATOS, J. W. da M. A Constru\u00e7\u00e3o Do Conceito De Seguran\u00e7a P\u00fablica Na Jurisprud\u00eancia Do Supremo Tribunal Federal No S\u00e9culo XXI. 2013.<\/p>\n<p>MAZZUOLI,\u2006 \u2006 V.\u2006 \u2006 de\u2006 \u2006 O. Curso\u2006 \u2006 de\u2006 \u2006 Direito\u2006 \u2006 Internacional\u2006 \u2006 P\u00fablico.\u2006\u2006 4\u00aa ed. S\u00e3o Paulo: Editora Revista dos\u2006 \u2006 Tribunais, 2010, pp. 750-751.<\/p>\n<p>MENDON\u00c7A FILHO, M. C.; Martins, M. C.; Nobre, M. T.; Neves, P. S. da C. Desafios da educa\u00e7\u00e3o para a cidadania. Pol\u00edcia, direitos humanos e educa\u00e7\u00e3o para a cidadania, 2002. Dispon\u00edvel em &lt;https:\/\/www.corteidh.or.cr\/&gt; . Acesso em vinte e cinco de janeiro de 2022.<\/p>\n<p>Moraes, A. de. Constitui\u00e7\u00e3o do Brasil Interpretada. 5. ed. S\u00e3o Paulo: Atlas, 2005.<\/p>\n<p>SANDEL, Michael J. Justi\u00e7a: o que \u00e9 fazer a coisa certa. Editora Jos\u00e9 Olympio, 2020.<\/p>\n<p>SANTIAGO, Nestor Eduardo Araruna; MAIA, Maurilio Casas. O garantismo penal, o encarcerado vulner\u00e1vel e a interven\u00e7\u00e3o da Defensoria P\u00fablica na execu\u00e7\u00e3o penal: custos vulnerabilis. Revista Brasileira de Ci\u00eancias Criminais, S\u00e3o Paulo, v. 152, p. 173-209, 2019.<\/p>\n<p>S\u00c3O PAULO (MUN\u00cdCIPIO). Pol\u00edticas p\u00fablicas e igualdade de g\u00eanero. Secretaria do Governo Municipal. Coordenadoria Especial da Mulher &#8211; SGM. ORG.: Godinho, T.; DA SILVEIRA, M. L.<\/p>\n<p>SAPORI, L. F. Seguran\u00e7a p\u00fablica no Brasil : desafios e perspectivas. Rio de Janeiro: Editora FGV, 2007<\/p>\n<p>T\u00c1VORA, N. ALENCAR, R. R. Curso de Direito Processual Penal. 14.\u00aa Ed. Bahia: Jusposivm: 2019<\/p>\n<p>NEVES, M. Do di\u00e1logo entre as cortes supremas e a Corte Interamericana de Direitos Humanos ao transconstitucionalismo na Am\u00e9rica Latina. Revista de Informa\u00e7\u00e3o Legislativa. Ano 51 N\u00famero 201 jan.\/mar. 2014. Dispon\u00edvel em &lt;https:\/\/www.corteidh.or.cr\/&gt;. Acesso em cinco de janeiro de 2022.<\/p>\n<p>SARLET, W. I.; Dignidade da pessoa humana e direitos fundamentais na Constitui\u00e7\u00e3o da Rep\u00fablica de 1988. Porto Alegre: Livraria do Advogado, 2002, p. 62.<\/p>\n<p>SILVA, J. A. da. A dignidade da pessoa humana como valor supremo da democracia. Revista de Direito Administrativo, v. 212, p. 84-94, abr.\/jun. 1998<\/p>\n<p>OLIVEIRA JUNIOR, A de. Revista Brasileira de Ci\u00eancias Policiais. Bras\u00edlia, v. 2, n. 2, jul\/dez 2011.<\/p>\n<p>DISCIPLINA 4:<\/p>\n<p>Execu\u00e7\u00e3o penal e os direitos fundamentais<\/p>\n<p>Objetivo:<br \/>\nConhecer e compreender a rela\u00e7\u00e3o entre a Execu\u00e7\u00e3o Penal e os direitos fundamentais.<\/p>\n<p>Ementa:<br \/>\nGarantismo na execu\u00e7\u00e3o penal.<\/p>\n<p>Metodologia:<br \/>\nTodo o conte\u00fado deste curso ser\u00e1 disponibilizado na internet e a hospedagem ser\u00e1 no Ambiente Virtual de Aprendizagem da Plataforma Moodle \u2013 gratuito e de uso livre. O curso contar\u00e1 com uma equipe de monitoria para fazer os atendimentos, por telefone e e-mail das d\u00favidas relacionadas ao uso do AVA. Esses monitores estar\u00e3o \u00e0 disposi\u00e7\u00e3o nos tr\u00eas turnos. E t\u00eam o prazo de 24 horas para o retorno as mensagens recebidas.<\/p>\n<p>Carga hor\u00e1ria: 14 horas<\/p>\n<p>Modalidade: Ensino \u00e0 dist\u00e2ncia.<\/p>\n<p>Bibliografia B\u00e1sica:<\/p>\n<p>Assembl\u00e9ia Geral da ONU. (1948). Declara\u00e7\u00e3o Universal dos Direitos Humanos. (217 [III] A). Paris.<\/p>\n<p>BARACHO, J. A. de O. Direito Processual Constitucional. Editora F\u00f3rum: Belo Horizonte, 2006.<\/p>\n<p>BARRETO, R. Direitos humanos. Cole\u00e7\u00e3o Sinopses Para concursos, v. 39, 2012.<\/p>\n<p>BARROSO, L. R. Judicializa\u00e7\u00e3o, ativismo judicial e legitimidade democr\u00e1tica. Suffragium &#8211; Revista do Tribunal Regional Eleitoral do Cear\u00e1, Fortaleza, v. 5, n. 8, p. 11-22, jan.\/dez. 2009. Dispon\u00edvel em &lt;https:\/\/bibliotecadigital.tse.jus.br\/&gt; . Acesso em 20 de janeiro de 2022.<\/p>\n<p>_______Contramajorit\u00e1rio, representativo e iluminista: Os pap\u00e9is das cortes constitucionais nas democracias Contempor\u00e2neas. Dispon\u00edvel em &lt;https:\/\/www.conjur.com.br\/dl\/notas-palestra-luis-robertobarroso.pdf&gt; . Acesso em 20 de janeiro de 2022.<\/p>\n<p>BENGOCHEA, J. L. P.; GUIMAR\u00c3ES, L. B.; GOMES, M. L.; ABREU, S. R. DE. A Transi\u00e7\u00e3o De Uma Pol\u00edcia De Controle Para Uma Pol\u00edcia Cidad\u00e3. 2004. Sao Paulo Em Perspectiva.<\/p>\n<p>BRASIL. Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil: promulgada em 5 de outubro de 1988. Juspodvim, 2022.<\/p>\n<p>Decreto-Lei n\u00ba 3.689, de 3 de outubro de 1941. C\u00f3digo de Processo Penal.<\/p>\n<p>______ Minist\u00e9rio da Justi\u00e7a. Programa Nacional de Seguran\u00e7a P\u00fablica com Cidadania (Pronasci). Dispon\u00edvel em: &lt;http:\/\/www.mj.gov.br.pronasci&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>MATRIZ CURRICULAR NACIONAL para a\u00e7\u00f5es formativas dos profissionais da \u00e1rea de seguran\u00e7a p\u00fablica\/ coordena\u00e7\u00e3o: Andr\u00e9a da Silveira Passos..(et AL). Bras\u00edlia: Secretaria Nacional de Seguran\u00e7a P\u00fablica, 2014.<\/p>\n<p>______ Projeto de Lei n\u00ba 476. Cria, diretamente subordinada ao Estado Maior das For\u00e7as Armadas, a Escola Superior de Guerra, e d\u00e1 outras provid\u00eancias. Di\u00e1rio do Congresso Nacional, Se\u00e7\u00e3o 1, 8 jul. 1949, p. 5830.<\/p>\n<p>______Secretaria Nacional de Seguran\u00e7a P\u00fablica. Relat\u00f3rio de Gest\u00e3o. Exerc\u00edcio 2021. Dispon\u00edvel em: &lt;http:\/ \/www.mj.gov.br.senasp&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>______1\u00aa Confer\u00eancia Nacional de Seguran\u00e7a P\u00fablica (Conseg). 2009a. Dispon\u00edvelem: &lt;http:\/\/www.mj.gov.br.conseg&gt;. Acesso em: 29 set. 2021.<\/p>\n<p>______Supremo Tribunal Federal. Anulada decis\u00e3o que obriga filmagem para ingresso em domic\u00edlio de suspeitos. 06 de dezembro de 2021. Dispon\u00edvel em, &lt;https:\/\/www.direitonet.com.br\/noticias&gt;. Acesso em dez de dezembro de 2021.<\/p>\n<p>BRASIL. Relat\u00f3rio\/Comiss\u00e3o Nacional da Verdade. Bras\u00edlia: CNV, 2014. vol. I e II.<\/p>\n<p>CAMPOS, C. A. de A. Estado de Coisas Inconstitucional. 2016. Dispon\u00edvel em: http:\/\/jota.uol.com.br\/jotamundo-estado-de-coisas-inconstitucional&gt;. Consulta em: 01 ago. 2021.<\/p>\n<p>CARVALHO, V. A. de; Vieira, A de C.; Pol\u00edcia Penal no Brasil: realidade, debates e poss\u00edveis reflexos na seguran\u00e7a p\u00fablica. Revista Brasileira de Execu\u00e7\u00e3o Penal<\/p>\n<p>Bras\u00edlia, v. 1, n. 2, p. 273-297, jul.\/dez. 2020.<\/p>\n<p>COMPARATO, F. K. Afirma\u00e7\u00e3o Hist\u00f3rica dos Direitos Humanos. 7\u00aa edi\u00e7\u00e3o, rev., ampl. e atual., S\u00e3o Paulo: Editora Saraiva, 2010, p. 13<\/p>\n<p>______Fundamento dos direitos humanos. Cultura dos direitos humanos. S\u00e3o Paulo: LTR, p. 52-74, 1998. Dispon\u00edvel em &lt;http:\/\/www.iea.usp.br\/artigos&gt;. Acesso em 10 de dezembro de 2021.<\/p>\n<p>COSTA, A.T; LIMA, R. Seguran\u00e7a P\u00fablica. In: Crime, pol\u00edcia e justi\u00e7a no Brasil. 1. ed. S\u00e3o Paulo: Contexto, p. 482-490, 2014.<\/p>\n<p>DALLARI, D. de A. Elementos de teoria geral do Estado. 33. ed. S\u00e3o Paulo: Saraiva, 2016.<\/p>\n<p>DANIN, R. A. A constru\u00e7\u00e3o do racismo institucional Sist\u00eamico e seu reflexo na seguran\u00e7a p\u00fablica brasileira: uma abordagem sociol\u00f3gica. Revista Direitos, trabalho e pol\u00edtica social, CUIAB\u00c1, V. 4, n. 7, p. 141-164, Jul.\/dez. 2018<\/p>\n<p>DE LIMA, R. S., Ratton, J. L., &amp; de Azevedo, R. G. (2012). Crime, pol\u00edcia e justi\u00e7a no Brasil. Editora Contexto. 2014.<\/p>\n<p>DE PLACIDO E SILVA. Vocabul\u00e1rio Jur\u00eddico. Rio de Janeiro, Forense, 1997. Descri\u00e7\u00e3o F\u00edsica: 4 v. Refer\u00eancia: 1997.<\/p>\n<p>FERRAJOLI, Luigi. Direito e Raz\u00e3o: teoria do garantismo penal. 2010<\/p>\n<p>FLORINDO, M. T. Estado, Pol\u00edcia e Sociedade. Estado, Pol\u00edcia e Sociedade: Ensaio sobre a regularidade (e a perman\u00eancia) das pr\u00e1ticas discricion\u00e1rias de atua\u00e7\u00e3o policial. INTRATEXTOS, Rio de Janeiro, 3(1): 167-182, 2011.<\/p>\n<p>FREIRE, M. D. Paradigmas de seguran\u00e7a no Brasil: da ditadura aos nossos dias. Revista Brasileira de Seguran\u00e7a P\u00fablica, Ano 3, edi\u00e7\u00e3o 5, p. 100-114, ago.\/set. 2009.<\/p>\n<p>GOLDSTEIN, Herman. Policiando uma sociedade livre. Tradu\u00e7\u00e3o Marcello Rollemberg. 9\u00b0 ed. S\u00e3o Paulo: Editora Universidade de S\u00e3o Paulo, 2003. S\u00e9rie Policia e Sociedade , n.9. (organiza\u00e7\u00e3o Nancy Candia).<\/p>\n<p>LEITE, P. M. A volta da repress\u00e3o: do sonho ao vandalismo e \u00e0 brutalidade. Revista Isto \u00c9, S\u00e3o Paulo, n. 2274, junho. 2013. p. 38.<\/p>\n<p>LENZA, P. Direito Constitucional-Esquematizado. Saraiva Educa\u00e7\u00e3o SA, 2019.<\/p>\n<p>LOPES, E. Pol\u00edtica e seguran\u00e7a p\u00fablica: uma vontade de sujei\u00e7\u00e3o. Rio de Janeiro: Contraponto, 2009.<\/p>\n<p>MASSON, N. Manual de Direito Constitucional. Salvador. Juspdvim, 2018.<\/p>\n<p>MATOS, J. W. da M. A Constru\u00e7\u00e3o Do Conceito De Seguran\u00e7a P\u00fablica Na Jurisprud\u00eancia Do Supremo Tribunal Federal No S\u00e9culo XXI. 2013.<\/p>\n<p>MAZZUOLI,\u2006 \u2006 V.\u2006 \u2006 de\u2006 \u2006 O. Curso\u2006 \u2006 de\u2006 \u2006 Direito\u2006 \u2006 Internacional\u2006 \u2006 P\u00fablico.\u2006\u2006 4\u00aa ed. S\u00e3o Paulo: Editora Revista dos\u2006 \u2006 Tribunais, 2010, pp. 750-751.<\/p>\n<p>MENDON\u00c7A FILHO, M. C.; Martins, M. C.; Nobre, M. T.; Neves, P. S. da C. Desafios da educa\u00e7\u00e3o para a cidadania. Pol\u00edcia, direitos humanos e educa\u00e7\u00e3o para a cidadania, 2002. Dispon\u00edvel em &lt;https:\/\/www.corteidh.or.cr\/&gt; . Acesso em vinte e cinco de janeiro de 2022.<\/p>\n<p>Moraes, A. de. Constitui\u00e7\u00e3o do Brasil Interpretada. 5. ed. S\u00e3o Paulo: Atlas, 2005.<\/p>\n<p>SANDEL, Michael J. Justi\u00e7a: o que \u00e9 fazer a coisa certa. Editora Jos\u00e9 Olympio, 2020.<\/p>\n<p>SANTIAGO, Nestor Eduardo Araruna; MAIA, Maurilio Casas. O garantismo penal, o encarcerado vulner\u00e1vel e a interven\u00e7\u00e3o da Defensoria P\u00fablica na execu\u00e7\u00e3o penal: custos vulnerabilis. Revista Brasileira de Ci\u00eancias Criminais, S\u00e3o Paulo, v. 152, p. 173-209, 2019.<\/p>\n<p>S\u00c3O PAULO (MUN\u00cdCIPIO). Pol\u00edticas p\u00fablicas e igualdade de g\u00eanero. Secretaria do Governo Municipal. Coordenadoria Especial da Mulher &#8211; SGM. ORG.: Godinho, T.; DA SILVEIRA, M. L.<\/p>\n<p>SAPORI, L. F. Seguran\u00e7a p\u00fablica no Brasil : desafios e perspectivas. Rio de Janeiro: Editora FGV, 2007<\/p>\n<p>T\u00c1VORA, N. ALENCAR, R. R. Curso de Direito Processual Penal. 14.\u00aa Ed. Bahia: Jusposivm: 2019<\/p>\n<p>NEVES, M. Do di\u00e1logo entre as cortes supremas e a Corte Interamericana de Direitos Humanos ao transconstitucionalismo na Am\u00e9rica Latina. Revista de Informa\u00e7\u00e3o Legislativa. Ano 51 N\u00famero 201 jan.\/mar. 2014. Dispon\u00edvel em &lt;https:\/\/www.corteidh.or.cr\/&gt;. Acesso em cinco de janeiro de 2022.<\/p>\n<p>SARLET, W. I.; Dignidade da pessoa humana e direitos fundamentais na Constitui\u00e7\u00e3o da Rep\u00fablica de 1988. Porto Alegre: Livraria do Advogado, 2002, p. 62.<\/p>\n<p>SILVA, J. A. da. A dignidade da pessoa humana como valor supremo da democracia. Revista de Direito Administrativo, v. 212, p. 84-94, abr.\/jun. 1998<\/p>\n<p>OLIVEIRA JUNIOR, A de. Revista Brasileira de Ci\u00eancias Policiais. Bras\u00edlia, v. 2, n. 2, jul\/dez 2011.<\/p>\n<table>\n<thead>\n<tr>\n<td colspan=\"2\">\n<p class=\"Tabela_Texto_Centralizado\"><b>Curso<\/b>\u00a0<b>de Direitos e Garantias Fundamentais Aplicados \u00e0 Pr\u00e1tica Policial (DGFAPP)<\/b><\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>Carga Hor\u00e1ria em Hora\/Aula<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>Disciplina 01:<\/b><\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">Direitos e garantias fundamentais no Constitucionalismo Brasileiro<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>18 horas<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>Disciplina 02:<\/b><\/p>\n<p class=\"Tabela_Texto_Centralizado\">\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">Racismo, igualdade de g\u00eanero, a\u00e7\u00f5es afirmativas e a atua\u00e7\u00e3o policial<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>14 horas<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>Disciplina 03:<\/b><\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">Ativismo judicial: Um novo modelo jurisdicional no Brasil<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>14 horas<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>Disciplina 04:<\/b><\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\">Execu\u00e7\u00e3o penal e os direitos fundamentais<\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>14 horas<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<p class=\"Tabela_Texto_Centralizado\"><b>TOTAL<\/b><\/p>\n<\/td>\n<td>\n<p class=\"Tabela_Texto_Centralizado\"><b>60 horas<\/b><\/p>\n<\/td>\n<\/tr>\n<\/thead>\n<\/table>\n<p><a href=\"https:\/\/goias.gov.br\/seguranca\/wp-content\/uploads\/sites\/56\/2025\/01\/PORTARIA-No-34-DE-10-DE-JANEIRO-DE-2025.pdf\">PORTARIA N\u00ba 34, DE 10 DE JANEIRO DE 2025<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PORTARIA N\u00ba\u00a034, DE\u00a010 DE\u00a0janeiro DE\u00a02025 Autoriza e homologa a realiza\u00e7\u00e3o do curso Direitos e Garantias Fundamentais Aplicados \u00e0 Pr\u00e1tica Policial \u2013 DGFAPP, em modalidade de ensino \u00e0 dist\u00e2ncia \u2013 EaD. O SUBSECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA, nomeado pelo Decreto de 24 de abril de 2024, publicado no Di\u00e1rio Oficial do Estado n\u00ba 24.272, no [&hellip;]<\/p>\n","protected":false},"author":479,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[12],"tags":[],"class_list":["post-265826","post","type-post","status-publish","format-standard","hentry","category-portarias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Robson (SSP\/GO)","author_link":"https:\/\/goias.gov.br\/seguranca\/author\/robsonxavier\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/seguranca\/categoria\/portarias\/\" rel=\"category tag\">Portarias<\/a>","rttpg_excerpt":"PORTARIA N\u00ba\u00a034, DE\u00a010 DE\u00a0janeiro DE\u00a02025 Autoriza e homologa a realiza\u00e7\u00e3o do curso Direitos e Garantias Fundamentais Aplicados \u00e0 Pr\u00e1tica Policial \u2013 DGFAPP, em modalidade de ensino \u00e0 dist\u00e2ncia \u2013 EaD. O SUBSECRET\u00c1RIO DE ESTADO DA SEGURAN\u00c7A P\u00daBLICA, nomeado pelo Decreto de 24 de abril de 2024, publicado no Di\u00e1rio Oficial do Estado n\u00ba 24.272, no&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/265826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/users\/479"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/comments?post=265826"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/265826\/revisions"}],"predecessor-version":[{"id":265829,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/265826\/revisions\/265829"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/media?parent=265826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/categories?post=265826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/tags?post=265826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}