{"id":258758,"date":"2024-09-11T12:02:55","date_gmt":"2024-09-11T15:02:55","guid":{"rendered":"https:\/\/goias.gov.br\/seguranca\/?p=258758"},"modified":"2024-09-11T12:02:55","modified_gmt":"2024-09-11T15:02:55","slug":"pregao-eletronico-no-18-2024-pmgo","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/seguranca\/pregao-eletronico-no-18-2024-pmgo\/","title":{"rendered":"PREG\u00c3O ELETR\u00d4NICO N\u00ba 18\/2024\/PMGO"},"content":{"rendered":"<ul>\n<li style=\"text-align: center\"><u>AVISO DE LICITA\u00c7\u00c3O<\/u><\/li>\n<\/ul>\n<p style=\"text-align: center\"><strong>PREG\u00c3O ELETR\u00d4NICO N\u00ba 18\/2024\/PMGO<\/strong><\/p>\n<p style=\"text-align: center\"><strong>PROCESSO N\u00b0 202400005025080<\/strong><\/p>\n<p style=\"text-align: center\"><strong>Contrata\u00e7\u00e3o SISLOG n\u00ba 107340<\/strong><\/p>\n<p style=\"text-align: center\">O Estado de Goi\u00e1s, por interm\u00e9dio da <strong>POL\u00cdCIA MILITAR DO ESTADO DE GOI\u00c1S<\/strong> torna p\u00fablico, para conhecimento dos interessados, que realizar\u00e1 procedimento na modalidade <strong>Preg\u00e3o Eletr\u00f4nico, <\/strong>tipo<strong> Menor Pre\u00e7o por Lote, <\/strong>sendo<strong> Lote exclusivo para Microempresas e Empresas de Pequeno Porte, <\/strong>Modo de Disputa<strong> Aberto<\/strong> nos termos do Art. 28, inciso I da Lei Federal n\u00ba 14.133, de 1\u00ba de abril de 2021 e na forma do Decreto Estadual n\u00ba 10.247, de 30 de mar\u00e7o de 2023. Objeto:\u00a0 <strong>Aquisi\u00e7\u00e3o de material de ferradoria para o Regimento de Cavalaria da Pol\u00edcia Militar do Estado de Goi\u00e1s. <\/strong>Data e hor\u00e1rio de in\u00edcio da sess\u00e3o p\u00fablica: <strong>10h:00min<\/strong> (hor\u00e1rio de Bras\u00edlia-DF) do dia <strong>24\/09\/2024<\/strong>. Endere\u00e7o eletr\u00f4nico: <a href=\"http:\/\/www.sislog.go.gov.br\/\">www.sislog.go.gov.br<\/a>. O fornecedor interessado em participar do certame dever\u00e1 ser previamente cadastrado no sistema oficial de cadastro de fornecedores do Estado e encaminhar\u00e1, exclusivamente por meio do sistema eletr\u00f4nico, a proposta com a descri\u00e7\u00e3o do objeto e pre\u00e7o ofertado, at\u00e9 a data e hor\u00e1rio estabelecidos para in\u00edcio da Sess\u00e3o P\u00fablica. Informa\u00e7\u00f5es acerca do cadastro de fornecedores, Termo de Refer\u00eancia e demais documentos da contrata\u00e7\u00e3o encontram-se dispon\u00edveis nos sites: www.sislog.go.gov.br. Maiores informa\u00e7\u00f5es pelo telefone: 62 98188-0076 e\/ou e-mail: licitacao.pmgo@gmail.com.<\/p>\n<h3><\/h3>\n<h3 style=\"text-align: center\">MARCELO GRANJA &#8211; CORONEL PM<\/h3>\n<ul>\n<li style=\"text-align: center\"><strong>Comandante-Geral da PMGO<br \/>\n<\/strong><strong>Ordenador de Despesas<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.pm.go.gov.br\/wp-content\/uploads\/2024\/09\/pregao-eletronico-no-182024pmgo-5.pdf\" target=\"_blank\" rel=\"noopener\">SEI_GOVERNADORIA &#8211; 64726512 &#8211; Edital<\/a><\/p>\n<p><a href=\"https:\/\/www.pm.go.gov.br\/wp-content\/uploads\/2024\/09\/pregao-eletronico-no-182024pmgo-6.pdf\" target=\"_blank\" rel=\"noopener\">SEI_GOVERNADORIA &#8211; 64509300 &#8211; Termo de Refer\u00eancia<\/a><\/p>\n<p><a href=\"https:\/\/www.pm.go.gov.br\/wp-content\/uploads\/2024\/09\/pregao-eletronico-no-182024pmgo-8.pdf\" target=\"_blank\" rel=\"noopener\">Especifica\u00e7\u00e3o t\u00e9cnica<\/a><\/p>\n<p><a href=\"https:\/\/www.pm.go.gov.br\/wp-content\/uploads\/2024\/09\/pregao-eletronico-no-182024pmgo-7.pdf\" target=\"_blank\" rel=\"noopener\">SEI_GOVERNADORIA &#8211; 64722258 &#8211; Minuta de Nota de Empenho<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVISO DE LICITA\u00c7\u00c3O PREG\u00c3O ELETR\u00d4NICO N\u00ba 18\/2024\/PMGO PROCESSO N\u00b0 202400005025080 Contrata\u00e7\u00e3o SISLOG n\u00ba 107340 O Estado de Goi\u00e1s, por interm\u00e9dio da POL\u00cdCIA MILITAR DO ESTADO DE GOI\u00c1S torna p\u00fablico, para conhecimento dos interessados, que realizar\u00e1 procedimento na modalidade Preg\u00e3o Eletr\u00f4nico, tipo Menor Pre\u00e7o por Lote, sendo Lote exclusivo para Microempresas e Empresas de Pequeno Porte, [&hellip;]<\/p>\n","protected":false},"author":504,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[13],"tags":[],"class_list":["post-258758","post","type-post","status-publish","format-standard","hentry","category-editais-pm"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"carolinaluz","author_link":"https:\/\/goias.gov.br\/seguranca\/author\/carolinaluz\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/seguranca\/categoria\/editais-pm\/\" rel=\"category tag\">Editais PM<\/a>","rttpg_excerpt":"AVISO DE LICITA\u00c7\u00c3O PREG\u00c3O ELETR\u00d4NICO N\u00ba 18\/2024\/PMGO PROCESSO N\u00b0 202400005025080 Contrata\u00e7\u00e3o SISLOG n\u00ba 107340 O Estado de Goi\u00e1s, por interm\u00e9dio da POL\u00cdCIA MILITAR DO ESTADO DE GOI\u00c1S torna p\u00fablico, para conhecimento dos interessados, que realizar\u00e1 procedimento na modalidade Preg\u00e3o Eletr\u00f4nico, tipo Menor Pre\u00e7o por Lote, sendo Lote exclusivo para Microempresas e Empresas de Pequeno Porte,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/258758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/users\/504"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/comments?post=258758"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/258758\/revisions"}],"predecessor-version":[{"id":258759,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/posts\/258758\/revisions\/258759"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/media?parent=258758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/categories?post=258758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/seguranca\/wp-json\/wp\/v2\/tags?post=258758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}