{"id":9973,"date":"2017-07-24T12:07:25","date_gmt":"2017-07-24T15:07:25","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/1a-conferencia-estadual-de-vigilancia-em-saude-cevs\/"},"modified":"2017-07-24T12:07:25","modified_gmt":"2017-07-24T15:07:25","slug":"1a-conferencia-estadual-de-vigilancia-em-saude-cevs","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/1a-conferencia-estadual-de-vigilancia-em-saude-cevs\/","title":{"rendered":"1\u00aa Confer\u00eancia Estadual de Vigil\u00e2ncia em Sa\u00fade &#8211; CEVS"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9972\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435.jpg\" alt=\"\" width=\"1296\" height=\"1573\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435.jpg 1296w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435-247x300.jpg 247w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435-844x1024.jpg 844w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435-768x932.jpg 768w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435-1266x1536.jpg 1266w\" sizes=\"(max-width: 1296px) 100vw, 1296px\" \/><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p><strong>O QUE &Eacute;<em><\/em><\/strong><\/p>\n<p>A Confer&ecirc;ncia Estadual de Vigil&acirc;ncia em Sa&uacute;de &#8211; CEVS &eacute; uma das tr&ecirc;s etapas da Confer&ecirc;ncia Nacional de Vigil&acirc;ncia em Sa&uacute;de &ndash;&nbsp; CNVS composta pelos componentes municipal, estadual e nacional. A decis&atilde;o de realizar a 1&ordf; CNVS surgiu na 15&ordf; Confer&ecirc;ncia Nacional de Sa&uacute;de realizada em 2015, que identificou a necessidade de fortalecer a participa&ccedil;&atilde;o de Vigil&acirc;ncia em Sa&uacute;de na formula&ccedil;&atilde;o da Pol&iacute;tica de Sa&uacute;de conforme determinam a Lei n&ordm; 8080\/1990 e a Lei n&ordm; 8.142\/1990.<\/p>\n<p>A exemplo da CNVS, a CEVS tamb&eacute;m est&aacute; estruturada em tr&ecirc;s etapas: Confer&ecirc;ncia Municipal de Vigil&acirc;ncia em Sa&uacute;de,&nbsp; Confer&ecirc;ncia Regional de Vigil&acirc;ncia em Sa&uacute;de e Confer&ecirc;ncia Estadual de Vigil&acirc;ncia em Sa&uacute;de. Estes, s&atilde;o espa&ccedil;os para se debater os problemas, as propostas de mudan&ccedil;as e de melhorias nos processos e nas a&ccedil;&otilde;es de Vigil&acirc;ncia em Sa&uacute;de, incluindo a gest&atilde;o, em prol de uma melhor qualidade de vida dos usu&aacute;rios do SUS. Tem como tema um eixo principal: <strong>&ldquo;Pol&iacute;tica Nacional de Vigil&acirc;ncia em Sa&uacute;de e o fortalecimento do SUS como direito &agrave; Prote&ccedil;&atilde;o e Promo&ccedil;&atilde;o da Sa&uacute;de do povo Brasileiro&rdquo;<\/strong> e est&aacute; dividido em quatro subeixos: &bull; Subeixo <strong>1 &#8211; O Lugar da Vigil&acirc;ncia em Sa&uacute;de no SUS<\/strong> &bull; Subeixo <strong>2 &#8211; Responsabilidades do Estado e dos governos com a vigil&acirc;ncia em sa&uacute;de<\/strong> &bull; Subeixo <strong>3 &#8211; Saberes, Pr&aacute;ticas, processos de trabalhos e tecnologias na vigil&acirc;ncia em sa&uacute;de. <\/strong>&bull; Subeixo <strong>4 &#8211; Vigil&acirc;ncia em sa&uacute;de participativa e democr&aacute;tica para enfrentamento das iniquidades sociais em sa&uacute;de.<\/strong><\/p>\n<p><strong>OBJETIVO<em><\/em><\/strong><\/p>\n<p>Envolver a comunidade, usu&aacute;rios do SUS, a sociedade organizada e os profissionais e t&eacute;cnicos da sa&uacute;de, que vivem em diferentes regi&otilde;es do Estado, na discuss&atilde;o de temas relacionados &agrave; promo&ccedil;&atilde;o, preven&ccedil;&atilde;o, prote&ccedil;&atilde;o e gest&atilde;o na &aacute;rea de sa&uacute;de, com a finalidade de produzir diretrizes e propostas que possam contribuir na formula&ccedil;&atilde;o da Pol&iacute;tica Nacional de Vigil&acirc;ncia em Sa&uacute;de.<\/p>\n<p><strong>COMO FUNCIONA<em><\/em><\/strong><\/p>\n<p>Ap&oacute;s finalizada a solenidade de abertura e aprovado o Regulamento da Confer&ecirc;ncia, dar-se-&aacute; in&iacute;cio &agrave; apresenta&ccedil;&atilde;o de palestras que constam da programa&ccedil;&atilde;o. Os delegados eleitos nas Confer&ecirc;ncias Municipais, os representantes das organiza&ccedil;&otilde;es dos usu&aacute;rios do SUS, os Gestores, os profissionais que trabalham na &aacute;rea de sa&uacute;de de institui&ccedil;&otilde;es p&uacute;blicas, privadas e filantr&oacute;picas e os convidados da comunidade, reunir-se-&atilde;o em grupos para debater sobre as propostas apresentadas. Os temas colocados em debate&nbsp; provenientes das Confer&ecirc;ncias Municipais de Sa&uacute;de, que constam nos relat&oacute;rios. Os delegados ter&atilde;o direito a voz e voto nas mesas que decidir&atilde;o quais Diretrizes e Propostas dever&atilde;o ser colocadas em pauta para aprova&ccedil;&atilde;o da Plen&aacute;ria.&nbsp; Dentre os assuntos que ser&atilde;o debatidos destacam-se: estrutura das redes de servi&ccedil;o e de aten&ccedil;&atilde;o &agrave; sa&uacute;de que tenham repercuss&atilde;o no Estado; a integralidade da aten&ccedil;&atilde;o; cobertura vacinal; a&ccedil;&otilde;es das vigil&acirc;ncias sanit&aacute;ria e ambiental; aten&ccedil;&atilde;o prim&aacute;ria, nos problemas de sa&uacute;de referentes &agrave;s doen&ccedil;as transmiss&iacute;veis e doen&ccedil;as e agravos n&atilde;o transmiss&iacute;veis; diagn&oacute;stico laboratorial e de assist&ecirc;ncia m&eacute;dica; vigil&acirc;ncia da sa&uacute;de do trabalhador e as interfaces da vigil&acirc;ncia em sa&uacute;de relacionadas &agrave; gest&atilde;o.<\/p>\n<p>Das Confer&ecirc;ncias Regionais sair&atilde;o os delegados que participar&atilde;o da etapa estadual da CEVS a ser realizada em Goi&acirc;nia no m&ecirc;s de outubro. Somam-se a eles, os convidados da Secretaria Estadual de Sa&uacute;de &#8211; SES e do Conselho Estadual de Sa&uacute;de &ndash; CES. As propostas levantadas na 1&ordf; CEVS subsidiar&atilde;o a elabora&ccedil;&atilde;o e efetiva&ccedil;&atilde;o da Politica Nacional de Vigil&acirc;ncia em Sa&uacute;de. O relat&oacute;rio resultante da 1&ordf; CEVS ser&aacute; encaminhado para a etapa nacional da 1&ordf; CNVS. Os delegados eleitos na 1&ordf; CEVS,&nbsp; representar&atilde;o o Estado de Goi&aacute;s na 1&ordf; CNVS em Bras&iacute;lia no m&ecirc;s de novembro\/2017.<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O QUE &Eacute; A Confer&ecirc;ncia Estadual de Vigil&acirc;ncia em Sa&uacute;de &#8211; CEVS &eacute; uma das tr&ecirc;s etapas da Confer&ecirc;ncia Nacional de Vigil&acirc;ncia em Sa&uacute;de &ndash;&nbsp; CNVS composta pelos componentes municipal, estadual e nacional. A decis&atilde;o de realizar a 1&ordf; CNVS surgiu na 15&ordf; Confer&ecirc;ncia Nacional de Sa&uacute;de realizada em 2015, que identificou a necessidade de [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":9972,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-9973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-conselho"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435.jpg",1296,1573,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435.jpg",1296,1573,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435.jpg",1296,1573,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435-247x300.jpg",247,300,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435-844x1024.jpg",844,1024,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435-1266x1536.jpg",1266,1536,true],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/07\/logo-final-1-cevs-435.jpg",1296,1573,false]},"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/conselho-estadual-de-saude\/noticias-conselho\/\" rel=\"category tag\">Not\u00edcias Conselho<\/a>","rttpg_excerpt":"O QUE &Eacute; A Confer&ecirc;ncia Estadual de Vigil&acirc;ncia em Sa&uacute;de &#8211; CEVS &eacute; uma das tr&ecirc;s etapas da Confer&ecirc;ncia Nacional de Vigil&acirc;ncia em Sa&uacute;de &ndash;&nbsp; CNVS composta pelos componentes municipal, estadual e nacional. A decis&atilde;o de realizar a 1&ordf; CNVS surgiu na 15&ordf; Confer&ecirc;ncia Nacional de Sa&uacute;de realizada em 2015, que identificou a necessidade de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=9973"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/9972"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=9973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=9973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=9973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}