{"id":9887,"date":"2018-06-11T08:06:14","date_gmt":"2018-06-11T11:06:14","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/o-ces-go-participara-de-audiencia-publica-de-constituicao-e-lancamento-do-forum-estadual-de-prevencao-e-erradicacao-do-trabalho-infantil-e-promocao-da-aprendizagem\/"},"modified":"2018-06-11T08:06:14","modified_gmt":"2018-06-11T11:06:14","slug":"o-ces-go-participara-de-audiencia-publica-de-constituicao-e-lancamento-do-forum-estadual-de-prevencao-e-erradicacao-do-trabalho-infantil-e-promocao-da-aprendizagem","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/o-ces-go-participara-de-audiencia-publica-de-constituicao-e-lancamento-do-forum-estadual-de-prevencao-e-erradicacao-do-trabalho-infantil-e-promocao-da-aprendizagem\/","title":{"rendered":"O CES-GO participar\u00e1 de Audi\u00eancia P\u00fablica de Constitui\u00e7\u00e3o e Lan\u00e7amento do F\u00f3rum Estadual de Preven\u00e7\u00e3o e Erradica\u00e7\u00e3o do Trabalho Infantil e Promo\u00e7\u00e3o da Aprendizagem."},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p>O Conselho Estadual de Sa&uacute;de de Goi&aacute;s (CES-GO) participar&aacute; de Audi&ecirc;ncia P&uacute;blica de Constitui&ccedil;&atilde;o e Lan&ccedil;amento do F&oacute;rum Estadual de Preven&ccedil;&atilde;o e Erradica&ccedil;&atilde;o do Trabalho Infantil e Promo&ccedil;&atilde;o da Aprendizagem &#8211; FEPETIAGO, a ser promovido no dia 12\/06\/2018, no Audit&oacute;rio Costa Lima da Assembleia Legislativa do Estado de Goi&aacute;s.<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Estadual de Sa&uacute;de de Goi&aacute;s (CES-GO) participar&aacute; de Audi&ecirc;ncia P&uacute;blica de Constitui&ccedil;&atilde;o e Lan&ccedil;amento do F&oacute;rum Estadual de Preven&ccedil;&atilde;o e Erradica&ccedil;&atilde;o do Trabalho Infantil e Promo&ccedil;&atilde;o da Aprendizagem &#8211; FEPETIAGO, a ser promovido no dia 12\/06\/2018, no Audit&oacute;rio Costa Lima da Assembleia Legislativa do Estado de Goi&aacute;s.<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-9887","post","type-post","status-publish","format-standard","hentry","category-noticias-conselho"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/conselho-estadual-de-saude\/noticias-conselho\/\" rel=\"category tag\">Not\u00edcias Conselho<\/a>","rttpg_excerpt":"O Conselho Estadual de Sa&uacute;de de Goi&aacute;s (CES-GO) participar&aacute; de Audi&ecirc;ncia P&uacute;blica de Constitui&ccedil;&atilde;o e Lan&ccedil;amento do F&oacute;rum Estadual de Preven&ccedil;&atilde;o e Erradica&ccedil;&atilde;o do Trabalho Infantil e Promo&ccedil;&atilde;o da Aprendizagem &#8211; FEPETIAGO, a ser promovido no dia 12\/06\/2018, no Audit&oacute;rio Costa Lima da Assembleia Legislativa do Estado de Goi&aacute;s.","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=9887"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9887\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=9887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=9887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=9887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}