

{"id":9685,"date":"2018-04-24T12:04:36","date_gmt":"2018-04-24T15:04:36","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/sest-sus-participa-de-seminario-internacional-no-conass\/"},"modified":"2018-04-24T12:04:36","modified_gmt":"2018-04-24T15:04:36","slug":"sest-sus-participa-de-seminario-internacional-no-conass","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/sest-sus-participa-de-seminario-internacional-no-conass\/","title":{"rendered":"Sest\/SUS participa de Semin\u00e1rio Internacional no Conass"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9684\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9.jpg\" alt=\"\" width=\"1280\" height=\"854\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9.jpg 1280w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9-300x200.jpg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9-1024x683.jpg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p>A Superintendente de Educa&ccedil;&atilde;o em Sa&uacute;de e Trabalho para o SUS, Rafaela Veronezi, participou hoje, 24\/04, de um debate que reuniu especialistas do Brasil, Canad&aacute;, Costa Rica, Portugal e Reino Unido sobre o futuro dos sistemas universais de sa&uacute;de no Conselho Nacional de Secret&aacute;rios de Sa&uacute;de &ndash; Conass, em Bras&iacute;lia. Ao lado da Superintendente de Pol&iacute;ticas de Aten&ccedil;&atilde;o Integral &agrave; Sa&uacute;de, Evandilde Fernandes ela acompanhou o Secret&aacute;rio de Estado da Sa&uacute;de de Goi&aacute;s, Leonardo Vilela, que tomar&aacute; posse, ainda hoje, na presid&ecirc;ncia do Conass.<\/p>\n<p><strong>Debate<\/strong><\/p>\n<p>As transforma&ccedil;&otilde;es sociais, pol&iacute;ticas e econ&ocirc;micas t&ecirc;m gerado constantes mudan&ccedil;as no perfil demogr&aacute;fico e epidemiol&oacute;gico das popula&ccedil;&otilde;es em todo o mundo. Esse fen&ocirc;meno tem impactado fortemente os sistemas de sa&uacute;de, principalmente aqueles que t&ecirc;m a universalidade como princ&iacute;pio, tornando a sustentabilidade desses um desafio a ser enfrentado em diversos pa&iacute;ses.<\/p>\n<p>Diante deste cen&aacute;rio, o CONASS &ndash; Conselho Nacional de Secret&aacute;rios de Sa&uacute;de &ndash; convidou especialistas do Brasil, Canad&aacute;, Costa Rica, Portugal e Reino Unido para esse debate sobre o futuro dos sistemas universais de sa&uacute;de, em especial do Sistema &Uacute;nico de Sa&uacute;de (SUS).<\/p>\n<p>O projeto CONASS Debate tem como tema &ldquo;O Futuro dos Sistemas Universais de Sa&uacute;de&rdquo;, com objetivo de discutir estrat&eacute;gias e a&ccedil;&otilde;es que possibilitem o fortalecimento do SUS.<\/p>\n<p>O debate pretende, no ano em que o sistema de sa&uacute;de brasileiro completa 30 anos, buscar solu&ccedil;&otilde;es em um cen&aacute;rio de grave crise pol&iacute;tica e econ&ocirc;mica que amea&ccedil;a n&atilde;o apenas o sistema, idealizado e constru&iacute;do para atender a todos de maneira igualit&aacute;ria e equ&acirc;nime, mas o direito &agrave; sa&uacute;de conquistado e estabelecido da Constitui&ccedil;&atilde;o Federal de 1988.<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Superintendente de Educa&ccedil;&atilde;o em Sa&uacute;de e Trabalho para o SUS, Rafaela Veronezi, participou hoje, 24\/04, de um debate que reuniu especialistas do Brasil, Canad&aacute;, Costa Rica, Portugal e Reino Unido sobre o futuro dos sistemas universais de sa&uacute;de no Conselho Nacional de Secret&aacute;rios de Sa&uacute;de &ndash; Conass, em Bras&iacute;lia. Ao lado da Superintendente de [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":9684,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-9685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vigilancia-em-saude"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9.jpg",1280,854,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9.jpg",1280,854,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9.jpg",1280,854,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9-300x200.jpg",300,200,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9.jpg",1280,854,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/foto-dr_-leonardo-conass-24-de-abril-2018-cb9.jpg",1280,854,false]},"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/vigilancia-em-saude\/\" rel=\"category tag\">Vigil\u00e2ncia em Sa\u00fade<\/a>","rttpg_excerpt":"A Superintendente de Educa&ccedil;&atilde;o em Sa&uacute;de e Trabalho para o SUS, Rafaela Veronezi, participou hoje, 24\/04, de um debate que reuniu especialistas do Brasil, Canad&aacute;, Costa Rica, Portugal e Reino Unido sobre o futuro dos sistemas universais de sa&uacute;de no Conselho Nacional de Secret&aacute;rios de Sa&uacute;de &ndash; Conass, em Bras&iacute;lia. Ao lado da Superintendente de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=9685"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/9684"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=9685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=9685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=9685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}