{"id":9683,"date":"2018-04-24T12:04:02","date_gmt":"2018-04-24T15:04:02","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/gestores-participam-de-construcao-do-peeps-em-formosa\/"},"modified":"2018-04-24T12:04:02","modified_gmt":"2018-04-24T15:04:02","slug":"gestores-participam-de-construcao-do-peeps-em-formosa","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/gestores-participam-de-construcao-do-peeps-em-formosa\/","title":{"rendered":"Gestores participam de constru\u00e7\u00e3o do PEEPS em Formosa"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9682\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544.jpg\" alt=\"\" width=\"1032\" height=\"581\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544.jpg 1032w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544-300x169.jpg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544-1024x576.jpg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544-768x432.jpg 768w\" sizes=\"(max-width: 1032px) 100vw, 1032px\" \/><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Acontece hoje na regi&atilde;o do&nbsp; Entorno Norte &#8211; munic&iacute;pio de&nbsp; Formosa a 2&deg;oficina&nbsp; para constru&ccedil;&atilde;o do Plano Estadual de Educa&ccedil;&atilde;o Permanente em sa&uacute;de PEEPS. A proposta para a constru&ccedil;&atilde;o do plano &eacute; a realiza&ccedil;&atilde;o de encontros como este nas 18 regi&otilde;es do estado. O objetivo das oficinas &eacute; a identifica&ccedil;&atilde;o dos problemas existentes no &acirc;mbito de a&ccedil;&otilde;es e servi&ccedil;os de sa&uacute;de, que demandam, para sua solu&ccedil;&atilde;o, o desenvolvimento de a&ccedil;&otilde;es de educa&ccedil;&atilde;o permanente em sa&uacute;de (EPS), ou seja, a&ccedil;&otilde;es que envolvam qualifica&ccedil;&atilde;o, forma&ccedil;&atilde;o ou capacita&ccedil;&atilde;o. Na oficina da regi&atilde;o Entorno Norte est&atilde;o participando os gestores dos munic&iacute;pios &Aacute;gua&nbsp; Fria, Alto Para&iacute;so, cabeceiras, Flores de Goi&aacute;s, Formosa, Planaltina, S&atilde;o&nbsp; Jo&atilde;o da Alian&ccedil;a e Vila Boa, participam tamb&eacute;m coordenadores de Educa&ccedil;&atilde;o Permanente, representes da CIES a coordenadora da Regional de sa&uacute;de, Secret&aacute;rios de Sa&uacute;de dos munic&iacute;pios referidos e demais colaboradores.<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Acontece hoje na regi&atilde;o do&nbsp; Entorno Norte &#8211; munic&iacute;pio de&nbsp; Formosa a 2&deg;oficina&nbsp; para constru&ccedil;&atilde;o do Plano Estadual de Educa&ccedil;&atilde;o Permanente em sa&uacute;de PEEPS. A proposta para a constru&ccedil;&atilde;o do plano &eacute; a realiza&ccedil;&atilde;o de encontros como este nas 18 regi&otilde;es do [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":9682,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-9683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vigilancia-em-saude"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544.jpg",1032,581,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544.jpg",1032,581,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544.jpg",1032,581,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544-300x169.jpg",300,169,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544.jpg",1032,581,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/04\/oficina-peeps-formosa-abril-2018-544.jpg",1032,581,false]},"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/vigilancia-em-saude\/\" rel=\"category tag\">Vigil\u00e2ncia em Sa\u00fade<\/a>","rttpg_excerpt":"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Acontece hoje na regi&atilde;o do&nbsp; Entorno Norte &#8211; munic&iacute;pio de&nbsp; Formosa a 2&deg;oficina&nbsp; para constru&ccedil;&atilde;o do Plano Estadual de Educa&ccedil;&atilde;o Permanente em sa&uacute;de PEEPS. A proposta para a constru&ccedil;&atilde;o do plano &eacute; a realiza&ccedil;&atilde;o de encontros como este nas 18 regi&otilde;es do&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=9683"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/9682"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=9683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=9683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=9683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}