{"id":839228,"date":"2026-06-10T13:37:33","date_gmt":"2026-06-10T16:37:33","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=839228"},"modified":"2026-06-10T13:37:33","modified_gmt":"2026-06-10T16:37:33","slug":"extrato-da-portaria-no-1590-2026-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-da-portaria-no-1590-2026-ses-go\/","title":{"rendered":"Extrato da Portaria n\u00ba 1590\/2026 \u2013 SES\/GO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">EXTRATO DA PORTARIA N\u00ba 1590\/2026\/SES\/GO, PROCESSO 202600010014378<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de recursos financeiros pelas Organiza\u00e7\u00f5es Sociais de Sa\u00fade e\/ou Organiza\u00e7\u00f5es da Sociedade Civil a t\u00edtulo de investimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Considerando o Of\u00edcio de Solicita\u00e7\u00e3o de Recursos n\u00ba 496413\/2026\/AGIR (SEI n\u00ba 90743737), o Despacho n\u00ba 304\/2026\/SES\/GPINFRA-21298 (90776612), a Requisi\u00e7\u00e3o de Despesa n\u00ba 59\/2026 (90929424), o Despacho n\u00ba 109\/2026 &#8211; GERTEL (90929817) e, Considerando ainda o que consta no Processo n\u00ba 202600010014378, resolve:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art. 1\u00ba. APROVAR o repasse de recursos, do Fundo Estadual de Sa\u00fade\/FES para a Associa\u00e7\u00e3o de Gest\u00e3o, Inova\u00e7\u00e3o e Resultados em Sa\u00fade &#8211; AGIR, Organiza\u00e7\u00e3o Social de Sa\u00fade respons\u00e1vel pelo Hospital Estadual de Jata\u00ed Dr. Serafim de Carvalho \u2013 HEJ, a t\u00edtulo de investimento para aquisi\u00e7\u00e3o de equipamentos, conforme se observa no anexo \u00fanico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art. 2\u00ba. DETERMINAR a transfer\u00eancia de recursos, na modalidade de transfer\u00eancias para organiza\u00e7\u00f5es sem fins lucrativos, no valor correspondente ao da Requisi\u00e7\u00e3o de Despesas no total de R$35.000,00 (trinta e cinco mil reais).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par\u00e1grafo \u00fanico. Em caso de irregularidades na presta\u00e7\u00e3o de contas, o processo ser\u00e1 encaminhado \u00e0 Superintend\u00eancia de Monitoramento dos Conv\u00eanios e Contratos de Gest\u00e3o &#8211; SUPECC para acompanhamento e monitoramento (art. 48 da Portaria n\u00ba 3924\/2024 &#8211; SES\/GO (68882873)).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art. 3\u00ba A vig\u00eancia do presente instrumento ser\u00e1 de 12 (doze) meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">RAS\u00cdVEL DOS REIS SANTOS J\u00daNIOR<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ANEXO \u00daNICO<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Detalhamento<\/strong><\/td><td><strong>Qtde<\/strong><\/td><td><strong>Prazo para sua Realiza\u00e7\u00e3o<\/strong><\/td><td><strong>Estimativa de Custo Unit\u00e1rio<\/strong><\/td><td><strong>Estimativa<\/strong><strong> <\/strong><strong>de Custo Total<\/strong><\/td><\/tr><tr><td><a><\/a> Repasse de recursos \u00e0 Associa\u00e7\u00e3o de Gest\u00e3o, Inova\u00e7\u00e3o e Resultados em Sa\u00fade \u2013 AGIR a t\u00edtulo de investimento, <strong>para contrata\u00e7\u00e3o de empresa especializada na elabora\u00e7\u00e3o de maquete eletr\u00f4nica,<\/strong><strong> <\/strong>destinado ao Hospital Estadual de Jata\u00ed Dr. Serafim de Carvalho \u2013 HEJ, conforme DESPACHO N\u00ba 304\/2026\/SES\/GPINFRA-21298 (<a href=\"https:\/\/sei.go.gov.br\/sei\/controlador.php?acao=protocolo_visualizar&amp;id_protocolo=95533574&amp;id_procedimento_atual=91135546&amp;infra_sistema=100000100&amp;infra_unidade_atual=6506&amp;infra_hash=48d9548735de39769697a227cdf172ae6f254229400976d252d8275ce3845edbbe153522e59cf048ef86f953884f9282d64f2540a3fe36462b7b556c0ff6b753daf1444c4a11d54766fef3b4821f08471dbe8e0f066d3d1c8868029fb5225e66\" target=\"_blank\" rel=\"noreferrer noopener\">90776612<\/a>).<\/td><td>01<\/td><td>Imediato<\/td><td><strong>R$ 35.00,00&nbsp;<\/strong><\/td><td><strong>R$ 35.00,00&nbsp;<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D<\/strong><strong>ata da assinatura:<\/strong> 08\/06\/2026. Signat\u00e1rio: Ras\u00edvel dos Reis Santos J\u00fanior &#8211; Secret\u00e1rio de Estado da Sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EXTRATO DA PORTARIA N\u00ba 1590\/2026\/SES\/GO, PROCESSO 202600010014378 O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[503],"tags":[],"class_list":["post-839228","post","type-post","status-publish","format-standard","hentry","category-extrato-de-portarias-2026"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ricardocruz","author_link":"https:\/\/goias.gov.br\/saude\/author\/ricardocruz\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/extrato-de-portarias-2026\/\" rel=\"category tag\">Extrato de Portarias 2026<\/a>","rttpg_excerpt":"EXTRATO DA PORTARIA N\u00ba 1590\/2026\/SES\/GO, PROCESSO 202600010014378 O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/839228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=839228"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/839228\/revisions"}],"predecessor-version":[{"id":839255,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/839228\/revisions\/839255"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=839228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=839228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=839228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}