{"id":7959,"date":"2019-09-02T05:09:45","date_gmt":"2019-09-02T08:09:45","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/jornada-cientifica-do-hdt-aborda-temas-relevantes-na-area-da-saude\/"},"modified":"2019-09-02T05:09:45","modified_gmt":"2019-09-02T08:09:45","slug":"jornada-cientifica-do-hdt-aborda-temas-relevantes-na-area-da-saude","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/jornada-cientifica-do-hdt-aborda-temas-relevantes-na-area-da-saude\/","title":{"rendered":"JORNADA CIENT\u00cdFICA DO HDT ABORDA TEMAS RELEVANTES NA \u00c1REA DA SA\u00daDE"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-7958\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94.jpg\" alt=\"\" width=\"1500\" height=\"937\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94.jpg 1500w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94-300x187.jpg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94-1024x640.jpg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94-768x480.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p>A superintendente da Escola de Sa&uacute;de de Goi&aacute;s (ESG), Kelli Coelho Santos, participou, nesta quinta-feira (29), da abertura da VIII JORNADA CIENT&Iacute;FICA DO Hospital Estadual de Doen&ccedil;as Tropicais Dr. Anuar Rassi. Realizada no Audit&oacute;rio da &Aacute;rea VI da PUC-GO: Escola de Forma&ccedil;&atilde;o de Professores e Humanidades, a solenidade contou com a presen&ccedil;a da Secret&aacute;ria Municipal de Sa&uacute;de, Dra F&aacute;tima Mru&eacute;; o diretor do HDT, Dr. Roger Moreira, e a diretora de Ensino e Pesquisa deste hospital, Dra. Mar&iacute;lia Dalva Turchi, que tamb&eacute;m &eacute; a coordenaora da Jornada.<\/p>\n<p>O evento durou dois dias e abordou temas relevantes na &aacute;rea da sa&uacute;de de interesse regional e nacional. Durante a jornada, foram realizadas mesas redondas e minicursos sobre assuntos atuais relacionados &agrave;s doen&ccedil;as infecciosas e dermatol&oacute;gicas e atualidades em sa&uacute;de, voltados para colaboradores da institui&ccedil;&atilde;o, profissionais e acad&ecirc;micos da &aacute;rea da sa&uacute;de.<\/p>\n<p><strong><em>HDT como refer&ecirc;ncia <\/em><\/strong><\/p>\n<p>Durante seu discurso, Kelli destacou a import&acirc;ncia do HDT na forma&ccedil;&atilde;o profissional na &aacute;rea de sa&uacute;de com enfoque em doen&ccedil;as infecciosas e dermatol&oacute;gicas, e da pesquisa cient&iacute;fica como instrumento de melhoria no atendimento aos usu&aacute;rios do Sistema &Uacute;nico de Sa&uacute;de.<\/p>\n<p>&ldquo;Segundo dados do Sistema de Monitoramento de Pesquisas, desde 2012 j&aacute; foram realizadas 65 pesquisas cient&iacute;ficas no HDT. S&oacute; neste ano s&atilde;o 20 pesquisas em andamento neste hospital, e um total de 77 pesquisas em andamento nas unidades p&uacute;blicas de sa&uacute;de do Estado de Goi&aacute;s&rdquo;, afirmou.<\/p>\n<p><strong><em>III Jornada Cient&iacute;fica da SES-GO ser&aacute; em outubro<\/em><\/strong><\/p>\n<p>O fomento da SES-GO na realiza&ccedil;&atilde;o de a&ccedil;&otilde;es educacionais com o objetivo de qualificar atores sociais do SUS para a produ&ccedil;&atilde;o e dissemina&ccedil;&atilde;o do conhecimento cient&iacute;fico atinge seu ponto alto de 2019 durante a III Jornada Cient&iacute;fica da SES-GO. Quem toma frente da organiza&ccedil;&atilde;o do evento, que est&aacute; programado para final de outubro, &eacute; a Ger&ecirc;ncia de Pesquisa e Inova&ccedil;&atilde;o da Escola de Sa&uacute;de de Goi&aacute;s. A expectativa &eacute; reunir cerca de 300 pesquisadores, docentes, discentes das Institui&ccedil;&otilde;es de Ensino e Pesquisa, membros de CEPs, gestores e profissionais de sa&uacute;de do Estado de Goi&aacute;s.<\/p>\n<p>Com o tema &ldquo;Ci&ecirc;ncia no cotidiano do SUS&rdquo;, a jornada pretende fortalecer as discuss&otilde;es no campo cient&iacute;fico em rela&ccedil;&atilde;o a temas como integridade na pesquisa da sa&uacute;de humana, comunica&ccedil;&atilde;o cient&iacute;fica e gest&atilde;o p&uacute;blica no SUS informada por evid&ecirc;ncias.<\/p>\n<p>Gabriela Dutra, da Comunica&ccedil;&atilde;o da Escola de Sa&uacute;de de Goi&aacute;s<\/p>\n<p>Fotos: Karim Alexandre<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A superintendente da Escola de Sa&uacute;de de Goi&aacute;s (ESG), Kelli Coelho Santos, participou, nesta quinta-feira (29), da abertura da VIII JORNADA CIENT&Iacute;FICA DO Hospital Estadual de Doen&ccedil;as Tropicais Dr. Anuar Rassi. Realizada no Audit&oacute;rio da &Aacute;rea VI da PUC-GO: Escola de Forma&ccedil;&atilde;o de Professores e Humanidades, a solenidade contou com a presen&ccedil;a da Secret&aacute;ria Municipal [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":7958,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-7959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-escola"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94.jpg",1500,937,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94.jpg",1500,937,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94.jpg",1500,937,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94-300x187.jpg",300,187,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94-1024x640.jpg",1024,640,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94.jpg",1500,937,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2019\/09\/jornada-cientifica-hdt-c94.jpg",1500,937,false]},"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/escola-de-saude\/noticias-escola\/\" rel=\"category tag\">Not\u00edcias Escola<\/a>","rttpg_excerpt":"A superintendente da Escola de Sa&uacute;de de Goi&aacute;s (ESG), Kelli Coelho Santos, participou, nesta quinta-feira (29), da abertura da VIII JORNADA CIENT&Iacute;FICA DO Hospital Estadual de Doen&ccedil;as Tropicais Dr. Anuar Rassi. Realizada no Audit&oacute;rio da &Aacute;rea VI da PUC-GO: Escola de Forma&ccedil;&atilde;o de Professores e Humanidades, a solenidade contou com a presen&ccedil;a da Secret&aacute;ria Municipal&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=7959"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/7958"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=7959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=7959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=7959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}