

{"id":783548,"date":"2026-05-04T10:49:54","date_gmt":"2026-05-04T13:49:54","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/historico-do-cargo-superintendente-da-escola-de-saude-de-goias\/"},"modified":"2026-05-04T10:49:54","modified_gmt":"2026-05-04T13:49:54","slug":"historico-do-cargo-superintendente-da-escola-de-saude-de-goias","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/historico-do-cargo-superintendente-da-escola-de-saude-de-goias\/","title":{"rendered":"Hist\u00f3rico do Cargo Superintendente da Escola de Sa\u00fade de Goi\u00e1s"},"content":{"rendered":"<div class=\"accordion\" id=\"accordionExample\">\n<div class='accordion-item' style='border: none;'>\n<h2 class='accordion-header' id='heading-0'>\n                    <button class='accordion-button' type='button' data-bs-toggle='collapse' data-bs-target='#collapse-0' aria-expanded='false' aria-controls='collapse-0' style='border: none; background-color: transparent;'><br \/>\n                        Adriana Martins de Lucena: de: 03-06-2024 at\u00e9 07-06-2024  &#8211; interino<br \/>\n                    <\/button><br \/>\n                <\/h2>\n<div id='collapse-0' class='accordion-collapse collapse' aria-labelledby='heading-0' data-bs-parent='#accordionExample'>\n<div class='accordion-body'>\n<div class=\"r34ics-ajax-container loading\" id=\"historico-agenda-autoridades\" data-view=\"month\" data-view-is-list-style=\"0\" data-view-is-list-long=\"0\" data-args=\"8f7c9e0d7747fca0d798a5c843c590deaeb44ccc\" data-js-args=\"{&quot;debug&quot;:null}\">&nbsp;<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class='accordion-item' style='border: none;'>\n<h2 class='accordion-header' id='heading-1'>\n                    <button class='accordion-button' type='button' data-bs-toggle='collapse' data-bs-target='#collapse-1' aria-expanded='false' aria-controls='collapse-1' style='border: none; background-color: transparent;'><br \/>\n                        ADRIANA MARTINS DE LUCENA: de: 18-10-2024 at\u00e9 23-10-2024  &#8211; interino<br \/>\n                    <\/button><br \/>\n                <\/h2>\n<div id='collapse-1' class='accordion-collapse collapse' aria-labelledby='heading-1' data-bs-parent='#accordionExample'>\n<div class='accordion-body'>\n<div class=\"r34ics-ajax-container loading\" id=\"historico-agenda-autoridades\" data-view=\"month\" data-view-is-list-style=\"0\" data-view-is-list-long=\"0\" data-args=\"5ae82ca77a34557ea5a7aa178b6c48fc7e9f335f\" data-js-args=\"{&quot;debug&quot;:null}\">&nbsp;<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class='accordion-item' style='border: none;'>\n<h2 class='accordion-header' id='heading-2'>\n                    <button class='accordion-button' type='button' data-bs-toggle='collapse' data-bs-target='#collapse-2' aria-expanded='false' aria-controls='collapse-2' style='border: none; background-color: transparent;'><br \/>\n                        ADRIANA MARTINS DE LUCENA: de: 17-12-2024 at\u00e9 03-01-2025  &#8211; interino<br \/>\n                    <\/button><br \/>\n                <\/h2>\n<div id='collapse-2' class='accordion-collapse collapse' aria-labelledby='heading-2' data-bs-parent='#accordionExample'>\n<div class='accordion-body'>\n<div class=\"r34ics-ajax-container loading\" id=\"historico-agenda-autoridades\" data-view=\"month\" data-view-is-list-style=\"0\" data-view-is-list-long=\"0\" data-args=\"ab4b07d2d4738ef2e44ae2c263ecd1386f71be39\" data-js-args=\"{&quot;debug&quot;:null}\">&nbsp;<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class='accordion-item' style='border: none;'>\n<h2 class='accordion-header' id='heading-3'>\n                    <button class='accordion-button' type='button' data-bs-toggle='collapse' data-bs-target='#collapse-3' aria-expanded='false' aria-controls='collapse-3' style='border: none; background-color: transparent;'><br \/>\n                        RAFAELA JULIA BATISTA VERONEZI: de: 01-08-2020 at\u00e9 31-08-2025<br \/>\n                    <\/button><br \/>\n                <\/h2>\n<div id='collapse-3' class='accordion-collapse collapse' aria-labelledby='heading-3' data-bs-parent='#accordionExample'>\n<div class='accordion-body'>\n<div class=\"r34ics-ajax-container loading\" id=\"historico-agenda-autoridades\" data-view=\"month\" data-view-is-list-style=\"0\" data-view-is-list-long=\"0\" data-args=\"cfbcd4d6b66cfbeb4140049a24035b13210bf920\" data-js-args=\"{&quot;debug&quot;:null}\">&nbsp;<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class='accordion-item' style='border: none;'>\n<h2 class='accordion-header' id='heading-4'>\n                    <button class='accordion-button' type='button' data-bs-toggle='collapse' data-bs-target='#collapse-4' aria-expanded='false' aria-controls='collapse-4' style='border: none; background-color: transparent;'><br \/>\n                        MIGUEL DE MENDONCA LABORAO: de: 05-01-2026 at\u00e9 09-01-2026  &#8211; interino<br \/>\n                    <\/button><br \/>\n                <\/h2>\n<div id='collapse-4' class='accordion-collapse collapse' aria-labelledby='heading-4' data-bs-parent='#accordionExample'>\n<div class='accordion-body'>\n<div class=\"r34ics-ajax-container loading\" id=\"historico-agenda-autoridades\" data-view=\"month\" data-view-is-list-style=\"0\" data-view-is-list-long=\"0\" data-args=\"91db335dc470ca3d04233ced2d4077ef4b8c31a2\" data-js-args=\"{&quot;debug&quot;:null}\">&nbsp;<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<style>\n        .accordion-button:hover {\n            background-color: #f8f9fa; \/* Cor cinza claro *\/\n            color: #6c757d; \/* Cor cinza do texto *\/\n        }\n        <\/style>\n","protected":false},"excerpt":{"rendered":"<p>Adriana Martins de Lucena: de: 03-06-2024 at\u00e9 07-06-2024 &#8211; interino ADRIANA MARTINS DE LUCENA: de: 18-10-2024 at\u00e9 23-10-2024 &#8211; interino ADRIANA MARTINS DE LUCENA: de: 17-12-2024 at\u00e9 03-01-2025 &#8211; interino RAFAELA JULIA BATISTA VERONEZI: de: 01-08-2020 at\u00e9 31-08-2025 MIGUEL DE MENDONCA LABORAO: de: 05-01-2026 at\u00e9 09-01-2026 &#8211; interino<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[356],"tags":[],"class_list":["post-783548","post","type-post","status-publish","format-standard","hentry","category-historico-de-agenda"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/historico-de-agenda\/\" rel=\"category tag\">historico-de-agenda<\/a>","rttpg_excerpt":"Adriana Martins de Lucena: de: 03-06-2024 at\u00e9 07-06-2024 &#8211; interino ADRIANA MARTINS DE LUCENA: de: 18-10-2024 at\u00e9 23-10-2024 &#8211; interino ADRIANA MARTINS DE LUCENA: de: 17-12-2024 at\u00e9 03-01-2025 &#8211; interino RAFAELA JULIA BATISTA VERONEZI: de: 01-08-2020 at\u00e9 31-08-2025 MIGUEL DE MENDONCA LABORAO: de: 05-01-2026 at\u00e9 09-01-2026 &#8211; interino","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/783548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=783548"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/783548\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=783548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=783548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=783548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}