{"id":714073,"date":"2026-02-27T08:16:16","date_gmt":"2026-02-27T11:16:16","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=714073"},"modified":"2026-02-27T08:16:16","modified_gmt":"2026-02-27T11:16:16","slug":"extrato-do-8o-apostilamento-ao-contrato-no-380-2019-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-do-8o-apostilamento-ao-contrato-no-380-2019-ses-go\/","title":{"rendered":"Extrato do 8\u00ba Apostilamento ao Contrato n\u00ba 380\/2019 \u2013 SES\/GO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">EXTRATO DO 8\u00ba APOSTILAMENTO AO CONTRATO N\u00ba 380\/2019-SES\/GO. Processo n\u00ba: \u00a0201900010008297. Contratada: \u00a0EQUATORIAL GOI\u00c1S DISTRIBUIDORA DE ENERGIA S.A. Objeto: Retifica\u00e7\u00e3o, em decorr\u00eancia de erro material, a\u00a0\u00a0CL\u00c1USULA PRIMEIRA\u00a0do 7\u00ba Apostilamento ao Contrato n\u00ba\u00a0380\/2019-SES\/GO\u00a0CUSD\/CCER. Onde se l\u00ea:01. CL\u00c1USULA PRIMEIRA \u2013 DA DOCUMENTA\u00c7\u00c3O OR\u00c7AMENT\u00c1RIA PARA O EXERC\u00cdCIO FINANCEIRO DE 2025:01.1 \u2013 A despesa para o exerc\u00edcio financeiro referente aos meses de Janeiro, Fevereiro, Mar\u00e7o e Abril de 2026 ter\u00e1 valor estimado de\u00a0R$ 839.554,15\u00a0(oitocentos e trinta e nove mil, quinhentos e cinquenta e quatro reais e quinze centavos),\u00a0cujo valor complementar \u00e9 de\u00a0R$711.779,53\u00a0(setecentos e onze mil, setecentos e setenta e nove reais e cinquenta e tr\u00eas centavos)\u00a0para unidades\u00a0Administrativas\u00a0e\u00a0R$ 127.774,62\u00a0(cento e vinte e sete mil, setecentos e setenta e quatro reais e sessenta e dois centavos)\u00a0para unidades\u00a0Assistenciais, conforme requisi\u00e7\u00e3o de despesa n\u00ba 3\/2026\/SES\/GAAL. Leia-se:01. CL\u00c1USULA PRIMEIRA \u2013 DA DOCUMENTA\u00c7\u00c3O OR\u00c7AMENT\u00c1RIA PARA O EXERC\u00cdCIO FINANCEIRO DE 2025 e 2026:01.1 \u2013 A despesa para o exerc\u00edcio financeiro de 2025, referente ao m\u00eas de dezembro de \u00a0ter\u00e1 valor estimado de\u00a0R$ 167.786,42\u00a0(cento e sessenta e sete mil, setecentos e oitenta e seis reais e quarenta e dois centavos), sendo o valor complementar \u00a0de\u00a0R$ 167.786,42\u00a0(cento e sessenta e sete mil, setecentos e oitenta e seis reais e quarenta e dois centavos) para\u00a0Unidades Administrativas,\u00a0conforme requisi\u00e7\u00e3o de despesa n\u00ba 32\/2025 \u2013 SES\/CGCC\/GAAL. 01.2-A despesa para o exerc\u00edcio financeiro 2026, referente aos meses de janeiro, fevereiro e mar\u00e7o ter\u00e1 valor estimado de\u00a0R$ 839.554,15\u00a0(oitocentos e trinta e nove mil, quinhentos e cinquenta e quatro reais e quinze centavos), sendo o\u00a0valor complementar \u00e9 de\u00a0R$ 711.779,53\u00a0(setecentos e onze mil, setecentos e setenta e nove reais e cinquenta e tr\u00eas centavos)\u00a0para unidades\u00a0Administrativas\u00a0e\u00a0R$ 127.774,62\u00a0(cento e vinte e sete mil, setecentos e setenta e quatro reais e sessenta e dois centavos)\u00a0para unidades\u00a0Assistenciais, conforme requisi\u00e7\u00e3o de despesa n\u00ba 3\/2026\/SES\/GAAL. Data da assinatura: 26\/02\/2026. Signat\u00e1rio: Ras\u00edvel dos Reis Santos J\u00fanior \u2013 Secret\u00e1rio de Estado da Sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EXTRATO DO 8\u00ba APOSTILAMENTO AO CONTRATO N\u00ba 380\/2019-SES\/GO. Processo n\u00ba: \u00a0201900010008297. Contratada: \u00a0EQUATORIAL GOI\u00c1S DISTRIBUIDORA DE ENERGIA S.A. Objeto: Retifica\u00e7\u00e3o, em decorr\u00eancia de erro material, a\u00a0\u00a0CL\u00c1USULA PRIMEIRA\u00a0do 7\u00ba Apostilamento ao Contrato n\u00ba\u00a0380\/2019-SES\/GO\u00a0CUSD\/CCER. Onde se l\u00ea:01. CL\u00c1USULA PRIMEIRA \u2013 DA DOCUMENTA\u00c7\u00c3O OR\u00c7AMENT\u00c1RIA PARA O EXERC\u00cdCIO FINANCEIRO DE 2025:01.1 \u2013 A despesa para o exerc\u00edcio financeiro referente [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[499],"tags":[],"class_list":["post-714073","post","type-post","status-publish","format-standard","hentry","category-contratos-e-termos-aditivos-2026"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ricardocruz","author_link":"https:\/\/goias.gov.br\/saude\/author\/ricardocruz\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/contratos-e-termos-aditivos-2026\/\" rel=\"category tag\">Contratos e Termos Aditivos 2026<\/a>","rttpg_excerpt":"EXTRATO DO 8\u00ba APOSTILAMENTO AO CONTRATO N\u00ba 380\/2019-SES\/GO. Processo n\u00ba: \u00a0201900010008297. Contratada: \u00a0EQUATORIAL GOI\u00c1S DISTRIBUIDORA DE ENERGIA S.A. Objeto: Retifica\u00e7\u00e3o, em decorr\u00eancia de erro material, a\u00a0\u00a0CL\u00c1USULA PRIMEIRA\u00a0do 7\u00ba Apostilamento ao Contrato n\u00ba\u00a0380\/2019-SES\/GO\u00a0CUSD\/CCER. Onde se l\u00ea:01. CL\u00c1USULA PRIMEIRA \u2013 DA DOCUMENTA\u00c7\u00c3O OR\u00c7AMENT\u00c1RIA PARA O EXERC\u00cdCIO FINANCEIRO DE 2025:01.1 \u2013 A despesa para o exerc\u00edcio financeiro referente&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/714073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=714073"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/714073\/revisions"}],"predecessor-version":[{"id":714087,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/714073\/revisions\/714087"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=714073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=714073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=714073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}