

{"id":708581,"date":"2026-02-20T12:01:45","date_gmt":"2026-02-20T15:01:45","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=708581"},"modified":"2026-02-20T12:01:45","modified_gmt":"2026-02-20T15:01:45","slug":"extrato-do-termo-de-doacao-no-159-2026-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-do-termo-de-doacao-no-159-2026-ses-go\/","title":{"rendered":"Extrato do Termo de Doa\u00e7\u00e3o n\u00ba 159\/2026 \u2013 SES\/GO"},"content":{"rendered":"\n<p><strong>Processo n\u00ba:<\/strong>\u00a0202500010042947.\u00a0<strong>Doador<\/strong>:<strong>\u00a0<\/strong>Estado de Goi\u00e1s\/Secretaria de Estado da Sa\u00fade.\u00a0<strong>Donat\u00e1ria:<\/strong>\u00a0Munic\u00edpio de Formosa-GO.\u00a0<strong>Objeto:\u00a0<\/strong>Doa\u00e7\u00e3o<strong>\u00a0<\/strong>de Bens M\u00f3veis relacionados no evento SEI (75660418), que se destinar\u00e1 para uso exclusivo da Secretaria Municipal de Sa\u00fade do Munic\u00edpio de Formosa-GO.\u00a0<strong>Valor<\/strong>: R$ 126.726,99\u00a0<strong>Data de Assinatura:<\/strong>\u00a019\/02\/2026.\u00a0<strong>Signat\u00e1rios:<\/strong>\u00a0Ras\u00edvel\u00a0dos Reis Santos J\u00fanior &#8211; Secret\u00e1rio de Estado da Sa\u00fade; Simone Dias Ribeiro de Melo &#8211; Munic\u00edpio de Formosa-GO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Processo n\u00ba:\u00a0202500010042947.\u00a0Doador:\u00a0Estado de Goi\u00e1s\/Secretaria de Estado da Sa\u00fade.\u00a0Donat\u00e1ria:\u00a0Munic\u00edpio de Formosa-GO.\u00a0Objeto:\u00a0Doa\u00e7\u00e3o\u00a0de Bens M\u00f3veis relacionados no evento SEI (75660418), que se destinar\u00e1 para uso exclusivo da Secretaria Municipal de Sa\u00fade do Munic\u00edpio de Formosa-GO.\u00a0Valor: R$ 126.726,99\u00a0Data de Assinatura:\u00a019\/02\/2026.\u00a0Signat\u00e1rios:\u00a0Ras\u00edvel\u00a0dos Reis Santos J\u00fanior &#8211; Secret\u00e1rio de Estado da Sa\u00fade; Simone Dias Ribeiro de Melo &#8211; Munic\u00edpio de Formosa-GO.<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[504],"tags":[],"class_list":["post-708581","post","type-post","status-publish","format-standard","hentry","category-termo-de-cessao-de-uso-2026"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/termo-de-cessao-de-uso-2026\/\" rel=\"category tag\">Termo de Cess\u00e3o de Uso 2026<\/a>","rttpg_excerpt":"Processo n\u00ba:\u00a0202500010042947.\u00a0Doador:\u00a0Estado de Goi\u00e1s\/Secretaria de Estado da Sa\u00fade.\u00a0Donat\u00e1ria:\u00a0Munic\u00edpio de Formosa-GO.\u00a0Objeto:\u00a0Doa\u00e7\u00e3o\u00a0de Bens M\u00f3veis relacionados no evento SEI (75660418), que se destinar\u00e1 para uso exclusivo da Secretaria Municipal de Sa\u00fade do Munic\u00edpio de Formosa-GO.\u00a0Valor: R$ 126.726,99\u00a0Data de Assinatura:\u00a019\/02\/2026.\u00a0Signat\u00e1rios:\u00a0Ras\u00edvel\u00a0dos Reis Santos J\u00fanior &#8211; Secret\u00e1rio de Estado da Sa\u00fade; Simone Dias Ribeiro de Melo &#8211; Munic\u00edpio de Formosa-GO.","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/708581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=708581"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/708581\/revisions"}],"predecessor-version":[{"id":708591,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/708581\/revisions\/708591"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=708581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=708581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=708581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}