

{"id":598026,"date":"2025-11-07T08:14:18","date_gmt":"2025-11-07T11:14:18","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=598026"},"modified":"2025-11-07T08:14:18","modified_gmt":"2025-11-07T11:14:18","slug":"extrato-da-portaria-no-3919-2025-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-da-portaria-no-3919-2025-ses-go\/","title":{"rendered":"Extrato da Portaria n\u00ba 3919\/2025 \u2013 SES\/GO"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">EXTRATO DA PORTARIA N\u00ba 3919\/2025\/SES\/GO, PROCESSO 202400010085155<\/h5>\n\n\n\n<p>O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de recursos financeiros pelas Organiza\u00e7\u00f5es Sociais de Sa\u00fade e\/ou Organiza\u00e7\u00f5es da Sociedade Civil a t\u00edtulo de investimento.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Considerando o Of\u00edcio de Solicita\u00e7\u00e3o de Recursos n\u00ba 201\/2025 &#8211; IMED (80212358), o Despacho n\u00ba 182\/2025 &#8211; GESAD (80269582), a Requisi\u00e7\u00e3o de Despesa n\u00ba 16\/2025 (81083505), o Despacho n\u00ba 48\/2025 &#8211; GERTEL (81083505) e, Considerando ainda o que consta no Processo n\u00ba 202400010085155, resolve:<\/h5>\n\n\n\n<p>Art. 1\u00ba. APROVAR o repasse de recursos, do Fundo Estadual de Sa\u00fade\/FES para \u00e0 Funda\u00e7\u00e3o Universit\u00e1ria Evang\u00e9lica &#8211; FUNEV, Organiza\u00e7\u00e3o Social de Sa\u00fade respons\u00e1vel pela Policl\u00ednica Estadual da Regi\u00e3o do Entorno &#8211; Formosa, a t\u00edtulo de investimento para aquisi\u00e7\u00e3o de equipamentos, conforme se observa no anexo \u00fanico.<\/p>\n\n\n\n<p>Art. 2\u00ba. DETERMINAR a transfer\u00eancia de recursos, na modalidade de transfer\u00eancias para organiza\u00e7\u00f5es sem fins lucrativos, no valor correspondente ao da Requisi\u00e7\u00e3o de Despesas no total de R$ 205.440,00 (duzentos e cinco mil quatrocentos e quarenta reais).<\/p>\n\n\n\n<p>Par\u00e1grafo \u00fanico. Em caso de irregularidades na presta\u00e7\u00e3o de contas, o processo ser\u00e1 encaminhado \u00e0 Superintend\u00eancia de Monitoramento dos Conv\u00eanios e Contratos de Gest\u00e3o &#8211; SUPECC para acompanhamento e monitoramento (art. 48 da Portaria n\u00ba 3924\/2024 &#8211; SES\/GO (68882873)).<\/p>\n\n\n\n<p>Art. 3\u00ba A vig\u00eancia do presente instrumento ser\u00e1 de 12 (doze) meses.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">RAS\u00cdVEL DOS REIS SANTOS J\u00daNIOR<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\"><\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">ANEXO \u00daNICO<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\"><\/h5>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Detalhamento<\/strong><\/td><td><strong>Qtde<\/strong><\/td><td><strong>Prazo para sua Realiza\u00e7\u00e3o<\/strong><\/td><td><strong>Estimativa de Custo Unit\u00e1rio<\/strong><\/td><td><strong>Estimativa de Custo Total<\/strong><\/td><\/tr><tr><td>Repasse de recursos ao Instituto de Medicina, Estudos e Desenvolvimento &#8211; IMED, a t\u00edtulo de investimento, para <strong>aquisi\u00e7\u00e3o de Servi\u00e7o de Consultoria Financeiro\/Cont\u00e1bil<\/strong>, destinado ao Policl\u00ednica Estadual da Regi\u00e3o do Entorno &#8211; Formosa.<\/td><td>400h<\/td><td>Imediato<\/td><td><strong>R$ 240,00<\/strong><\/td><td><strong>R$ 96.000,00<\/strong><\/td><\/tr><tr><td>Repasse de recursos ao Instituto de Medicina, Estudos e Desenvolvimento &#8211; IMED, a t\u00edtulo de investimento, para <strong>aquisi\u00e7\u00e3o de Servi\u00e7o de Consultoria Financeiro\/Cont\u00e1bil<\/strong>, destinado ao Policl\u00ednica Estadual da Regi\u00e3o do Entorno &#8211; Formosa.<\/td><td>456h<\/td><td>Imediato<\/td><td><strong>R$ 240,00<\/strong><\/td><td><strong>R$ 109.440,00<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>D<\/strong><strong>ata da assinatura:<\/strong> 04\/11\/2025. Signat\u00e1rio: Ras\u00edvel dos Reis Santos J\u00fanior &#8211; Secret\u00e1rio de Estado da Sa\u00fade.<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>EXTRATO DA PORTARIA N\u00ba 3919\/2025\/SES\/GO, PROCESSO 202400010085155 O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[423],"tags":[],"class_list":["post-598026","post","type-post","status-publish","format-standard","hentry","category-extrato-de-portarias-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ricardocruz","author_link":"https:\/\/goias.gov.br\/saude\/author\/ricardocruz\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/extrato-de-portarias-2025\/\" rel=\"category tag\">Extrato de Portarias 2025<\/a>","rttpg_excerpt":"EXTRATO DA PORTARIA N\u00ba 3919\/2025\/SES\/GO, PROCESSO 202400010085155 O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/598026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=598026"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/598026\/revisions"}],"predecessor-version":[{"id":598033,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/598026\/revisions\/598033"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=598026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=598026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=598026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}