

{"id":478031,"date":"2025-08-26T12:05:30","date_gmt":"2025-08-26T15:05:30","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=478031"},"modified":"2025-08-26T12:47:06","modified_gmt":"2025-08-26T15:47:06","slug":"ses-go-conclui-serie-de-oficinas-para-a-padronizacao-dos-documentos-eletronicos","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/ses-go-conclui-serie-de-oficinas-para-a-padronizacao-dos-documentos-eletronicos\/","title":{"rendered":"SES-GO conclui s\u00e9rie de oficinas para a padroniza\u00e7\u00e3o dos documentos eletr\u00f4nicos"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>Equipes definiram pela estrutura\u00e7\u00e3o de uma comiss\u00e3o respons\u00e1vel por realizar a padroniza\u00e7\u00e3o. Iniciativa vai proporcionar melhoria na assist\u00eancia ao paciente<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos-1024x684.jpeg\" alt=\"\" class=\"wp-image-478045\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos-1024x684.jpeg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos-300x200.jpeg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos-768x513.jpeg 768w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Superintendente Luiselena Esmeraldo acentua que a s\u00e9rie de oficinas definiu pela forma\u00e7\u00e3o de uma comiss\u00e3o respons\u00e1vel por padronizar os documentos<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>A Secretaria de Estado da Sa\u00fade de Goi\u00e1s (SES-GO) encerrou, nesta ter\u00e7a-feira (26\/08), a s\u00e9rie de oficinas do Projeto de Padroniza\u00e7\u00e3o de Documentos Eletr\u00f4nicos no Sistema de Gest\u00e3o Hospitalar. O quarto e \u00faltimo encontro, realizado no audit\u00f3rio da Superintend\u00eancia da Escola de Sa\u00fade de Goi\u00e1s, contou com a participa\u00e7\u00e3o de profissionais das \u00e1reas de Servi\u00e7o Social, Educa\u00e7\u00e3o F\u00edsica, Musicoterapia, Arteterapia, Biomedicina, Terapia Ocupacional, Enfermagem e Hemodi\u00e1lise.<\/p>\n\n\n\n<p>O Projeto de Padroniza\u00e7\u00e3o de Documentos Eletr\u00f4nicos no Sistema de Gest\u00e3o Hospitalar \u00e9 coordenado pela Ger\u00eancia de Sa\u00fade Digital da Superintend\u00eancia de Tecnologia, Informa\u00e7\u00e3o e Sa\u00fade Digital (Sutis) da SES-GO. A ampla a\u00e7\u00e3o visa ajustar o Prontu\u00e1rio Eletr\u00f4nico do Paciente (PEP) \u00e0s necessidades reais dos profissionais de sa\u00fade.<\/p>\n\n\n\n<p>A titular da Sutis, Luiselena Luna Esmeraldo, enfatiza que o ciclo de oficinas teve a participa\u00e7\u00e3o maci\u00e7a de representantes de diferentes setores de todas as unidades da rede p\u00fablica estadual. As equipes, conforme disse, definiram pela forma\u00e7\u00e3o de uma comiss\u00e3o para realizar a avalia\u00e7\u00e3o, consolida\u00e7\u00e3o e padroniza\u00e7\u00e3o dos documentos.<\/p>\n\n\n\n<p>O levantamento feito pela SES-GO constatou que existem cerca de 800 documentos inseridos no PEP, muitos deles duplicados e outros em desuso. A coordenadora de Tecnologia em Aten\u00e7\u00e3o Especializada, Tatiana Feitosa Ara\u00fajo, enfatiza que a padroniza\u00e7\u00e3o dos documentos eletr\u00f4nicos vai impactar na melhoria, amplia\u00e7\u00e3o e humaniza\u00e7\u00e3o do atendimento ao paciente. \u201cO profissional da assist\u00eancia vai passar menos tempo no preenchimento de informa\u00e7\u00f5es no computador, o que d\u00e1 possibilidade de dar mais aten\u00e7\u00e3o ao usu\u00e1rio do SUS\u201d, sublinha.<\/p>\n\n\n\n<p>Maria Jos\u00e9 Silva (texto) e Marco Monteiro (foto) \/ Comunica\u00e7\u00e3o Setorial da SES-GO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Equipes definiram pela estrutura\u00e7\u00e3o de uma comiss\u00e3o respons\u00e1vel por realizar a padroniza\u00e7\u00e3o. Iniciativa vai proporcionar melhoria na assist\u00eancia ao paciente<\/p>\n","protected":false},"author":164,"featured_media":478045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[335],"class_list":["post-478031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-saude-digital"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos.jpeg",1280,855,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos.jpeg",1280,855,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos.jpeg",1280,855,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos-150x150.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos-300x200.jpeg",300,200,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos-1024x684.jpeg",1024,684,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos.jpeg",1280,855,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/08\/2608-luiselena-padronizacao-documentos.jpeg",1280,855,false]},"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Equipes definiram pela estrutura\u00e7\u00e3o de uma comiss\u00e3o respons\u00e1vel por realizar a padroniza\u00e7\u00e3o. Iniciativa vai proporcionar melhoria na assist\u00eancia ao paciente","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/478031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=478031"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/478031\/revisions"}],"predecessor-version":[{"id":478126,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/478031\/revisions\/478126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/478045"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=478031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=478031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=478031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}