

{"id":46381,"date":"2024-04-19T07:46:53","date_gmt":"2024-04-19T10:46:53","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=46381"},"modified":"2024-04-19T07:46:53","modified_gmt":"2024-04-19T10:46:53","slug":"termo-de-julgamento-e-homologacao-no-103630","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/termo-de-julgamento-e-homologacao-no-103630\/","title":{"rendered":"Termo de Julgamento e Homologa\u00e7\u00e3o n\u00ba 103630"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>TERMO DE HOMOLOGA\u00c7\u00c3O<\/strong><\/h4>\n\n\n\n<p><a><\/a> <strong>N\u00famero do Processo SISLOG: 103630<\/strong><\/p>\n\n\n\n<p><a><\/a> N\u00famero do Processo SEI: 202400005000381<\/p>\n\n\n\n<p><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a> Pelo presente instrumento, considerando os procedimentos relativos \u00e0 contrata\u00e7\u00e3o de&nbsp;Cess\u00e3o de uso de sistema informatizado PROCEMPA, para apoiar, suportar e gerir a operacionaliza\u00e7\u00e3o de a\u00e7\u00f5es de regula\u00e7\u00e3o do acesso ao Sistema \u00danico de Sa\u00fade (SUS), no que diz respeito ao atendimento de urg\u00eancia, ambulatorial e interna\u00e7\u00f5es hospitalares, a serem executadas pela Superintend\u00eancia de Regula\u00e7\u00e3o, Controle e Avalia\u00e7\u00e3o, contendo licen\u00e7a de uso e manuten\u00e7\u00e3o, atualiza\u00e7\u00f5es de vers\u00e3o, consultoria em processos de regula\u00e7\u00e3o utilizados nos sistemas, configura\u00e7\u00e3o e parametriza\u00e7\u00e3o dos sistemas, treinamento de multiplicadores, Opera\u00e7\u00e3o assistida durante 2 semanas para cada modulo implantado e suporte n\u00edvel 03. Entre as premissas, caracter\u00edsticas e funcionalidades do Sistema do Complexo Regulador, destaca-se: Sistema Web, com alta disponibilidade e interface de f\u00e1cil navega\u00e7\u00e3o; Acesso seguro, rastre\u00e1vel e audit\u00e1vel; Identifica\u00e7\u00e3o un\u00edvoca dos pacientes atrav\u00e9s de Webservice do Cart\u00e3o SUS integrado diretamente com o sistema DATASUS em tempo real; Campos estruturados de preenchimento obrigat\u00f3rio, com as informa\u00e7\u00f5es necess\u00e1rias para a an\u00e1lise da necessidade assistencial e da prioridade do caso (protocolos); An\u00e1lise das refer\u00eancias para a necessidade assistencial do paciente de acordo com as pactua\u00e7\u00f5es intergestores; Servi\u00e7os de integra\u00e7\u00e3o para promover a informa\u00e7\u00e3o atualizada da oferta de servi\u00e7os e capacidade operacional instalada em tempo real e minimizar o impacto na opera\u00e7\u00e3o assistencial dos servi\u00e7os solicitantes e executantes. Filas de espera de solicita\u00e7\u00f5es ordenadas por prioridade (gravidade + situa\u00e7\u00f5es tempo sens\u00edveis com maior import\u00e2ncia do tempo resposta para o melhor desfecho, situa\u00e7\u00f5es de risco e vulnerabilidades,&#8230;), com informa\u00e7\u00f5es atualizadas por interoperabilidade e compartilhadas on-line; Utiliza\u00e7\u00e3o das fontes oficiais de informa\u00e7\u00e3o do Sistema \u00danico de Sa\u00fade como subs\u00eddio da oferta e habilita\u00e7\u00e3o de servi\u00e7os e das refer\u00eancias regionalizadas: o webservice do Cart\u00e3o SUS &#8211; CADSUS; o Cadastro Nacional de Estabelecimentos de Sa\u00fade ? CNES, as pactua\u00e7\u00f5es CIB (Comiss\u00e3o Intergestora Bipartite) e os documentos descritivos dos contratos dos prestadores; M\u00f3dulo sistematizado para os processos de autoriza\u00e7\u00e3o, controle e faturamento dos servi\u00e7os prestados integrado \u00e0s a\u00e7\u00f5es de regula\u00e7\u00e3o; Utiliza\u00e7\u00e3o de bancos de dados dos sistemas e de ferramentas de Business Intelligence (BI) para gerar relat\u00f3rios de indicadores da demanda e oferta de servi\u00e7os, da efici\u00eancia da regula\u00e7\u00e3o e do tempo de resposta para o acesso assistencial, da produ\u00e7\u00e3o e performance dos prestadores de servi\u00e7os, entre outros., mediante&nbsp;Dispensa, referente ao processo de contrata\u00e7\u00e3o SISLOG n\u00ba&nbsp;103630\/2024&nbsp;e processo SEI n\u00ba&nbsp;202400005000381, realizada atendendo aos preceitos da&nbsp;Lei Federal n\u00ba 14.133 de abril de 2021&nbsp;e da Instru\u00e7\u00e3o Normativa n\u00ba 5\/2023-SEAD, decido AUTORIZAR e HOMOLOGAR a presente contrata\u00e7\u00e3o, fundamentada na&nbsp;Lei 14.133\/2021, Art. 75, IX, conforme resultado a seguir:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td colspan=\"2\"><strong>Descri\u00e7\u00e3o do item 001<\/strong><br>C\u00f3digo 670 &#8211; Licen\u00e7a para Uso de Software, conforme Termo de Refer\u00eancia.<\/td><\/tr><tr><td colspan=\"2\"><strong>Informa\u00e7\u00f5es Adicionais<\/strong><br>Cess\u00e3o de uso de sistema informatizado PROCEMPA, para apoiar, suportar e gerir a operacionaliza\u00e7\u00e3o de a\u00e7\u00f5es de regula\u00e7\u00e3o do acesso ao Sistema \u00danico de Sa\u00fade (SUS), no que diz respeito ao atendimento de urg\u00eancia, ambulatorial e interna\u00e7\u00f5es hospitalares, a serem executadas pela Superintend\u00eancia de Regula\u00e7\u00e3o, Controle e Avalia\u00e7\u00e3o, contendo licen\u00e7a de uso e manuten\u00e7\u00e3o, atualiza\u00e7\u00f5es de vers\u00e3o, consultoria em processos de regula\u00e7\u00e3o utilizados nos sistemas, configura\u00e7\u00e3o e parametriza\u00e7\u00e3o dos sistemas, treinamento de multiplicadores, Opera\u00e7\u00e3o assistida durante 2 semanas para cada modulo implantado e suporte n\u00edvel 03. Licen\u00e7a e Manuten\u00e7\u00e3o GERCON<\/td><\/tr><tr><td>Per\u00edodo (Meses)<\/td><td>60<\/td><\/tr><tr><td>Quantidade<\/td><td>1<\/td><\/tr><tr><td>Unidade<\/td><td>unidade<\/td><\/tr><tr><td>CPF\/CNPJ<\/td><td>89.398.473\/0001-00<\/td><\/tr><tr><td>Fornecedor<\/td><td>COMPANHIA DE PROCESSAMENTO DE DADOS DO MUNICIPIO DE PORTO ALEGRE &#8211; PROCEMPA<\/td><\/tr><tr><td>Total<\/td><td>R$ 22.668.449,400<\/td><\/tr><tr><td colspan=\"2\"><strong>Descri\u00e7\u00e3o do item 002<\/strong><br>C\u00f3digo 670 &#8211; Licen\u00e7a para Uso de Software, conforme Termo de Refer\u00eancia.<\/td><\/tr><tr><td colspan=\"2\"><strong>Informa\u00e7\u00f5es Adicionais<\/strong><br>Cess\u00e3o de uso de sistema informatizado PROCEMPA, para apoiar, suportar e gerir a operacionaliza\u00e7\u00e3o de a\u00e7\u00f5es de regula\u00e7\u00e3o do acesso ao Sistema \u00danico de Sa\u00fade (SUS), no que diz respeito ao atendimento de urg\u00eancia, ambulatorial e interna\u00e7\u00f5es hospitalares, a serem executadas pela Superintend\u00eancia de Regula\u00e7\u00e3o, Controle e Avalia\u00e7\u00e3o, contendo licen\u00e7a de uso e manuten\u00e7\u00e3o, atualiza\u00e7\u00f5es de vers\u00e3o, consultoria em processos de regula\u00e7\u00e3o utilizados nos sistemas, configura\u00e7\u00e3o e parametriza\u00e7\u00e3o dos sistemas, treinamento de multiplicadores, Opera\u00e7\u00e3o assistida durante 2 semanas para cada modulo implantado e suporte n\u00edvel 03. Licen\u00e7a e Manuten\u00e7\u00e3o GERINT<\/td><\/tr><tr><td>Per\u00edodo (Meses)<\/td><td>58<\/td><\/tr><tr><td>Quantidade<\/td><td>1<\/td><\/tr><tr><td>Unidade<\/td><td>unidade<\/td><\/tr><tr><td>CPF\/CNPJ<\/td><td>89.398.473\/0001-00<\/td><\/tr><tr><td>Fornecedor<\/td><td>COMPANHIA DE PROCESSAMENTO DE DADOS DO MUNICIPIO DE PORTO ALEGRE &#8211; PROCEMPA<\/td><\/tr><tr><td>Total<\/td><td>R$ 10.956.416,920<\/td><\/tr><tr><td colspan=\"2\"><strong>Descri\u00e7\u00e3o do item 003<\/strong><br>C\u00f3digo 670 &#8211; Licen\u00e7a para Uso de Software, conforme Termo de Refer\u00eancia.<\/td><\/tr><tr><td colspan=\"2\"><strong>Informa\u00e7\u00f5es Adicionais<\/strong><br>Cess\u00e3o de uso de sistema informatizado PROCEMPA, para apoiar, suportar e gerir a operacionaliza\u00e7\u00e3o de a\u00e7\u00f5es de regula\u00e7\u00e3o do acesso ao Sistema \u00danico de Sa\u00fade (SUS), no que diz respeito ao atendimento de urg\u00eancia, ambulatorial e interna\u00e7\u00f5es hospitalares, a serem executadas pela Superintend\u00eancia de Regula\u00e7\u00e3o, Controle e Avalia\u00e7\u00e3o, contendo licen\u00e7a de uso e manuten\u00e7\u00e3o, atualiza\u00e7\u00f5es de vers\u00e3o, consultoria em processos de regula\u00e7\u00e3o utilizados nos sistemas, configura\u00e7\u00e3o e parametriza\u00e7\u00e3o dos sistemas, treinamento de multiplicadores, Opera\u00e7\u00e3o assistida durante 2 semanas para cada modulo implantado e suporte n\u00edvel 03. Licen\u00e7a e Manuten\u00e7\u00e3o GERPAC<\/td><\/tr><tr><td>Per\u00edodo (Meses)<\/td><td>56<\/td><\/tr><tr><td>Quantidade<\/td><td>1<\/td><\/tr><tr><td>Unidade<\/td><td>unidade<\/td><\/tr><tr><td>CPF\/CNPJ<\/td><td>89.398.473\/0001-00<\/td><\/tr><tr><td>Fornecedor<\/td><td>COMPANHIA DE PROCESSAMENTO DE DADOS DO MUNICIPIO DE PORTO ALEGRE &#8211; PROCEMPA<\/td><\/tr><tr><td>Total<\/td><td>R$ 3.526.202,960<\/td><\/tr><tr><td colspan=\"2\"><strong>Descri\u00e7\u00e3o do item 004<\/strong><br>C\u00f3digo 670 &#8211; Licen\u00e7a para Uso de Software, conforme Termo de Refer\u00eancia.<\/td><\/tr><tr><td colspan=\"2\"><strong>Informa\u00e7\u00f5es Adicionais<\/strong><br>Cess\u00e3o de uso de sistema informatizado PROCEMPA, para apoiar, suportar e gerir a operacionaliza\u00e7\u00e3o de a\u00e7\u00f5es de regula\u00e7\u00e3o do acesso ao Sistema \u00danico de Sa\u00fade (SUS), no que diz respeito ao atendimento de urg\u00eancia, ambulatorial e interna\u00e7\u00f5es hospitalares, a serem executadas pela Superintend\u00eancia de Regula\u00e7\u00e3o, Controle e Avalia\u00e7\u00e3o, contendo licen\u00e7a de uso e manuten\u00e7\u00e3o, atualiza\u00e7\u00f5es de vers\u00e3o, consultoria em processos de regula\u00e7\u00e3o utilizados nos sistemas, configura\u00e7\u00e3o e parametriza\u00e7\u00e3o dos sistemas, treinamento de multiplicadores, Opera\u00e7\u00e3o assistida durante 2 semanas para cada modulo implantado e suporte n\u00edvel 03. Horas por desenvolvimento &#8211; por demanda<\/td><\/tr><tr><td>Per\u00edodo (Meses)<\/td><td>60<\/td><\/tr><tr><td>Quantidade<\/td><td>352<\/td><\/tr><tr><td>Unidade<\/td><td>unidade<\/td><\/tr><tr><td>CPF\/CNPJ<\/td><td>89.398.473\/0001-00<\/td><\/tr><tr><td>Fornecedor<\/td><td>COMPANHIA DE PROCESSAMENTO DE DADOS DO MUNICIPIO DE PORTO ALEGRE &#8211; PROCEMPA<\/td><\/tr><tr><td>Total<\/td><td>R$ 4.371.840,000<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><a><\/a> Assim, determino a divulga\u00e7\u00e3o da presente contrata\u00e7\u00e3o no sistema eletr\u00f4nico de contrata\u00e7\u00f5es estaduais &#8211; SISLOG, nos termos do art. 9\u00ba da Instru\u00e7\u00e3o Normativa n\u00ba 5\/2023-SEAD, com a posterior publica\u00e7\u00e3o do contrato decorrente, que ser\u00e1 publicado nos termos do artigo 94 da&nbsp;Lei Federal n\u00ba 14.133 de abril de 2021&nbsp;e art. 11 da Instru\u00e7\u00e3o Normativa n\u00ba 5\/2023-SEAD.<\/p>\n\n\n\n<p>Goi\u00e2nia -18 de Abril de 2024<\/p>\n\n\n\n<p><strong>THALLES PAULINO DE \u00c1VILA<\/strong><\/p>\n\n\n\n<p>Superintendente de Gest\u00e3o Integrada<\/p>\n\n\n\n<p>Secretaria de Estado da Sa\u00fade<br>Delega\u00e7\u00e3o de Compet\u00eancia<\/p>\n\n\n\n<p><a href=\"https:\/\/diariooficial.abc.go.gov.br\/portal\/visualizacoes\/pdf\/6074\/#\/p:18\/e:6074\">Portaria n\u00b0 645\/2024-SES<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TERMO DE HOMOLOGA\u00c7\u00c3O N\u00famero do Processo SISLOG: 103630 N\u00famero do Processo SEI: 202400005000381 Pelo presente instrumento, considerando os procedimentos relativos \u00e0 contrata\u00e7\u00e3o de&nbsp;Cess\u00e3o de uso de sistema informatizado PROCEMPA, para apoiar, suportar e gerir a operacionaliza\u00e7\u00e3o de a\u00e7\u00f5es de regula\u00e7\u00e3o do acesso ao Sistema \u00danico de Sa\u00fade (SUS), no que diz respeito ao atendimento de [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[269],"tags":[],"class_list":["post-46381","post","type-post","status-publish","format-standard","hentry","category-dispensa-e-inexigibilidade-2024"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ricardocruz","author_link":"https:\/\/goias.gov.br\/saude\/author\/ricardocruz\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/dispensa-e-inexigibilidade-2024\/\" rel=\"category tag\">Dispensa e Inexigibilidade 2024<\/a>","rttpg_excerpt":"TERMO DE HOMOLOGA\u00c7\u00c3O N\u00famero do Processo SISLOG: 103630 N\u00famero do Processo SEI: 202400005000381 Pelo presente instrumento, considerando os procedimentos relativos \u00e0 contrata\u00e7\u00e3o de&nbsp;Cess\u00e3o de uso de sistema informatizado PROCEMPA, para apoiar, suportar e gerir a operacionaliza\u00e7\u00e3o de a\u00e7\u00f5es de regula\u00e7\u00e3o do acesso ao Sistema \u00danico de Sa\u00fade (SUS), no que diz respeito ao atendimento de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/46381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=46381"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/46381\/revisions"}],"predecessor-version":[{"id":46382,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/46381\/revisions\/46382"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=46381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=46381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=46381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}