

{"id":4512,"date":"2016-02-03T15:06:17","date_gmt":"2016-02-03T17:06:17","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/amamentacao-evita-cancer-e-garante-a-saude-do-bebe\/"},"modified":"2016-02-03T15:06:17","modified_gmt":"2016-02-03T17:06:17","slug":"amamentacao-evita-cancer-e-garante-a-saude-do-bebe","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/amamentacao-evita-cancer-e-garante-a-saude-do-bebe\/","title":{"rendered":"Amamenta\u00e7\u00e3o evita c\u00e2ncer e garante a sa\u00fade do beb\u00ea"},"content":{"rendered":"<p><h6><\/h6>\n<\/p>\n<div class=\"tx cl\">\n<p>O aumento de campanhas governamentais ao longo dos anos tem refor\u00e7ado a import\u00e2ncia da amamenta\u00e7\u00e3o para as crian\u00e7as por diversos benef\u00edcios. No entanto, poucas pessoas conhecem as vantagens do ato para a sa\u00fade feminina. A preocupa\u00e7\u00e3o em incentivar e orientar mulheres para a relev\u00e2ncia do assunto extrapola o aspecto alimentar. Uma pesquisa divulgada pela revista brit\u00e2nica &#8220;The Lancet&#8221; em 28 de janeiro aponta que o aleitamento materno preveniria mais de 800 mil mortes infantis e at\u00e9 20 mil \u00f3bitos por c\u00e2ncer de mama a cada ano no mundo. Em n\u00edvel global, o c\u00e2ncer de mama \u00e9 o que mais mata mulheres, ficando atr\u00e1s apenas do c\u00e2ncer de pele tipo n\u00e3o melanoma, segundo informa\u00e7\u00f5es do Instituto Nacional do C\u00e2ncer (Inca).<\/p>\n<p>O coordenador de Ginecologia e Obstetr\u00edcia da Maternidade Nossa Senhora de Lourdes (MNSL), Wilson Arantes, refor\u00e7a a associa\u00e7\u00e3o entre amamenta\u00e7\u00e3o prolongada e preven\u00e7\u00e3o ao c\u00e2ncer de mama e c\u00e2ncer de ov\u00e1rio devido a produ\u00e7\u00e3o de horm\u00f4nios espec\u00edficos, incentivo \u00e0 funcionalidade da mama, reserva folicular (a popula\u00e7\u00e3o total de \u00f3vulos de uma mulher em um intervalo de tempo) e repouso do ov\u00e1rio. Para o m\u00e9dico, a lacta\u00e7\u00e3o deve ser incentivada como alimento por causa dos benef\u00edcios imunol\u00f3gicos e at\u00e9 emocionais na rela\u00e7\u00e3o entre m\u00e3e e filho.<\/p>\n<p>Apesar disso, ele ressalta a import\u00e2ncia do aleitamento independentemente do tempo de dura\u00e7\u00e3o. \u201cQuanto mais tempo a mulher se dedicar a esse ato, pelo menos at\u00e9 por volta dos dois anos de idade da crian\u00e7a, melhor. Esse fator associado a v\u00e1rias gesta\u00e7\u00f5es contribui para a preven\u00e7\u00e3o dessas doen\u00e7as\u201d, afirma. Com novas mudan\u00e7as no estilo de vida, ele espera que a prote\u00e7\u00e3o natural se estenda \u00e0s mulheres modernas que t\u00eam menos filhos e mant\u00eam lacta\u00e7\u00e3o exclusiva por tempo reduzido. Na pesquisa veiculada pela revista inglesa, houve constata\u00e7\u00e3o de que uma a cada cinco crian\u00e7as que vivem em pa\u00edses com rendas elevadas s\u00e3o amamentadas at\u00e9 os 12 meses, enquanto apenas uma em cada tr\u00eas de pa\u00edses com renda m\u00e9dia e baixa se alimentam de leite materno durante os primeiros seis meses de vida.<\/p>\n<p>De acordo com o coordenador de Pediatria da MNSL, Rodrigo Bas\u00edlio, o reflexo na sa\u00fade e no desenvolvimento dos pequenos \u00e9 positivo em toda a vida. \u201cA amamenta\u00e7\u00e3o aumenta a imunidade infantil por causa de anticorpos que evitam infec\u00e7\u00f5es virais e bacterianas, como diarreias e infec\u00e7\u00e3o de vias a\u00e9reas superiores (pneumonia, gripe, bronquiolite e outras)\u201d, diz. Al\u00e9m disso, ele explica que \u201co ato aumenta o v\u00ednculo entre ambos e tamb\u00e9m oferece nutrientes para o desenvolvimento neuropsicomotor por conter subst\u00e2ncias que atuam no c\u00e9rebro e na retina da crian\u00e7a\u201d. Na pr\u00e1tica, a falta de aten\u00e7\u00e3o ao aleitamento materno representa maior impacto financeiro com sistemas de sa\u00fade do segmento materno e pedi\u00e1trico e menor expectativa de vida.<\/p>\n<p>O mesmo estudo sinaliza que a amamenta\u00e7\u00e3o diminui o risco de morte s\u00fabita da crian\u00e7a em mais de um ter\u00e7o dos casos, enquanto nos pa\u00edses com rendas baixas seria poss\u00edvel evitar a metade dos epis\u00f3dios de diarreia e um ter\u00e7o das infec\u00e7\u00f5es respirat\u00f3rias. Como as vantagens para m\u00e3e e filho est\u00e3o relacionadas ao tempo de lacta\u00e7\u00e3o, quanto mais as mulheres alimentam a crian\u00e7a com leite materno, maior a prote\u00e7\u00e3o. Especialmente para as mam\u00e3es de primeira viagem, a orienta\u00e7\u00e3o sobre a melhor forma de executar \u00e9 fundamental.<\/p>\n<p>Na MNSL, por exemplo, elas contam com equipe de profissionais de sa\u00fade dispon\u00edvel para fornecer informa\u00e7\u00f5es e instru\u00e7\u00f5es. Com as recomenda\u00e7\u00f5es, a mulher se sente mais segura facilitando assim a adapta\u00e7\u00e3o \u00e0 nova rotina. Entre as sugest\u00f5es oferecidas est\u00e3o a ingest\u00e3o de l\u00edquidos, refei\u00e7\u00f5es balanceadas ao longo do dia e mamadas frequentes, que estimulam a produ\u00e7\u00e3o do leite materno considerado alimento mais completo para o beb\u00ea.<\/p>\n<p><strong>Interrup\u00e7\u00e3o<\/strong>\u00a0&#8211; A Organiza\u00e7\u00e3o Mundial da Sa\u00fade e o Minist\u00e9rio da Sa\u00fade recomendam a amamenta\u00e7\u00e3o exclusiva por seis meses. Ap\u00f3s esse per\u00edodo, o Minist\u00e9rio da Sa\u00fade recomenda a combina\u00e7\u00e3o com alimenta\u00e7\u00e3o complementar. Em rela\u00e7\u00e3o \u00e0 amamenta\u00e7\u00e3o exclusiva, a indica\u00e7\u00e3o \u00e9 suspens\u00e3o apenas em caso de rea\u00e7\u00e3o negativa do beb\u00ea por suspeita de sensibilidade ou alergia alimentar a alguma subst\u00e2ncia que a mulher tenha ingerido (leite de vaca, castanhas, frutos do mar e carne de porco costumam ser vil\u00f5es). No caso das mulheres que trabalham fora de casa, a sugest\u00e3o \u00e9 armazenar o leite para que o cuidador da crian\u00e7a a alimente durante a aus\u00eancia da m\u00e3e. O pediatra Rodrigo ressalta a necessidade de cuidados em rela\u00e7\u00e3o \u00e0 higiene e ao armazenamento em potes de vidro com tampa de pl\u00e1sticos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O aumento de campanhas governamentais ao longo dos anos tem refor\u00e7ado a import\u00e2ncia da amamenta\u00e7\u00e3o para as crian\u00e7as por diversos benef\u00edcios. No entanto, poucas pessoas conhecem as vantagens do ato para a sa\u00fade feminina. A preocupa\u00e7\u00e3o em incentivar e orientar mulheres para a relev\u00e2ncia do assunto extrapola o aspecto alimentar. Uma pesquisa divulgada pela revista [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4512","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"O aumento de campanhas governamentais ao longo dos anos tem refor\u00e7ado a import\u00e2ncia da amamenta\u00e7\u00e3o para as crian\u00e7as por diversos benef\u00edcios. No entanto, poucas pessoas conhecem as vantagens do ato para a sa\u00fade feminina. A preocupa\u00e7\u00e3o em incentivar e orientar mulheres para a relev\u00e2ncia do assunto extrapola o aspecto alimentar. Uma pesquisa divulgada pela revista&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/4512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=4512"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/4512\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=4512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=4512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=4512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}