{"id":449295,"date":"2025-07-29T16:15:00","date_gmt":"2025-07-29T19:15:00","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=449295"},"modified":"2025-07-29T16:15:02","modified_gmt":"2025-07-29T19:15:02","slug":"extrato-da-portaria-no-2206-2025-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-da-portaria-no-2206-2025-ses-go\/","title":{"rendered":"Extrato da Portaria n\u00ba 2206\/2025 \u2013 SES\/GO"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de recursos financeiros pelas Organiza\u00e7\u00f5es Sociais de Sa\u00fade e\/ou Organiza\u00e7\u00f5es da Sociedade Civil a t\u00edtulo de investimento.<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\"><a><\/a><a><\/a><a><\/a> Considerando o Of\u00edcio de Solicita\u00e7\u00e3o de Recursos n\u00ba 779\/2025 &#8211; FUNEV (72970118), Considerando o Despacho n\u00ba 318\/2025 &#8211; GEA (73334317), Considerando a Requisi\u00e7\u00e3o de Despesa n\u00ba 109\/2025 (73951940). Considerando ainda o que consta no Processo n\u00ba 202500010025935, resolve:<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">Art. 1\u00ba. APROVAR o repasse de recursos, do Fundo Estadual de Sa\u00fade\/FES para a Funda\u00e7\u00e3o Universit\u00e1ria Evang\u00e9lica &#8211; FUNEV, Organiza\u00e7\u00e3o Social de Sa\u00fade respons\u00e1vel pelo gerenciamento do Hospital Estadual de Piren\u00f3polis Ernestina Lopes Jaime\/HEELJ, a t\u00edtulo de investimento para aquisi\u00e7\u00e3o de <strong>18 (dezoito) mesas para refei\u00e7\u00e3o, <\/strong>conforme se observa no anexo \u00fanico.<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">Art. 2\u00ba. DETERMINAR a transfer\u00eancia de recursos, na modalidade de transfer\u00eancias para organiza\u00e7\u00f5es sem fins lucrativos, no valor correspondente ao da Requisi\u00e7\u00e3o de Despesas no total de R$ 13.644,00 (treze mil seiscentos e quarenta e quatro reais).<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">Art. 3\u00ba. A vig\u00eancia do presente instrumento ser\u00e1 de 12 (doze) meses.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">ANEXO \u00daNICO<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Detalhamento<\/strong><\/td><td><strong>Estimativa de Custo<\/strong><\/td><\/tr><tr><td>Repasse de recursos \u00e0 Funda\u00e7\u00e3o Universit\u00e1ria Evang\u00e9lica &#8211; FUNEV, a t\u00edtulo de investimento para aquisi\u00e7\u00e3o de <strong>18 (dezoito) mesas para refei\u00e7\u00e3o <\/strong>destinado ao Hospital Estadual de Piren\u00f3polis Ernestina Lopes Jaime\/HEELJ.<\/td><td><strong>R$ 13.644,00<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>D<\/strong><strong>ata da assinatura:<\/strong> 25\/07\/2025. Signat\u00e1rio: Ras\u00edvel dos Reis Santos J\u00fanior &#8211; Secret\u00e1rio de Estado da Sa\u00fade.<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de recursos financeiros pelas Organiza\u00e7\u00f5es Sociais de Sa\u00fade [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[423],"tags":[],"class_list":["post-449295","post","type-post","status-publish","format-standard","hentry","category-extrato-de-portarias-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/extrato-de-portarias-2025\/\" rel=\"category tag\">Extrato de Portarias 2025<\/a>","rttpg_excerpt":"O SECRET\u00c1RIO DE ESTADO DA SA\u00daDE, no uso de suas atribui\u00e7\u00f5es legais, considerando o disposto nos Art. 5\u00ba e 6\u00ba da Lei Estadual n\u00ba 17.797\/2012 e Art. 8\u00ba do Decreto Estadual n\u00ba 7.824\/2013 e Portaria n\u00ba 3.924\/2024 \u2013 GAB\/SES \u2013 GO, que trata sobre normas para solicita\u00e7\u00e3o de recursos financeiros pelas Organiza\u00e7\u00f5es Sociais de Sa\u00fade&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/449295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=449295"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/449295\/revisions"}],"predecessor-version":[{"id":449308,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/449295\/revisions\/449308"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=449295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=449295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=449295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}