

{"id":44201,"date":"2024-03-11T10:44:32","date_gmt":"2024-03-11T13:44:32","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=44201"},"modified":"2024-03-13T10:50:57","modified_gmt":"2024-03-13T13:50:57","slug":"saude-estadual-inicia-preparativos-para-a-oitava-edicao-do-ppsus","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/saude-estadual-inicia-preparativos-para-a-oitava-edicao-do-ppsus\/","title":{"rendered":"Sa\u00fade estadual inicia preparativos para a oitava edi\u00e7\u00e3o do PPSUS"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>Programa visa promover avan\u00e7o cient\u00edfico e tecnol\u00f3gico, adaptando-se \u00e0s particularidades de cada Estado brasileiro e contribuindo para a redu\u00e7\u00e3o das disparidades regionais<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"965\" height=\"532\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg\" alt=\"\" class=\"wp-image-44203\"\/><figcaption class=\"wp-element-caption\"><em>Participantes da reuni\u00e3o de alinhamento para oficina de prioridades de pesquisas do OPP<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>A Secretaria de Estado da Sa\u00fade de Goi\u00e1s (SES-GO) j\u00e1 come\u00e7ou a se preparar para a oitava edi\u00e7\u00e3o do Programa de Pesquisas para o Sistema \u00danico de Sa\u00fade (PPSUS). Iniciativa crucial de descentraliza\u00e7\u00e3o do fomento \u00e0 pesquisa em sa\u00fade nas unidades federativas, o programa visa promover o avan\u00e7o cient\u00edfico e tecnol\u00f3gico, adaptando-se \u00e0s particularidades de cada Estado brasileiro e contribuindo para a redu\u00e7\u00e3o das disparidades regionais.<\/p>\n\n\n\n<p>O pontap\u00e9 inicial foi dado no dia 7 de mar\u00e7o, quando a SES-GO, por meio da Ger\u00eancia de Pesquisa e Inova\u00e7\u00e3o da Superintend\u00eancia da Escola de Sa\u00fade de Goi\u00e1s (Gepi\/Sesg), participou da reuni\u00e3o de alinhamento para a oficina de prioridades de pesquisas do Observat\u00f3rio de Pol\u00edticas P\u00fablicas em Sa\u00fade. <\/p>\n\n\n\n<p>O evento contou ainda com representantes do Minist\u00e9rio da Sa\u00fade, Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico (CNPq), Secretarias Estaduais de Sa\u00fade e Funda\u00e7\u00f5es de Amparo\/Apoio (FAP) \u00e0 Pesquisa de todo o Pa\u00eds. Na ocasi\u00e3o, foi apresentada uma nova metodologia para levantamento de problemas de sa\u00fade, sele\u00e7\u00e3o de prioridades de pesquisa e propostas de linhas de pesquisa para orientar os eixos da chamada p\u00fablica.<\/p>\n\n\n\n<p>Neste ano, as etapas das oficinas do PPSUS v\u00e3o ocorrer virtualmente, e espera-se que sejam consolidadas ainda no primeiro semestre de 2024, incluindo a divulga\u00e7\u00e3o das chamadas p\u00fablicas. A expectativa da Gepi\/Sesg \u00e9 de que esta edi\u00e7\u00e3o impulsione n\u00e3o apenas a pesquisa em sa\u00fade, mas tamb\u00e9m a competitividade dos pesquisadores locais.<\/p>\n\n\n\n<p><strong>Parcerias federais e estaduais<\/strong><br>Coordenado pelo Minist\u00e9rio da Sa\u00fade, por meio do Departamento de Ci\u00eancia e Tecnologia da Secretaria de Ci\u00eancia, Tecnologia e Insumos Estrat\u00e9gicos (Decit\/SCTIE), o PPSUS conta com parcerias federais, incluindo o CNPq, e estaduais, envolvendo FAPs, Secretarias Estaduais de Sa\u00fade e de Ci\u00eancia e Tecnologia (SECT). A Gepi\/Sesg representa a SES-GO como ponto de apoio ao PPSUS em Goi\u00e1s.<\/p>\n\n\n\n<p>Uma das caracter\u00edsticas inovadoras do PPSUS \u00e9 seu modelo de gest\u00e3o descentralizado e participativo, que envolve gestores, profissionais de sa\u00fade, pesquisadores e representantes da sociedade civil. Esse programa visa colocar os principais problemas de sa\u00fade da popula\u00e7\u00e3o entre as prioridades dos pesquisadores brasileiros, usando a relev\u00e2ncia sociossanit\u00e1ria como um dos crit\u00e9rios para a defini\u00e7\u00e3o dos temas de pesquisa.<\/p>\n\n\n\n<p>A pesquisa em sa\u00fade representa 30% da produ\u00e7\u00e3o cient\u00edfica nacional. Entretanto, h\u00e1 uma concentra\u00e7\u00e3o consider\u00e1vel de doutores, mestres e institui\u00e7\u00f5es de pesquisa nas regi\u00f5es sudeste e sul do Pa\u00eds. Essa desigualdade se reflete tamb\u00e9m nos investimentos insuficientes em pesquisa, especialmente nas regi\u00f5es menos desenvolvidas. <\/p>\n\n\n\n<p>Diante desse contexto, os objetivos do PPSUS s\u00e3o claros: financiar pesquisas sobre temas priorit\u00e1rios para a sa\u00fade da popula\u00e7\u00e3o brasileira, fortalecer os sistemas locais de sa\u00fade, ci\u00eancia e tecnologia, reduzir as desigualdades regionais e promover a equidade.<\/p>\n\n\n\n<p>Gabriela Dutra\/Superintend\u00eancia da Escola de Sa\u00fade de Goi\u00e1s<br>Foto: Gepi\/Sesg<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programa visa promover avan\u00e7o cient\u00edfico e tecnol\u00f3gico, adaptando-se \u00e0s particularidades de cada Estado brasileiro e contribuindo para a redu\u00e7\u00e3o das disparidades regionais<\/p>\n","protected":false},"author":166,"featured_media":44203,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[163],"class_list":["post-44201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-escola-de-saude"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg",965,532,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg",965,532,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg",965,532,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg",150,83,false],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg",300,165,false],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg",965,532,false],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg",965,532,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2024\/03\/11.03-FOTO_PPSUS-1.jpeg",965,532,false]},"rttpg_author":{"display_name":"josegomes","author_link":"https:\/\/goias.gov.br\/saude\/author\/josegomes\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Programa visa promover avan\u00e7o cient\u00edfico e tecnol\u00f3gico, adaptando-se \u00e0s particularidades de cada Estado brasileiro e contribuindo para a redu\u00e7\u00e3o das disparidades regionais","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/44201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/166"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=44201"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/44201\/revisions"}],"predecessor-version":[{"id":44407,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/44201\/revisions\/44407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/44203"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=44201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=44201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=44201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}