{"id":439143,"date":"2025-07-15T08:35:25","date_gmt":"2025-07-15T11:35:25","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=439143"},"modified":"2025-07-15T08:35:26","modified_gmt":"2025-07-15T11:35:26","slug":"resultado-de-julgamento-e-homologacao-do-p-e-no-113-2025-110809","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/resultado-de-julgamento-e-homologacao-do-p-e-no-113-2025-110809\/","title":{"rendered":"Resultado de Julgamento e Homologa\u00e7\u00e3o do P.E. n\u00ba 113\/2025 \u2013 110809"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Preg\u00e3o Eletr\u00f4nico n.\u00b0 113\/2025 SES-GO<\/strong> <strong>SISLOG: 110809<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Secretaria de Estado da Sa\u00fade de Goi\u00e1s torna p\u00fablico o resultado do Preg\u00e3o Eletr\u00f4nico n\u00ba 113\/2025, P<\/strong><strong>rocesso SEI 202400005045342, <\/strong><strong>para contrata\u00e7\u00e3o de produtos nutricionais e\/ou produtos para sa\u00fade, que foram concedidos nas apresenta\u00e7\u00f5es e concentra\u00e7\u00f5es registradas na ANVISA prescritas nos receitu\u00e1rios m\u00e9dicos presentes nos autos das a\u00e7\u00f5es judiciais. Os itens 003, 004, 005, 006 e 022 foram adjudicados e homologados \u00e0 empresa: BN EXPRESS II COMERCIO E SERVICOS LTDA com o CNPJ 44.891.225.0001-50.<\/strong> Os itens 007 e 008 foram adjudicados \u00e0 empresa LIKE FARMA LOGISTICA CERTA COMERCIO E DISTRIBUIDORA DE PRODUTOS LTDA com o CNPJ 54.703.989.0001-29. Os itens 009, 010, 011, 013 e 014 foram adjudicados \u00e0 empresa SANT\u00c9 M\u00c9DICA HOSPITALAR LTDA com o CNPJ 16.699.864.0001-83. Os itens 018 e 021 foram adjudicados \u00e0 empresa SALUTE MED HOSPITALAR LTDA com o CNPJ 51.406.738.0001-94. <strong>Restou fracassado o item 019; Os itens 001, 002, 012, 015, 016, 017 e 020 restaram desertos. Conforme integra do Termo de Julgamento e Homologa\u00e7\u00e3o dispon\u00edvel nos seguintes s\u00edtios:<\/strong><strong> <\/strong><a href=\"https:\/\/sislog.go.gov.br\/\"><strong>https:\/\/sislog.go.gov.br<\/strong><\/a><strong> e <\/strong><a href=\"https:\/\/pncp.gov.br\/app\/editais\"><strong>https:\/\/pncp.gov.br\/app\/editais<\/strong><\/a><strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Goi\u00e2nia, 14 de julho de 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>THALLES PAULINO DE \u00c1VILA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Superintendente de Gest\u00e3o Integrada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria de Estado da Sa\u00fade<br>Delega\u00e7\u00e3o de Compet\u00eancia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/diariooficial.abc.go.gov.br\/portal\/visualizacoes\/pdf\/6470\/#\/p:24\/e:6470\">Portaria n\u00ba 854, de 04 de abril de 2025<\/a><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/termo-homologacao\/2025\/termo-julgamento-homologacao-110809.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Termo de Julgamento e Homologa\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Preg\u00e3o Eletr\u00f4nico n.\u00b0 113\/2025 SES-GO SISLOG: 110809 A Secretaria de Estado da Sa\u00fade de Goi\u00e1s torna p\u00fablico o resultado do Preg\u00e3o Eletr\u00f4nico n\u00ba 113\/2025, Processo SEI 202400005045342, para contrata\u00e7\u00e3o de produtos nutricionais e\/ou produtos para sa\u00fade, que foram concedidos nas apresenta\u00e7\u00f5es e concentra\u00e7\u00f5es registradas na ANVISA prescritas nos receitu\u00e1rios m\u00e9dicos presentes nos autos das a\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[416],"tags":[],"class_list":["post-439143","post","type-post","status-publish","format-standard","hentry","category-pregao-eletronico-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/pregao-eletronico-2025\/\" rel=\"category tag\">Preg\u00e3o Eletr\u00f4nico 2025<\/a>","rttpg_excerpt":"Preg\u00e3o Eletr\u00f4nico n.\u00b0 113\/2025 SES-GO SISLOG: 110809 A Secretaria de Estado da Sa\u00fade de Goi\u00e1s torna p\u00fablico o resultado do Preg\u00e3o Eletr\u00f4nico n\u00ba 113\/2025, Processo SEI 202400005045342, para contrata\u00e7\u00e3o de produtos nutricionais e\/ou produtos para sa\u00fade, que foram concedidos nas apresenta\u00e7\u00f5es e concentra\u00e7\u00f5es registradas na ANVISA prescritas nos receitu\u00e1rios m\u00e9dicos presentes nos autos das a\u00e7\u00f5es&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/439143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=439143"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/439143\/revisions"}],"predecessor-version":[{"id":439166,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/439143\/revisions\/439166"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=439143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=439143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=439143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}