{"id":435565,"date":"2025-07-09T16:21:03","date_gmt":"2025-07-09T19:21:03","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=435565"},"modified":"2025-07-09T16:21:04","modified_gmt":"2025-07-09T19:21:04","slug":"termo-de-homologacao-no-115527-inexigibilidade-n-o-65-2025","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/termo-de-homologacao-no-115527-inexigibilidade-n-o-65-2025\/","title":{"rendered":"Termo de Homologa\u00e7\u00e3o n\u00ba 115527 \u2013 Inexigibilidade n.\u00ba 65\/2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>N\u00famero do Processo SISLOG: 115527<\/strong><strong><br><\/strong>N\u00famero do Processo SEI: 202500005022308<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Pelo presente instrumento, considerando os procedimentos relativos \u00e0 contrata\u00e7\u00e3o de Aquisi\u00e7\u00e3o de inscri\u00e7\u00f5es para o 1\u00aa ISCIP &#8211; International Symposium on Critically III Patients, que ser\u00e1 realizado nos dias 10 e 11 de julho do corrente ano, no Centro de Conven\u00e7\u00f5es Rebou\u00e7as, em S\u00e3o Paulo., mediante Inexigibilidade, referente ao processo de contrata\u00e7\u00e3o SISLOG n\u00ba 115527\/2025 e processo SEI n\u00ba 202500005022308, realizada atendendo aos preceitos da Lei federal n\u00ba 14.133, de 01 de abril de 2021 e da Instru\u00e7\u00e3o Normativa n\u00ba 5\/2023-SEAD, decido AUTORIZAR e HOMOLOGAR a presente contrata\u00e7\u00e3o, fundamentada na Lei 14.133\/2021, Art. 74, III, f, conforme resultado a seguir:<strong><br><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td colspan=\"3\"><strong>Descri\u00e7\u00e3o do item 001<\/strong><br>C\u00f3digo 909 &#8211; Capacita\u00e7\u00e3o Profissional, participa\u00e7\u00e3o em congresso.<\/td><\/tr><tr><td colspan=\"3\"><strong>Informa\u00e7\u00f5es Adicionais<\/strong><br>Aquisi\u00e7\u00e3o de inscri\u00e7\u00f5es para o 1\u00aa ISCIP &#8211; International Symposium on Critically III Patients, que ser\u00e1 realizado nos dias 10 e 11 de julho do corrente ano, no Centro de Conven\u00e7\u00f5es Rebou\u00e7as, em S\u00e3o Paulo. M\u00e9dicos<\/td><\/tr><tr><td>Per\u00edodo (Meses)<\/td><td colspan=\"2\">&nbsp;<\/td><\/tr><tr><td>Quantidade<\/td><td colspan=\"2\">300<\/td><\/tr><tr><td>Unidade<\/td><td colspan=\"2\">unidade<\/td><\/tr><tr><td>CPF\/CNPJ<\/td><td colspan=\"2\">69.271.781\/0001-55<\/td><\/tr><tr><td>Fornecedor<\/td><td colspan=\"2\">NOVA PARADIGMA ORGANIZACAO DE CONGRESSOS LTDA<\/td><\/tr><tr><td>Valor Unit\u00e1rio<\/td><td colspan=\"2\">R$ 470,00<\/td><\/tr><tr><td>Valor Total<\/td><td colspan=\"2\">R$ 141.000,00<\/td><\/tr><tr><td colspan=\"3\"><strong>Descri\u00e7\u00e3o do item 002<\/strong><br>C\u00f3digo 909 &#8211; Capacita\u00e7\u00e3o Profissional, participa\u00e7\u00e3o em congresso.<\/td><\/tr><tr><td colspan=\"3\"><strong>Informa\u00e7\u00f5es Adicionais<\/strong><br>Aquisi\u00e7\u00e3o de inscri\u00e7\u00f5es para o 1\u00aa ISCIP &#8211; International Symposium on Critically III Patients, que ser\u00e1 realizado nos dias 10 e 11 de julho do corrente ano, no Centro de Conven\u00e7\u00f5es Rebou\u00e7as, em S\u00e3o Paulo. Enfermeiros<\/td><\/tr><tr><td colspan=\"2\">Per\u00edodo (Meses)<\/td><td>&nbsp;<\/td><\/tr><tr><td colspan=\"2\">Quantidade<\/td><td>100<\/td><\/tr><tr><td colspan=\"2\">Unidade<\/td><td>unidade<\/td><\/tr><tr><td colspan=\"2\">CPF\/CNPJ<\/td><td>69.271.781\/0001-55<\/td><\/tr><tr><td colspan=\"2\">Fornecedor<\/td><td>NOVA PARADIGMA ORGANIZACAO DE CONGRESSOS LTDA<\/td><\/tr><tr><td colspan=\"2\">Valor Unit\u00e1rio<\/td><td>R$ 290,00<\/td><\/tr><tr><td colspan=\"2\">Valor Total<\/td><td>R$ 29.000,00<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, determino a divulga\u00e7\u00e3o da presente contrata\u00e7\u00e3o no sistema eletr\u00f4nico de contrata\u00e7\u00f5es estaduais &#8211; SISLOG, nos termos do art. 9\u00ba da Instru\u00e7\u00e3o Normativa n\u00ba 5\/2023-SEAD, com a posterior publica\u00e7\u00e3o do contrato decorrente, que ser\u00e1 publicado nos termos do artigo 94 da Lei federal n\u00ba 14.133, de 01 de abril de 2021 e art. 11 da Instru\u00e7\u00e3o Normativa n\u00ba 5\/2023-SEAD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>LUANY BATISTA AMARAL<\/strong><br>Superintendente de Gest\u00e3o Integrada em Substitui\u00e7\u00e3o<br>(Portaria n\u00ba 1477, de 05 de junho de 2025)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Secretaria de Estado da Sa\u00fade<\/em><br><em>Delega\u00e7\u00e3o de Compet\u00eancia<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/diariooficial.abc.go.gov.br\/portal\/visualizacoes\/pdf\/6601\/#\/p:46\/e:6601\">Portaria n\u00ba 854, de 04 de abril de 2025<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00famero do Processo SISLOG: 115527N\u00famero do Processo SEI: 202500005022308 &nbsp;Pelo presente instrumento, considerando os procedimentos relativos \u00e0 contrata\u00e7\u00e3o de Aquisi\u00e7\u00e3o de inscri\u00e7\u00f5es para o 1\u00aa ISCIP &#8211; International Symposium on Critically III Patients, que ser\u00e1 realizado nos dias 10 e 11 de julho do corrente ano, no Centro de Conven\u00e7\u00f5es Rebou\u00e7as, em S\u00e3o Paulo., mediante [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[419],"tags":[],"class_list":["post-435565","post","type-post","status-publish","format-standard","hentry","category-dispensa-e-inexigibilidade-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/dispensa-e-inexigibilidade-2025\/\" rel=\"category tag\">Dispensa e Inexigibilidade 2025<\/a>","rttpg_excerpt":"N\u00famero do Processo SISLOG: 115527N\u00famero do Processo SEI: 202500005022308 &nbsp;Pelo presente instrumento, considerando os procedimentos relativos \u00e0 contrata\u00e7\u00e3o de Aquisi\u00e7\u00e3o de inscri\u00e7\u00f5es para o 1\u00aa ISCIP &#8211; International Symposium on Critically III Patients, que ser\u00e1 realizado nos dias 10 e 11 de julho do corrente ano, no Centro de Conven\u00e7\u00f5es Rebou\u00e7as, em S\u00e3o Paulo., mediante&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/435565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=435565"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/435565\/revisions"}],"predecessor-version":[{"id":435638,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/435565\/revisions\/435638"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=435565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=435565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=435565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}