{"id":428808,"date":"2025-07-03T08:31:07","date_gmt":"2025-07-03T11:31:07","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=428808"},"modified":"2025-07-03T08:31:08","modified_gmt":"2025-07-03T11:31:08","slug":"termo-de-julgamento-e-homologacao-no-106409-dispensa-eletronica-n-o-17-2025","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/termo-de-julgamento-e-homologacao-no-106409-dispensa-eletronica-n-o-17-2025\/","title":{"rendered":"Termo de Julgamento e Homologa\u00e7\u00e3o n\u00ba 106409 \u2013 Dispensa Eletr\u00f4nica n.\u00ba 17\/2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>N\u00famero do Processo SISLOG: 106409<br><\/strong>N\u00famero do Processo SEI: 202400005020500<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a> \u00c0s 08:00 horas, do dia 28\/04\/2025, iniciou-se a sess\u00e3o p\u00fablica on-line para realiza\u00e7\u00e3o dos procedimentos relativos \u00e0 contrata\u00e7\u00e3o de TEDUGLUTIDA 5MG, P\u00d3 LIOF SOL. INJ , mediante Dispensa Eletr\u00f4nica, referente ao processo de contrata\u00e7\u00e3o SISLOG n\u00ba 106409\/2025 e processo SEI n\u00ba 202400005020500, quando o agente da contrata\u00e7\u00e3o direta e os membros da equipe de apoio, indicados pela Portaria de Designa\u00e7\u00e3o de Fun\u00e7\u00f5es, se reuniram em atendimento \u00e0s disposi\u00e7\u00f5es contidas no instrumento convocat\u00f3rio, juntamente com os fornecedores credenciados, chegaram ao seguinte resultado:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td colspan=\"2\"><strong>Descri\u00e7\u00e3o do item 001<br>C\u00f3digo 3278 &#8211; Teduglutida, 5 Mg Po Liof Sol Inj<\/strong><\/td><\/tr><tr><td><strong>Per\u00edodo (Meses)<\/strong><\/td><td><\/td><\/tr><tr><td><strong>Quantidade<\/strong><\/td><td>196<\/td><\/tr><tr><td><strong>Unidade<\/strong><\/td><td>unidade<\/td><\/tr><tr><td><strong>CPF\/CNPJ<\/strong><\/td><td>12.420.164\/0036-87<\/td><\/tr><tr><td><strong>Fornecedor<\/strong><\/td><td>CM HOSPITALAR S A<\/td><\/tr><tr><td><strong>Valor Unit\u00e1rio<\/strong><\/td><td>R$ 3.631,76<\/td><\/tr><tr><td><strong>Valor Total<\/strong><\/td><td>R$ 711.824,96<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> Considerando que o procedimento de sele\u00e7\u00e3o do fornecedor foi realizado atendendo aos preceitos da Lei 14.133\/2021, Art. 75, VIII, e do Decreto estadual n\u00ba 10.211, de 06 de fevereiro de 2023. Considerando que foi divulgado o resultado da sess\u00e3o p\u00fablica com o(s) licitante(s) melhor(es) classificado(s), ao(s) qual(is) foi(am) declarado(s) vencedor(es) no(s) respectivo(s) iten(s)\/lote(s), decido ADJUDICAR e HOMOLOGAR o presente certame, nos termos do art. 72 da Lei federal n\u00ba 14.133, de 01 de abril de 2021 e art. 27 do Decreto estadual n\u00ba 10.211, de 06 de fevereiro de 2023. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LUANY BATISTA AMARAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Superintendente de Gest\u00e3o Integrada em Substitui\u00e7\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Portaria n\u00ba 1477, de 05 de junho de 2025)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria de Estado da Sa\u00fade<br>Delega\u00e7\u00e3o de Compet\u00eancia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/diariooficial.abc.go.gov.br\/portal\/visualizacoes\/pdf\/6601\/#\/p:46\/e:6601\">Portaria n<\/a><a href=\"https:\/\/diariooficial.abc.go.gov.br\/portal\/visualizacoes\/pdf\/6601\/#\/p:46\/e:6601\">\u00ba 854, de 04 de abril de 2025<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00famero do Processo SISLOG: 106409N\u00famero do Processo SEI: 202400005020500 \u00c0s 08:00 horas, do dia 28\/04\/2025, iniciou-se a sess\u00e3o p\u00fablica on-line para realiza\u00e7\u00e3o dos procedimentos relativos \u00e0 contrata\u00e7\u00e3o de TEDUGLUTIDA 5MG, P\u00d3 LIOF SOL. INJ , mediante Dispensa Eletr\u00f4nica, referente ao processo de contrata\u00e7\u00e3o SISLOG n\u00ba 106409\/2025 e processo SEI n\u00ba 202400005020500, quando o agente da [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[419],"tags":[],"class_list":["post-428808","post","type-post","status-publish","format-standard","hentry","category-dispensa-e-inexigibilidade-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/dispensa-e-inexigibilidade-2025\/\" rel=\"category tag\">Dispensa e Inexigibilidade 2025<\/a>","rttpg_excerpt":"N\u00famero do Processo SISLOG: 106409N\u00famero do Processo SEI: 202400005020500 \u00c0s 08:00 horas, do dia 28\/04\/2025, iniciou-se a sess\u00e3o p\u00fablica on-line para realiza\u00e7\u00e3o dos procedimentos relativos \u00e0 contrata\u00e7\u00e3o de TEDUGLUTIDA 5MG, P\u00d3 LIOF SOL. INJ , mediante Dispensa Eletr\u00f4nica, referente ao processo de contrata\u00e7\u00e3o SISLOG n\u00ba 106409\/2025 e processo SEI n\u00ba 202400005020500, quando o agente da&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/428808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=428808"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/428808\/revisions"}],"predecessor-version":[{"id":428827,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/428808\/revisions\/428827"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=428808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=428808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=428808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}