

{"id":4251,"date":"2016-04-25T13:51:44","date_gmt":"2016-04-25T16:51:44","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/agentes-de-endemias-e-comunitarios-fundamentais-para-sucesso-do-goias-contra-o-aedes\/"},"modified":"2016-04-25T13:51:44","modified_gmt":"2016-04-25T16:51:44","slug":"agentes-de-endemias-e-comunitarios-fundamentais-para-sucesso-do-goias-contra-o-aedes","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/agentes-de-endemias-e-comunitarios-fundamentais-para-sucesso-do-goias-contra-o-aedes\/","title":{"rendered":"Agentes de endemias e comunit\u00e1rios: fundamentais para sucesso do \u201cGoi\u00e1s contra o Aedes\u201d"},"content":{"rendered":"<p><h6><\/h6>\n<\/p>\n<div class=\"tx cl\">\n<p><em>Esses profissionais identificam, eliminam os focos e orientam os moradores sobre cuidados preventivos para a sa\u00fade da fam\u00edlia.<\/em><\/p>\n<p>A opera\u00e7\u00e3o \u201cGoi\u00e1s Contra o Aedes\u201d, desenvolvida pela Secretaria de Estado da Sa\u00fade de Goi\u00e1s (SES-GO) com apoio do Corpo de Bombeiros Militar, Prefeituras Municipais de Sa\u00fade e \u00f3rg\u00e3os afins, tem alcan\u00e7ado pleno \u00eaxito no Estado. Desde o in\u00edcio da for\u00e7a-tarefa, em dezembro do ano passado, foram visitados em todo o Estado mais de 5 milh\u00f5es de im\u00f3veis entre casas, estabelecimentos comerciais, \u00f3rg\u00e3os p\u00fablicos e lotes baldios. Neste per\u00edodo, as equipes respons\u00e1veis pela a\u00e7\u00e3o eliminaram 80 mil criadouros do Aedes aegypti em todos os munic\u00edpios do Estado. A a\u00e7\u00e3o pretende erradicar o mosquito em todo o territ\u00f3rio goiano.<\/p>\n<p>Grande parte do \u00eaxito da megaopera\u00e7\u00e3o contra o Aedes em Goi\u00e1s \u00e9 resultante do empenho, dedica\u00e7\u00e3o e determina\u00e7\u00e3o dos agentes de endemias (AE) e agentes comunit\u00e1rios de sa\u00fade (ACS). Contratados pelos munic\u00edpios nos quais atuam, os AEs e ACSs est\u00e3o presentes em todas as equipes. Tais trabalhadores conhecem profundamente a \u00e1rea em que atuam e mant\u00e9m um v\u00ednculo de confian\u00e7a com os moradores em fun\u00e7\u00e3o do trabalho di\u00e1rio, das constantes visitas que realizam aos domic\u00edlios.<\/p>\n<p>Os dados da SES-GO constatam que em todo o Estado existem em atua\u00e7\u00e3o cerca de 8 mil agentes comunit\u00e1rios de sa\u00fade e 2,8 mil agentes de endemias. Este contingente de trabalhadores est\u00e1 distribu\u00eddo em mais de 1,3 mil equipes do programa Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia, que leva informa\u00e7\u00f5es preventivas \u00e0 popula\u00e7\u00e3o em visitas domiciliares.<\/p>\n<p>A gerente de Aten\u00e7\u00e3o \u00e0 Sa\u00fade da Superintend\u00eancia de Vigil\u00e2ncia em Sa\u00fade, Marisa Aparecida de Sousa e Silva, destaca que os AEs e ACSs representam uma importante for\u00e7a de trabalho na comunidade. \u201cEstas duas categorias atuam em prol da popula\u00e7\u00e3o. Tais agentes conhecem cada ente de sua \u00e1rea de atua\u00e7\u00e3o, o que lhe confere maior credibilidade, fortalece o v\u00ednculo e, ao mesmo tempo, lhe imp\u00f5e mais responsabilidades.\u201d<\/p>\n<p>Na a\u00e7\u00e3o Goi\u00e1s contra o Aedes, os agentes de endemias t\u00eam a fun\u00e7\u00e3o de identificar e eliminar os focos e, al\u00e9m disso, repassar orienta\u00e7\u00f5es aos moradores quanto \u00e0 import\u00e2ncia da vistoria rotineira. J\u00e1 os agentes comunit\u00e1rios de sa\u00fade atuam de forma complementar, levando informa\u00e7\u00f5es sobre a\u00e7\u00f5es e cuidados preventivos para a sa\u00fade da fam\u00edlia.<\/p>\n<p><strong>5 milh\u00f5es de visitas em 2016<\/strong><\/p>\n<p>A Diretriz Nacional para Controle de Epidemia de Dengue de 2009, do Minist\u00e9rio da Sa\u00fade, estabelece como par\u00e2metro que cada agente de endemias deve fazer de 20 a 25 visitas aos im\u00f3veis diariamente. Em Goi\u00e1s, foram realizadas aproximadamente 5 milh\u00f5es de visitas de janeiro a abril de 2016. Levando-se em considera\u00e7\u00e3o apenas os dias \u00fateis desse per\u00edodo, foram realizadas 25 visitas di\u00e1rias aos im\u00f3veis goianos, por cada agente de endemia do Estado (s\u00e3o 2,8 mil agentes em Goi\u00e1s). Ressalta-se que o c\u00e1lculo inclui, al\u00e9m de resid\u00eancias, lotes baldios, estabelecimentos comerciais, im\u00f3veis rurais, ou seja propriedades em geral e n\u00e3o apenas os domic\u00edlios residenciais.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esses profissionais identificam, eliminam os focos e orientam os moradores sobre cuidados preventivos para a sa\u00fade da fam\u00edlia. A opera\u00e7\u00e3o \u201cGoi\u00e1s Contra o Aedes\u201d, desenvolvida pela Secretaria de Estado da Sa\u00fade de Goi\u00e1s (SES-GO) com apoio do Corpo de Bombeiros Militar, Prefeituras Municipais de Sa\u00fade e \u00f3rg\u00e3os afins, tem alcan\u00e7ado pleno \u00eaxito no Estado. Desde [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4251","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Esses profissionais identificam, eliminam os focos e orientam os moradores sobre cuidados preventivos para a sa\u00fade da fam\u00edlia. A opera\u00e7\u00e3o \u201cGoi\u00e1s Contra o Aedes\u201d, desenvolvida pela Secretaria de Estado da Sa\u00fade de Goi\u00e1s (SES-GO) com apoio do Corpo de Bombeiros Militar, Prefeituras Municipais de Sa\u00fade e \u00f3rg\u00e3os afins, tem alcan\u00e7ado pleno \u00eaxito no Estado. Desde&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/4251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=4251"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/4251\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=4251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=4251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=4251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}