{"id":395608,"date":"2025-06-05T07:42:37","date_gmt":"2025-06-05T10:42:37","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=395608"},"modified":"2025-06-05T07:42:40","modified_gmt":"2025-06-05T10:42:40","slug":"extrato-do-contrato-no-55-2025-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-do-contrato-no-55-2025-ses-go\/","title":{"rendered":"Extrato do Contrato n\u00ba 55\/2025 \u2013 SES\/GO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">EXTRATO DO CONTRATO N\u00ba 55\/2025-SES\/GO. Processo n\u00ba: 202500010042017, vinculado ao de n\u00ba 202500005017602. Contratante: Estado de Goi\u00e1s, por interm\u00e9dio da Secretaria de Estado da Sa\u00fade. Contratado: Funda\u00e7\u00e3o Dom Cabral. Objeto: Contrata\u00e7\u00e3o de Servi\u00e7os: Programa de Implementa\u00e7\u00e3o da Alta Perfomance para a Lideran\u00e7a &#8211; Secretaria de Estado da Sa\u00fade de Goi\u00e1s &#8211; SES\/GO. Valor do contrato: R$ 3.214.500,00. Dota\u00e7\u00e3o Or\u00e7ament\u00e1ria: 2850.10.122.2400.4243.03.15000100.90. Vig\u00eancia: A vig\u00eancia do Contrato ser\u00e1 de 18 (dezoito) meses, contados a partir do dia 08 de junho de 2025, tendo efic\u00e1cia ap\u00f3s a divulga\u00e7\u00e3o no Portal Nacional de Contrata\u00e7\u00f5es P\u00fablicas (PNCP). Data da Assinatura: 04\/06\/2025. Signat\u00e1rios: Ras\u00edvel dos Reis Santos J\u00fanior \u2013 Secret\u00e1rio de Estado da Sa\u00fade; Ant\u00f4nio Batista da Silva J\u00fanior \u2013 Funda\u00e7\u00e3o Dom Cabral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EXTRATO DO CONTRATO N\u00ba 55\/2025-SES\/GO. Processo n\u00ba: 202500010042017, vinculado ao de n\u00ba 202500005017602. Contratante: Estado de Goi\u00e1s, por interm\u00e9dio da Secretaria de Estado da Sa\u00fade. Contratado: Funda\u00e7\u00e3o Dom Cabral. Objeto: Contrata\u00e7\u00e3o de Servi\u00e7os: Programa de Implementa\u00e7\u00e3o da Alta Perfomance para a Lideran\u00e7a &#8211; Secretaria de Estado da Sa\u00fade de Goi\u00e1s &#8211; SES\/GO. Valor do contrato: [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[421],"tags":[],"class_list":["post-395608","post","type-post","status-publish","format-standard","hentry","category-contratos-e-termos-aditivos-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ricardocruz","author_link":"https:\/\/goias.gov.br\/saude\/author\/ricardocruz\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/contratos-e-termos-aditivos-2025\/\" rel=\"category tag\">Contratos e Termos Aditivos 2025<\/a>","rttpg_excerpt":"EXTRATO DO CONTRATO N\u00ba 55\/2025-SES\/GO. Processo n\u00ba: 202500010042017, vinculado ao de n\u00ba 202500005017602. Contratante: Estado de Goi\u00e1s, por interm\u00e9dio da Secretaria de Estado da Sa\u00fade. Contratado: Funda\u00e7\u00e3o Dom Cabral. Objeto: Contrata\u00e7\u00e3o de Servi\u00e7os: Programa de Implementa\u00e7\u00e3o da Alta Perfomance para a Lideran\u00e7a &#8211; Secretaria de Estado da Sa\u00fade de Goi\u00e1s &#8211; SES\/GO. Valor do contrato:&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/395608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=395608"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/395608\/revisions"}],"predecessor-version":[{"id":395626,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/395608\/revisions\/395626"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=395608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=395608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=395608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}