{"id":38684,"date":"2023-12-13T10:36:00","date_gmt":"2023-12-13T13:36:00","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/?p=38684"},"modified":"2023-12-14T16:56:06","modified_gmt":"2023-12-14T19:56:06","slug":"extrato-da-portaria-n-2302-2023-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-da-portaria-n-2302-2023-ses-go\/","title":{"rendered":"Extrato da Portaria n.\u00b0 2302\/2023 &#8211; SES\/GO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Revoga\u00e7\u00e3o da Portaria n\u00ba 545\/2022-SES, de 25\/03\/2022, publicada na p\u00e1gina 51 do Di\u00e1rio Oficial do Estado de Goi\u00e1s n\u00ba 23.767, no dia 29\/03\/2022, que designou FABIANO DE OLIVEIRA BORBA como Gestor do Contrato n\u00b0 10\/2021 SES-GO, e designa\u00e7\u00e3o de novos Gestores do Contrato. Processo n\u00ba: 202000010035633. Objeto do Contrato: contrata\u00e7\u00e3o de servi\u00e7os de Outsourcing de Impress\u00e3o, com impressoras t\u00e9rmicas para o Laborat\u00f3rio Estadual de Sa\u00fade P\u00fablica &#8211; Dr. Giovanni Cysneiros &#8211; LACEN, por ades\u00e3o \u00e0 Ata de Registro de Pre\u00e7os n\u00b010\/2020, referente ao Preg\u00e3o Eletr\u00f4nico n\u00b0 28\/2019, da Secretaria Municipal de Administra\u00e7\u00e3o da Prefeitura de Goi\u00e2nia. Contratada: BKM Com\u00e9rcio e Loca\u00e7\u00e3o de Equipamentos Ltda. Gestores: FABIANO DE OLIVEIRA BORBA, CPF n\u00ba 801.XXX.XXX-34 e LUCIANA MACHADO MARTINS, CPF n\u00ba 706.XXX.XXX-15 Fundamento: Lei Federal n\u00ba 8.666\/1993, art. 67 e Lei Estadual n\u00ba 17.928\/2012, arts. 51\/54. Vig\u00eancia: A partir da data da assinatura: 11\/12\/2023. Signat\u00e1rio: S\u00e9rgio Alberto Cunha V\u00eancio \u2013 Secret\u00e1rio de Estado da Sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Revoga\u00e7\u00e3o da Portaria n\u00ba 545\/2022-SES, de 25\/03\/2022, publicada na p\u00e1gina 51 do Di\u00e1rio Oficial do Estado de Goi\u00e1s n\u00ba 23.767, no dia 29\/03\/2022, que designou FABIANO DE OLIVEIRA BORBA como Gestor do Contrato n\u00b0 10\/2021 SES-GO, e designa\u00e7\u00e3o de novos Gestores do Contrato. Processo n\u00ba: 202000010035633. Objeto do Contrato: contrata\u00e7\u00e3o de servi\u00e7os de Outsourcing de [&hellip;]<\/p>\n","protected":false},"author":698,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[],"class_list":["post-38684","post","type-post","status-publish","format-standard","hentry","category-extrato-de-portarias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"leidianesilva","author_link":"https:\/\/goias.gov.br\/saude\/author\/leidianesilva\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/extrato-de-portarias\/\" rel=\"category tag\">Extrato de Portarias 2023<\/a>","rttpg_excerpt":"Revoga\u00e7\u00e3o da Portaria n\u00ba 545\/2022-SES, de 25\/03\/2022, publicada na p\u00e1gina 51 do Di\u00e1rio Oficial do Estado de Goi\u00e1s n\u00ba 23.767, no dia 29\/03\/2022, que designou FABIANO DE OLIVEIRA BORBA como Gestor do Contrato n\u00b0 10\/2021 SES-GO, e designa\u00e7\u00e3o de novos Gestores do Contrato. Processo n\u00ba: 202000010035633. Objeto do Contrato: contrata\u00e7\u00e3o de servi\u00e7os de Outsourcing de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/38684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/698"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=38684"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/38684\/revisions"}],"predecessor-version":[{"id":38685,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/38684\/revisions\/38685"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=38684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=38684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=38684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}