

{"id":3797,"date":"2016-10-06T11:39:37","date_gmt":"2016-10-06T14:39:37","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/hmi-realiza-novo-parto-de-gemeas-siamesas\/"},"modified":"2016-10-06T11:39:37","modified_gmt":"2016-10-06T14:39:37","slug":"hmi-realiza-novo-parto-de-gemeas-siamesas","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/hmi-realiza-novo-parto-de-gemeas-siamesas\/","title":{"rendered":"HMI realiza novo parto de g\u00eameas siamesas"},"content":{"rendered":"<p>No fim da tarde de ontem, 5 de outubro (quarta-feira), o Hospital Materno Infantil (HMI) realizou mais um parto de g\u00eameas siamesas. As irm\u00e3s nasceram com 33 semanas, unidas pelo abd\u00f4men, compartilhando apenas o f\u00edgado. Juntas, elas pesam 3.885 quilogramas. Ap\u00f3s o nascimento, as beb\u00eas foram encaminhadas \u00e0 Unidade de Cuidados Intermedi\u00e1rios Neonatal (Ucin).<\/p>\n<div class=\"tx cl\">\n<div class=\"gmail_quote\">\n<div dir=\"ltr\">\n<div class=\"gmail_quote\">\n<div dir=\"ltr\">\n<div class=\"yj6qo ajU\">\n<p><div id=\":1k1\" class=\"ajR\" data-tooltip=\"Ocultar conte\u00fado expandido\"><img decoding=\"async\" class=\"ajT size-full wp-image-1226\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif\" alt=\"\" width=\"1\" height=\"1\" \/>O hospital informa ainda que o estado de sa\u00fade das g\u00eameas \u00e9 regular, uma respira com o aux\u00edlio de oxig\u00eanio inalat\u00f3rio, enquanto a outra respira normalmente. J\u00e1 a m\u00e3e, Nayara Soares dos Santos, de 19 anos, natural de Campos Belos, Goi\u00e1s, encontra-se internada na enfermaria da Cl\u00ednica de Ginecologia do HMI. O estado de sa\u00fade dela \u00e9 bom. N\u00e3o h\u00e1 previs\u00e3o de alta para as g\u00eameas assim como n\u00e3o h\u00e1 para a m\u00e3e.<\/div>\n<\/p>\n<\/div>\n<div class=\"adL\">\n<p><p dir=\"ltr\">Observa\u00e7\u00e3o:\u00a0A m\u00e3e das g\u00eameas e o cirurgi\u00e3o pedi\u00e1trico Zacharias Calil estar\u00e3o dispon\u00edveis para\u00a0<strong>entrevista na tarde de hoje (6 de outubro), \u00e0s 14h<\/strong>,\u00a0<strong>no Hospital Materno Infantil (HMI).<\/strong>\u00a0Todas as informa\u00e7\u00f5es sobre o estado de sa\u00fade das pacientes ser\u00e3o repassadas pela Assessoria de Imprensa do HMI, por meio de boletins expedidos duas vezes ao dia &#8211; \u00e0s 8h30min e \u00e0s 17h.<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No fim da tarde de ontem, 5 de outubro (quarta-feira), o Hospital Materno Infantil (HMI) realizou mais um parto de g\u00eameas siamesas. As irm\u00e3s nasceram com 33 semanas, unidas pelo abd\u00f4men, compartilhando apenas o f\u00edgado. Juntas, elas pesam 3.885 quilogramas. Ap\u00f3s o nascimento, as beb\u00eas foram encaminhadas \u00e0 Unidade de Cuidados Intermedi\u00e1rios Neonatal (Ucin). O [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":1226,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif",1,1,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif",1,1,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif",1,1,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif",1,1,false],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif",1,1,false],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif",1,1,false],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif",1,1,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2018\/10\/cleardot-a42.gif",1,1,false]},"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"No fim da tarde de ontem, 5 de outubro (quarta-feira), o Hospital Materno Infantil (HMI) realizou mais um parto de g\u00eameas siamesas. As irm\u00e3s nasceram com 33 semanas, unidas pelo abd\u00f4men, compartilhando apenas o f\u00edgado. Juntas, elas pesam 3.885 quilogramas. Ap\u00f3s o nascimento, as beb\u00eas foram encaminhadas \u00e0 Unidade de Cuidados Intermedi\u00e1rios Neonatal (Ucin). O&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/3797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=3797"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/3797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/1226"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=3797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=3797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=3797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}