{"id":367974,"date":"2025-05-16T16:22:41","date_gmt":"2025-05-16T19:22:41","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=367974"},"modified":"2025-05-16T16:22:41","modified_gmt":"2025-05-16T19:22:41","slug":"hemocentro-de-goias-e-complexo-oncologico-de-referencia-do-estado-de-goias-assinam-termo-de-cooperacao-16-05-2025","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/hemocentro-de-goias-e-complexo-oncologico-de-referencia-do-estado-de-goias-assinam-termo-de-cooperacao-16-05-2025\/","title":{"rendered":"Hemocentro de Goi\u00e1s e Complexo Oncol\u00f3gico de Refer\u00eancia do Estado de Goi\u00e1s assinam termo de coopera\u00e7\u00e3o &#8211; 16\/05\/2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fotos \u2013 Iron Braz<\/p>\n\n\n\n<!--more-->\n\n\n\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a977f2ff2f88&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a977f30032b0&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a977f30032b0\" class=\"wp-block-image size-large wp-lightbox-container\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"367991\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03-1024x683.jpeg\" alt=\"\" class=\"wp-image-367991\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03-1024x683.jpeg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03-300x200.jpeg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03-768x512.jpeg 768w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03.jpeg 1224w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\"><mark>Gestores da SES-GO, do Hemocentro e do Cora reuniram-se para firmar o termo de coopera\u00e7\u00e3o para disponibiliza\u00e7\u00e3o de hemocomponentes e treinamento de profissionais<\/mark><\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a977f3005303&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a977f3005303\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"367992\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-02-1024x683.jpeg\" alt=\"\" class=\"wp-image-367992\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-02-1024x683.jpeg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-02-300x200.jpeg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-02-768x512.jpeg 768w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-02.jpeg 1224w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\"><mark>O secret\u00e1rio Ras\u00edvel Santos destacou que o Hemocentro ser\u00e1 respons\u00e1vel por disponibilizar ao Cora os hemocomponentes para as transfus\u00f5es<\/mark><\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a977f3006181&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a977f3006181\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"367993\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-01-1024x683.jpeg\" alt=\"\" class=\"wp-image-367993\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-01-1024x683.jpeg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-01-300x200.jpeg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-01-768x512.jpeg 768w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-01.jpeg 1224w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\"><mark>S\u00e9rgio Vencio acentuou que durante o tratamento de c\u00e2ncer os pacientes passam por procedimentos que exigem transfus\u00f5es<\/mark><\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Fotos \u2013 Iron Braz<\/p>\n","protected":false},"author":164,"featured_media":367991,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98],"tags":[169],"class_list":["post-367974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-galeria-de-fotos","tag-galeria-de-fotos"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03.jpeg",1224,816,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03.jpeg",1224,816,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03.jpeg",1224,816,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03-150x150.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03-300x200.jpeg",300,200,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03-1024x683.jpeg",1024,683,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03.jpeg",1224,816,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2025\/05\/1605-termo-cooperacao-cora-hemocentro-03.jpeg",1224,816,false]},"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/galeria-de-fotos\/\" rel=\"category tag\">galeria de fotos<\/a>","rttpg_excerpt":"Fotos \u2013 Iron Braz","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/367974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=367974"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/367974\/revisions"}],"predecessor-version":[{"id":368024,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/367974\/revisions\/368024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/367991"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=367974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=367974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=367974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}