

{"id":36559,"date":"2023-11-07T13:56:32","date_gmt":"2023-11-07T16:56:32","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/extrato-do-contrato-n-087-2023-ses-go\/"},"modified":"2023-11-07T13:56:32","modified_gmt":"2023-11-07T16:56:32","slug":"extrato-do-contrato-n-087-2023-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-do-contrato-n-087-2023-ses-go\/","title":{"rendered":"Extrato do Contrato n.\u00b0 087\/2023 &#8211; SES\/GO"},"content":{"rendered":"<p>EXTRATO DO CONTRATO N&ordm; 87\/2023-SES\/GO. Processo n&ordm;: 202300010027822. Contratada: POSITIVO TECNOLOGIA S\/A. Objeto: aquisi&ccedil;&atilde;o de 26 (vinte e seis) Notebooks conforme especifica&ccedil;&otilde;es estabelecidas no Termo de Refer&ecirc;ncia, com garantia de 36 meses &quot;On-site&quot;, para atender demanda da Secretaria de Estado da Sa&uacute;de de Goi&aacute;s. Valor do contrato: R$ 92.482,00. Dota&ccedil;&atilde;o Or&ccedil;ament&aacute;ria: 2850.10.572.1022. 2082.04.15000100.90; 2850.10.302.1043.2167.04.26030239. 90. Vig&ecirc;ncia: A vig&ecirc;ncia do contrato ser&aacute; de 12 (doze) meses, contados a partir da data desta publica&ccedil;&atilde;o no Di&aacute;rio Oficial do Estado de Goi&aacute;s. Data da assinatura: 06\/11\/2023. Signat&aacute;rios: S&eacute;rgio Alberto Cunha V&ecirc;ncio &#8211; Secret&aacute;rio de Estado da Sa&uacute;de; Aldejunio de Oliveira &nbsp;&#8211; Positivo Tecnologia S\/A.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EXTRATO DO CONTRATO N&ordm; 87\/2023-SES\/GO. Processo n&ordm;: 202300010027822. Contratada: POSITIVO TECNOLOGIA S\/A. Objeto: aquisi&ccedil;&atilde;o de 26 (vinte e seis) Notebooks conforme especifica&ccedil;&otilde;es estabelecidas no Termo de Refer&ecirc;ncia, com garantia de 36 meses &quot;On-site&quot;, para atender demanda da Secretaria de Estado da Sa&uacute;de de Goi&aacute;s. Valor do contrato: R$ 92.482,00. Dota&ccedil;&atilde;o Or&ccedil;ament&aacute;ria: 2850.10.572.1022. 2082.04.15000100.90; 2850.10.302.1043.2167.04.26030239. 90. [&hellip;]<\/p>\n","protected":false},"author":693,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[146],"tags":[],"class_list":["post-36559","post","type-post","status-publish","format-standard","hentry","category-contratos-e-termos-aditivos-2023"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"elzenubiamoreira","author_link":"https:\/\/goias.gov.br\/saude\/author\/elzenubiamoreira\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/contratos-e-termos-aditivos-2023\/\" rel=\"category tag\">Contratos e Termos Aditivos 2023<\/a>","rttpg_excerpt":"EXTRATO DO CONTRATO N&ordm; 87\/2023-SES\/GO. Processo n&ordm;: 202300010027822. Contratada: POSITIVO TECNOLOGIA S\/A. Objeto: aquisi&ccedil;&atilde;o de 26 (vinte e seis) Notebooks conforme especifica&ccedil;&otilde;es estabelecidas no Termo de Refer&ecirc;ncia, com garantia de 36 meses &quot;On-site&quot;, para atender demanda da Secretaria de Estado da Sa&uacute;de de Goi&aacute;s. Valor do contrato: R$ 92.482,00. Dota&ccedil;&atilde;o Or&ccedil;ament&aacute;ria: 2850.10.572.1022. 2082.04.15000100.90; 2850.10.302.1043.2167.04.26030239. 90.&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/36559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/693"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=36559"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/36559\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=36559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=36559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=36559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}