{"id":359295,"date":"2025-05-12T15:31:15","date_gmt":"2025-05-12T18:31:15","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=359295"},"modified":"2025-05-12T15:31:15","modified_gmt":"2025-05-12T18:31:15","slug":"extrato-do-2o-apostilamento-ao-contrato-no-83-2023-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-do-2o-apostilamento-ao-contrato-no-83-2023-ses-go\/","title":{"rendered":"Extrato do 2\u00ba Apostilamento ao Contrato n\u00ba 83\/2023 \u2013 SES\/GO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Processo n\u00ba: 202200010042613. Contratada: Memora Processos Inovadores S.A. Objeto: Pagamento da diferen\u00e7a do valor do reajuste do Contrato n\u00ba 83\/2023\/SES, concedido por meio do 1\u00ba Apostilamento, &#8220;\u2026referente ao per\u00edodo compreendido entre o momento em que o direito ao reajuste foi adquirido e a data de assinatura do aditivo ou apostilamento.&#8221;, a saber, de 07\/08\/2024 at\u00e9 o dia 25\/11\/2024, conforme consignado no Parecer Jur\u00eddico SES\/PROCSET n\u00ba 107\/2025. Valor da difere\u00e7a do Reajuste: R$ 108.804,94. Vig\u00eancia: a partir da data de assinatura desta Apostila. Data da assinatura da Apostila: 09\/05\/2025. Signat\u00e1rio: Ras\u00edvel dos Reis Santos J\u00fanior. Secret\u00e1rio de Estado da Sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Processo n\u00ba: 202200010042613. Contratada: Memora Processos Inovadores S.A. Objeto: Pagamento da diferen\u00e7a do valor do reajuste do Contrato n\u00ba 83\/2023\/SES, concedido por meio do 1\u00ba Apostilamento, &#8220;\u2026referente ao per\u00edodo compreendido entre o momento em que o direito ao reajuste foi adquirido e a data de assinatura do aditivo ou apostilamento.&#8221;, a saber, de 07\/08\/2024 at\u00e9 [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[421],"tags":[],"class_list":["post-359295","post","type-post","status-publish","format-standard","hentry","category-contratos-e-termos-aditivos-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/contratos-e-termos-aditivos-2025\/\" rel=\"category tag\">Contratos e Termos Aditivos 2025<\/a>","rttpg_excerpt":"Processo n\u00ba: 202200010042613. Contratada: Memora Processos Inovadores S.A. Objeto: Pagamento da diferen\u00e7a do valor do reajuste do Contrato n\u00ba 83\/2023\/SES, concedido por meio do 1\u00ba Apostilamento, &#8220;\u2026referente ao per\u00edodo compreendido entre o momento em que o direito ao reajuste foi adquirido e a data de assinatura do aditivo ou apostilamento.&#8221;, a saber, de 07\/08\/2024 at\u00e9&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/359295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=359295"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/359295\/revisions"}],"predecessor-version":[{"id":359316,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/359295\/revisions\/359316"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=359295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=359295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=359295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}