

{"id":31467,"date":"2023-01-31T08:15:31","date_gmt":"2023-01-31T11:15:31","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/aviso-de-licitacao-do-p-e-n-008-2023\/"},"modified":"2023-01-31T08:15:31","modified_gmt":"2023-01-31T11:15:31","slug":"aviso-de-licitacao-do-p-e-n-008-2023","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/aviso-de-licitacao-do-p-e-n-008-2023\/","title":{"rendered":"Aviso de Licita\u00e7\u00e3o do P.E. n.\u00ba 008\/2023"},"content":{"rendered":"<p>A SECRETARIA DE ESTADO DA SA&Uacute;DE-SES\/GO, torna p&uacute;blico que far&aacute; realizar a licita&ccedil;&atilde;o abaixo relacionada na modalidade PREG&Atilde;O ELETR&Ocirc;NICO na forma da lei. O edital encontra-se &agrave; disposi&ccedil;&atilde;o dos interessados na Ger&ecirc;ncia de Compras Governamentais\/SES-GO, situada na Rua SC-l, n&ordm; 299, Parque Santa Cruz, Goi&acirc;nia\/GO, CEP: 74.860-270 &ndash; Fone: 3201-3800\/3482, e no site: www.comprasnet.go.gov.br.<br \/>\nP.E. N.&deg; 008\/2023. Proc: 202200010050183 &ndash; Objeto: Registro de pre&ccedil;o para eventuais aquisi&ccedil;&otilde;es, por meio de contrata&ccedil;&atilde;o futura, do MEDICAMENTO: USTEQUINUMABE 45MG SOLU&Ccedil;&Atilde;O INJET&Aacute;VEL X 0,50ML, SERINGA PREENCHIDA, destinado ao Setor de Planejamento e Compras da Judicializa&ccedil;&atilde;o\/CEMAC\/SAIS\/SES-GO. Tipo: menor pre&ccedil;o por Item. Valor total estimado: R$ 715.374,00.<br \/>\nData de in&iacute;cio da apresenta&ccedil;&atilde;o das propostas e documentos de habilita&ccedil;&atilde;o: A partir das 16:00 h do dia 31\/01\/2023 (Hor&aacute;rio de Bras&iacute;lia).<br \/>\nData da abertura da sess&atilde;o p&uacute;blica: A partir das 09:00 h do dia 14\/02\/2023 (Hor&aacute;rio de Bras&iacute;lia)<br \/>\nGoi&acirc;nia\/GO, 30 de janeiro de 2023.<br \/>\nNatal de Castro &ndash; Gerente da GCG\/SES-GO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A SECRETARIA DE ESTADO DA SA&Uacute;DE-SES\/GO, torna p&uacute;blico que far&aacute; realizar a licita&ccedil;&atilde;o abaixo relacionada na modalidade PREG&Atilde;O ELETR&Ocirc;NICO na forma da lei. O edital encontra-se &agrave; disposi&ccedil;&atilde;o dos interessados na Ger&ecirc;ncia de Compras Governamentais\/SES-GO, situada na Rua SC-l, n&ordm; 299, Parque Santa Cruz, Goi&acirc;nia\/GO, CEP: 74.860-270 &ndash; Fone: 3201-3800\/3482, e no site: www.comprasnet.go.gov.br. P.E. [&hellip;]<\/p>\n","protected":false},"author":697,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[144],"tags":[],"class_list":["post-31467","post","type-post","status-publish","format-standard","hentry","category-pregao-eletronico-2023"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"klaubueno","author_link":"https:\/\/goias.gov.br\/saude\/author\/klaubueno\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/pregao-eletronico-2023\/\" rel=\"category tag\">Preg\u00e3o Eletr\u00f4nico 2023<\/a>","rttpg_excerpt":"A SECRETARIA DE ESTADO DA SA&Uacute;DE-SES\/GO, torna p&uacute;blico que far&aacute; realizar a licita&ccedil;&atilde;o abaixo relacionada na modalidade PREG&Atilde;O ELETR&Ocirc;NICO na forma da lei. O edital encontra-se &agrave; disposi&ccedil;&atilde;o dos interessados na Ger&ecirc;ncia de Compras Governamentais\/SES-GO, situada na Rua SC-l, n&ordm; 299, Parque Santa Cruz, Goi&acirc;nia\/GO, CEP: 74.860-270 &ndash; Fone: 3201-3800\/3482, e no site: www.comprasnet.go.gov.br. P.E.&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/31467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/697"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=31467"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/31467\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=31467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=31467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=31467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}