

{"id":3031,"date":"2017-06-06T12:34:40","date_gmt":"2017-06-06T15:34:40","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/mnsl-promove-forum-perinatal-de-goias\/"},"modified":"2017-06-06T12:34:40","modified_gmt":"2017-06-06T15:34:40","slug":"mnsl-promove-forum-perinatal-de-goias","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/mnsl-promove-forum-perinatal-de-goias\/","title":{"rendered":"MNSL promove F\u00f3rum Perinatal de Goi\u00e1s"},"content":{"rendered":"<p>A Maternidade Nossa Senhora de Lourdes, por meio de uma parceria entre os setores de Fisioterapia, Fonoaudiologia e Qualidade, promoveu na manh\u00e3 de hoje, 6 de junho (ter\u00e7a-feira), mais uma edi\u00e7\u00e3o do F\u00f3rum Perinatal goiano, um encontro mensal itinerante idealizado pela Superintend\u00eancia de Pol\u00edticas de Aten\u00e7\u00e3o Integral \u00e0 Sa\u00fade, da Secretaria de Estado de Sa\u00fade de Goi\u00e1s (Spais\/SES-GO). O tema proposto pela MNSL foi \u201cHumaniza\u00e7\u00e3o com Foco Assistenciais \u00e0s M\u00e3es e Rec\u00e9m-Nascidos\u201d. Pela primeira vez, o evento, que tem como objetivo discutir temas sobre a sa\u00fade perinatal, foi organizado por uma institui\u00e7\u00e3o. At\u00e9 o \u00faltimo encontro, o f\u00f3rum era planejado pela Superintend\u00eancia e as unidades apenas ofereciam seu espa\u00e7o para as discuss\u00f5es. O grupo participante \u00e9 formado por representantes da SES-GO, dos conselhos de classe, das universidades, dos hospitais e maternidades da Rede Cegonha goianos, dos hospitais com leitos de unidade de terapia (UTI) neoprivados e das Secretarias Municipais de Sa\u00fade (SMS) de Goi\u00e2nia e An\u00e1polis.<\/p>\n<div class=\"tx cl\">\n<p>Ap\u00f3s a presidente do F\u00f3rum, Lilian Ghannam, dar in\u00edcio ao evento agradecendo a disposi\u00e7\u00e3o e iniciativa da MNSL, a coordenadora de Fisioterapia da Maternidade, Nayara Oliveira, ministrou sobre a Humaniza\u00e7\u00e3o na Unidade de Cuidados Intermedi\u00e1rios Neonatais (Ucin). \u201cUm beb\u00ea que precisa de mais cuidados pode receber at\u00e9 150 est\u00edmulos dolorosos por dia dentro da Ucin e, hoje, se sabe que um rec\u00e9m nascido sente mais dor do que um adulto, por isso \u00e9 preciso que tenhamos formas alternativas de minimizar o sofrimento deles\u201d. Segundo a profissional, a unidade adota medidas como a terapia aqu\u00e1tica, uso de redinha, posicionamento alto e M\u00e9todo Canguru com o intuito de proporcionar o m\u00e1ximo de conforto e dignidade aos pacientes.<\/p>\n<p>Dando continuidade \u00e0 explica\u00e7\u00e3o sobre as formas encontradas pela MNSL para humanizar o atendimento, a supervisora de Enfermagem da unidade, Juliana Carvalho, mudou o enfoque para as gestantes e ministrou sobre o Cuidado Amigo da Mulher (CAM). A enfermeira listou aos presentes todos os direitos que a Portaria 1.153\/CAM, de 22 de maio de 2014, do Minist\u00e9rio da Sa\u00fade, garante \u00e0s mulheres que buscam assist\u00eancia na Maternidade para realizar o parto. O direito a ser acompanhado por uma pessoa de sua livre escolha, a receber l\u00edquidos e alimentos durante o trabalho de parto, entre outros foram explicitados por ela. \u201c\u00c9 preciso estar ao lado da paciente e explicar a ela todos os procedimentos pelos quais ela for submetida\u201d, acrescentou a palestrante.<\/p>\n<p>A amamenta\u00e7\u00e3o tamb\u00e9m foi destaque durante o evento. A fonoaudi\u00f3loga da MNSL, Marilene Bueno, ministrou sobre os \u201c10 Passos para o Sucesso da Amamenta\u00e7\u00e3o\u201d. \u201cN\u00e3o obrigamos as m\u00e3es a amamentarem quando n\u00e3o querem, mas explicamos a elas todos os benef\u00edcios que o ato garante ao beb\u00ea e esclarecemos os mitos sobre o assunto\u201d, informou. Para finalizar, o analista de Qualidade e presidente do N\u00facleo de Seguran\u00e7a do Paciente (NSP) da unidade, Igor Bezerra, explicou sobre os processos realizados pelo setor para garantir o bem estar dos pacientes. \u201cTrabalhamos com processos sist\u00eamicos e an\u00e1lise estrat\u00e9gica, pois todas as atividades s\u00e3o pass\u00edveis de erro, mas por meio de uma metodologia programada, conseguimos disseminar as informa\u00e7\u00f5es e reduzir ao m\u00e1ximo qualquer falha\u201d, explicou.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Maternidade Nossa Senhora de Lourdes, por meio de uma parceria entre os setores de Fisioterapia, Fonoaudiologia e Qualidade, promoveu na manh\u00e3 de hoje, 6 de junho (ter\u00e7a-feira), mais uma edi\u00e7\u00e3o do F\u00f3rum Perinatal goiano, um encontro mensal itinerante idealizado pela Superintend\u00eancia de Pol\u00edticas de Aten\u00e7\u00e3o Integral \u00e0 Sa\u00fade, da Secretaria de Estado de Sa\u00fade [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3031","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"A Maternidade Nossa Senhora de Lourdes, por meio de uma parceria entre os setores de Fisioterapia, Fonoaudiologia e Qualidade, promoveu na manh\u00e3 de hoje, 6 de junho (ter\u00e7a-feira), mais uma edi\u00e7\u00e3o do F\u00f3rum Perinatal goiano, um encontro mensal itinerante idealizado pela Superintend\u00eancia de Pol\u00edticas de Aten\u00e7\u00e3o Integral \u00e0 Sa\u00fade, da Secretaria de Estado de Sa\u00fade&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/3031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=3031"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/3031\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=3031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=3031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=3031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}