

{"id":288010,"date":"2025-03-17T07:44:37","date_gmt":"2025-03-17T10:44:37","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=288010"},"modified":"2025-03-17T07:44:37","modified_gmt":"2025-03-17T10:44:37","slug":"aviso-de-dispensa-eletronica-112667-contratacao-no-159-2025","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/aviso-de-dispensa-eletronica-112667-contratacao-no-159-2025\/","title":{"rendered":"Aviso de Dispensa Eletr\u00f4nica \u2013 112667 \u2013 Contrata\u00e7\u00e3o n\u00ba 159\/2025"},"content":{"rendered":"\n<p><strong>DISPENSA DE LICITA\u00c7\u00c3O &#8211; COM COTA\u00c7\u00c3O ELETR\u00d4NICA &#8211; C\u00f3digo\u00a0112667<br>CONTRATA\u00c7\u00c3O N\u00ba\u00a0159\/2025\u00a0&#8211;\u00a0SES<br>PROCESSO N\u00b0\u00a0202500005005043<\/strong><\/p>\n\n\n\n<p><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a><a><\/a> &nbsp;O Estado de Goi\u00e1s, por interm\u00e9dio do(a)&nbsp;<strong>SES &#8211; SECRETARIA DE ESTADO DA SA\u00daDE<\/strong>,<strong>&nbsp;<\/strong>torna p\u00fablico<strong>,&nbsp;<\/strong>para conhecimento dos interessados, que realizar\u00e1 contrata\u00e7\u00e3o direta por&nbsp;<strong>Dispensa Eletr\u00f4nica<\/strong>, tipo&nbsp;<strong>Menor Pre\u00e7o<\/strong>, processo de contrata\u00e7\u00e3o SISLOG n\u00ba&nbsp;<strong>112667\/2025<\/strong>&nbsp;e processo SEI n\u00ba&nbsp;<strong>202500005005043<\/strong>, nos termos da&nbsp;Lei 14.133\/2021, Art. 75, VIII&nbsp;e na forma do&nbsp;Decreto estadual n\u00ba 10.211, de 06 de fevereiro de 2023.<\/p>\n\n\n\n<p><a><\/a> Objeto:&nbsp;<strong>OZEMPIC\u00ae 1,34MG\/ML SOL INJ X 3 ML<\/strong><\/p>\n\n\n\n<p><a><\/a><a><\/a> Data e hor\u00e1rio de in\u00edcio da sess\u00e3o eletr\u00f4nica de lances:&nbsp;<strong>08:00<\/strong>&nbsp;(hor\u00e1rio de Bras\u00edlia-DF) do dia&nbsp;<strong>31\/03\/2025<\/strong><\/p>\n\n\n\n<p>Endere\u00e7o eletr\u00f4nico:<strong>&nbsp;<\/strong><a href=\"https:\/\/sislog.go.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.sislog.go.gov.br<\/a><\/p>\n\n\n\n<p><a><\/a> Tratamento Diferenciado para ME\/EPP:&nbsp;<strong>n\u00e3o exclusiva para ME\/EPP\/EQUIPARADAS<\/strong>.<\/p>\n\n\n\n<p>O fornecedor interessado em participar do certame dever\u00e1 ser previamente cadastrado no sistema oficial de cadastro de fornecedores do Estado e dever\u00e1 encaminhar, exclusivamente por meio do sistema eletr\u00f4nico, a proposta com a descri\u00e7\u00e3o do objeto e pre\u00e7o ofertado, at\u00e9 a data e hor\u00e1rio estabelecidos para in\u00edcio da sess\u00e3o eletr\u00f4nica de lances.<\/p>\n\n\n\n<p><a><\/a> Informa\u00e7\u00f5es acerca do cadastro de fornecedores,&nbsp;<a href=\"http:\/\/sei.go.gov.br\/sei\/documento_consulta_externa.php?id_acesso_externo=1427074&amp;id_documento=73944258&amp;infra_hash=3e075fd6e79ae7275d73bdf02cba704b\" target=\"_blank\" rel=\"noreferrer noopener\">TR &#8211; Termo de Refer\u00eancia<\/a>&nbsp;e demais documentos da contrata\u00e7\u00e3o encontram-se dispon\u00edveis nos sites:&nbsp;<a href=\"https:\/\/sislog.go.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.sislog.go.gov.br<\/a>.&nbsp;Maiores informa\u00e7\u00f5es pelo telefone:&nbsp;<strong>(62) 3201-3800<\/strong>&nbsp;e\/ou e-mail:&nbsp;<strong>alexandre.slima@goias.gov.br.<\/strong><\/p>\n\n\n\n<p>&nbsp;<strong>DA APROVA\u00c7\u00c3O DOS DOCUMENTOS PELA AUTORIDADE COMPETENTE<\/strong><\/p>\n\n\n\n<p>&nbsp;Nos termos do artigo 7\u00ba, inciso XII, do Decreto Estadual n\u00ba 10.207\/2023, fica autorizada pelo Ordenador de despesas a realiza\u00e7\u00e3o da presente contrata\u00e7\u00e3o e ficam aprovados o Estudo T\u00e9cnico Preliminar, o Termo de Refer\u00eancia e seus anexos.<\/p>\n\n\n\n<p>&nbsp; <strong>THALLES PAULINO DE \u00c1VILA<\/strong><\/p>\n\n\n\n<p>Superintendente de Gest\u00e3o Integrada<\/p>\n\n\n\n<p>Secretaria de Estado da Sa\u00fade<br>Delega\u00e7\u00e3o de Compet\u00eancia<\/p>\n\n\n\n<p><a href=\"https:\/\/diariooficial.abc.go.gov.br\/portal\/visualizacoes\/pdf\/6470\/#\/p:24\/e:6470\">Portaria n\u00ba 9, de 02 de janeiro de 2025<\/a><\/p>\n\n\n\n<p>&nbsp; GOI\u00c2NIA, aos 13 dias do m\u00eas de mar\u00e7o de 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DISPENSA DE LICITA\u00c7\u00c3O &#8211; COM COTA\u00c7\u00c3O ELETR\u00d4NICA &#8211; C\u00f3digo\u00a0112667CONTRATA\u00c7\u00c3O N\u00ba\u00a0159\/2025\u00a0&#8211;\u00a0SESPROCESSO N\u00b0\u00a0202500005005043 &nbsp;O Estado de Goi\u00e1s, por interm\u00e9dio do(a)&nbsp;SES &#8211; SECRETARIA DE ESTADO DA SA\u00daDE,&nbsp;torna p\u00fablico,&nbsp;para conhecimento dos interessados, que realizar\u00e1 contrata\u00e7\u00e3o direta por&nbsp;Dispensa Eletr\u00f4nica, tipo&nbsp;Menor Pre\u00e7o, processo de contrata\u00e7\u00e3o SISLOG n\u00ba&nbsp;112667\/2025&nbsp;e processo SEI n\u00ba&nbsp;202500005005043, nos termos da&nbsp;Lei 14.133\/2021, Art. 75, VIII&nbsp;e na forma do&nbsp;Decreto estadual [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[419],"tags":[],"class_list":["post-288010","post","type-post","status-publish","format-standard","hentry","category-dispensa-e-inexigibilidade-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ricardocruz","author_link":"https:\/\/goias.gov.br\/saude\/author\/ricardocruz\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/dispensa-e-inexigibilidade-2025\/\" rel=\"category tag\">Dispensa e Inexigibilidade 2025<\/a>","rttpg_excerpt":"DISPENSA DE LICITA\u00c7\u00c3O &#8211; COM COTA\u00c7\u00c3O ELETR\u00d4NICA &#8211; C\u00f3digo\u00a0112667CONTRATA\u00c7\u00c3O N\u00ba\u00a0159\/2025\u00a0&#8211;\u00a0SESPROCESSO N\u00b0\u00a0202500005005043 &nbsp;O Estado de Goi\u00e1s, por interm\u00e9dio do(a)&nbsp;SES &#8211; SECRETARIA DE ESTADO DA SA\u00daDE,&nbsp;torna p\u00fablico,&nbsp;para conhecimento dos interessados, que realizar\u00e1 contrata\u00e7\u00e3o direta por&nbsp;Dispensa Eletr\u00f4nica, tipo&nbsp;Menor Pre\u00e7o, processo de contrata\u00e7\u00e3o SISLOG n\u00ba&nbsp;112667\/2025&nbsp;e processo SEI n\u00ba&nbsp;202500005005043, nos termos da&nbsp;Lei 14.133\/2021, Art. 75, VIII&nbsp;e na forma do&nbsp;Decreto estadual&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/288010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=288010"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/288010\/revisions"}],"predecessor-version":[{"id":288021,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/288010\/revisions\/288021"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=288010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=288010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=288010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}