

{"id":2780,"date":"2017-08-12T05:55:37","date_gmt":"2017-08-12T08:55:37","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/saude-estadual-promove-servicos-e-orienta-jovens-em-projeto-do-estado\/"},"modified":"2017-08-12T05:55:37","modified_gmt":"2017-08-12T08:55:37","slug":"saude-estadual-promove-servicos-e-orienta-jovens-em-projeto-do-estado","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/saude-estadual-promove-servicos-e-orienta-jovens-em-projeto-do-estado\/","title":{"rendered":"Sa\u00fade estadual promove servi\u00e7os e orienta jovens em projeto do Estado"},"content":{"rendered":"<p>O Parque Flamboyant foi Palco neste s\u00e1bado, 12, da primeira a\u00e7\u00e3o de projeto para jovens da Capital, promovido por in\u00fameras secretarias e \u00f3rg\u00e3os estaduais, incluindo a Secretaria de Estado da Sa\u00fade.<br \/>\n<!--more--><\/p>\n<p><div dir=\"auto\">O Parque Flamboyant foi Palco neste s\u00e1bado, 12, da primeira a\u00e7\u00e3o de projeto para jovens da Capital, promovido por in\u00fameras secretarias e \u00f3rg\u00e3os estaduais, incluindo a Secretaria de Estado da Sa\u00fade. A a\u00e7\u00e3o, que aconteceu das 8h \u00e0s 17h, foi criada em lembran\u00e7a ao M\u00eas da Juventude, comemorado em agosto. No encontro foram ministradas palestras, rodas de conversa, \u00a0pr\u00e1tica de atividades esportivas e l\u00fadicas, aplica\u00e7\u00e3o de vacinas, orienta\u00e7\u00f5es sobre sa\u00fade e entrega de material educativo. As pr\u00f3ximas atividades acontecem no dia 19, no Arei\u00e3o e no dia 26, no Parque Itatiaia.<\/div>\n<\/p>\n<p><div dir=\"auto\"><\/div>\n<\/p>\n<p><div dir=\"auto\">No estande da SES, que foi organizado pela Superintend\u00eancia de Pol\u00edtica de Aten\u00e7\u00e3o Integral \u00e0 Sa\u00fade (Spais), foram oferecidas vacinas contra HPV, hepatite e meningoc\u00f3cica para a popula\u00e7\u00e3o alvo, com apresenta\u00e7\u00e3o do cart\u00e3o de vacina, entrega de Cadernetas do Adolescente, al\u00e9m de orienta\u00e7\u00f5es diversas. &#8220;A expectativa \u00e9 que a gente traga o jovem para a Sa\u00fade, tentando diminuir essa invisibilidade que esse p\u00fablico tem com a \u00e1rea da Sa\u00fade&#8221;, esclareceu Luciene Tavares, subcoordenadora da Sa\u00fade do Adolescente do Estado.<\/div>\n<\/p>\n<p><div dir=\"auto\"><\/div>\n<\/p>\n<p><div dir=\"auto\">Segundo ela, o jovem \u00e9 visto na sa\u00fade como paciente curativo. &#8220;\u00c9 preciso mudar essa realidade e trazer a preven\u00e7\u00e3o para esse p\u00fablico&#8221;, comentou. Entre os temas tratados est\u00e3o: sa\u00fade sexual e reprodutiva, \u00e1lcool e outras drogas, gravidez na adolesc\u00eancia, Doen\u00e7as Sexualmente Transmiss\u00edveis (DST), dentre outros assuntos. Nas rodas de conversa o jovem teve a oportunidade de conversar abertamente sobre esses temas.<\/div>\n<\/p>\n<p><div dir=\"auto\"><\/div>\n<\/p>\n<p><div dir=\"auto\">A vacina contra HPV foi disponibilizada no evento devido \u00e0 baixa procura esse ano. Meninas de 9 a 15 anos e meninos de 11 a 15 anos podem receber a vacina, que previne o c\u00e2ncer de colo de \u00fatero, por exemplo.<\/div>\n<\/p>\n<p><div dir=\"auto\"><\/div>\n<\/p>\n<p><div dir=\"auto\">A caixa Shirlei Aparecida da Silva estava acompanhando o filho no evento e revelou que o adolescente de 13 anos teve dificuldade de aceitar o pedido da m\u00e3e de procurar o estande da Sa\u00fade. &#8220;Tive que conversar muito para ele aceitar. O jovem tem dificuldade de procurar orienta\u00e7\u00f5es nesse sentido, o que \u00e9 uma pena, porque \u00e9 muito importante falar sobre temas como DST e receber vacinas para prevenir doen\u00e7as. O jovem precisa entender que mesmo nesta idade \u00e9 preciso se preocupar&#8221;, disse.<\/div>\n<\/p>\n<p><div dir=\"auto\"><\/div>\n<\/p>\n<p><div dir=\"auto\">O jovem Eliseu Barbosa, de 16 anos, procurou o local e lembrou que muitas doen\u00e7as na adolesc\u00eancia s\u00e3o consequ\u00eancias da falta de informa\u00e7\u00e3o. &#8220;Acho necess\u00e1rio que n\u00f3s, jovens, tenhamos mais alertas sobre esses temas&#8221;, disse.<\/div>\n<\/p>\n<p><div dir=\"auto\"><\/div>\n<\/p>\n<p><div dir=\"auto\"><strong>Organiza\u00e7\u00e3o\u00a0<\/strong><\/div>\n<\/p>\n<p><div dir=\"auto\">O projeto acontece em parceria com o Conselho Estadual de Juventude, Secretaria da Sa\u00fade e da Educa\u00e7\u00e3o, entre outros \u00f3rg\u00e3os e entidades.<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Parque Flamboyant foi Palco neste s\u00e1bado, 12, da primeira a\u00e7\u00e3o de projeto para jovens da Capital, promovido por in\u00fameras secretarias e \u00f3rg\u00e3os estaduais, incluindo a Secretaria de Estado da Sa\u00fade.<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2780","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"O Parque Flamboyant foi Palco neste s\u00e1bado, 12, da primeira a\u00e7\u00e3o de projeto para jovens da Capital, promovido por in\u00fameras secretarias e \u00f3rg\u00e3os estaduais, incluindo a Secretaria de Estado da Sa\u00fade.","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/2780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=2780"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/2780\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=2780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=2780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=2780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}