

{"id":27671,"date":"2022-03-31T07:06:27","date_gmt":"2022-03-31T10:06:27","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/aviso-de-adiamento-do-p-e-n-083-2022\/"},"modified":"2022-03-31T07:06:27","modified_gmt":"2022-03-31T10:06:27","slug":"aviso-de-adiamento-do-p-e-n-083-2022","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/aviso-de-adiamento-do-p-e-n-083-2022\/","title":{"rendered":"Aviso de Adiamento do P.E. n.\u00ba 083\/2022"},"content":{"rendered":"<p style=\"text-align: justify;\">A SECRETARIA DE ESTADO DA SA&Uacute;DE-SES\/GO, torna p&uacute;blico aos interessados, que a data do certame em quest&atilde;o, referente ao processo administrativo n&ordm; 202100010048853, cujo objeto &eacute; o Registro de pre&ccedil;o para eventuais aquisi&ccedil;&otilde;es de medicamentos, destinados ao Setor de Planejamento e Compras da Judicializa&ccedil;&atilde;o\/CMAC\/SCAGES\/SES, e demais &oacute;rg&atilde;os interessados, inicialmente marcada para o dia 01\/04\/2022 &agrave;s 09:00 h, fica adiada &ldquo;sine die&rdquo;. O adiamento se deve face a necessidade de maior prazo para responder a pedido de impugna&ccedil;&atilde;o. Demais informa&ccedil;&otilde;es encontram-se &agrave; disposi&ccedil;&atilde;o dos interessados na Ger&ecirc;ncia de Compras Governamentais da SES-GO e no site: www.comprasnet.go.gov.br.<\/p>\n<p>Goi&acirc;nia\/GO, 30 de mar&ccedil;o de 2022<\/p>\n<p>Natal de Castro<br \/>\nGerente da GCG\/SES<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A SECRETARIA DE ESTADO DA SA&Uacute;DE-SES\/GO, torna p&uacute;blico aos interessados, que a data do certame em quest&atilde;o, referente ao processo administrativo n&ordm; 202100010048853, cujo objeto &eacute; o Registro de pre&ccedil;o para eventuais aquisi&ccedil;&otilde;es de medicamentos, destinados ao Setor de Planejamento e Compras da Judicializa&ccedil;&atilde;o\/CMAC\/SCAGES\/SES, e demais &oacute;rg&atilde;os interessados, inicialmente marcada para o dia 01\/04\/2022 &agrave;s [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[],"class_list":["post-27671","post","type-post","status-publish","format-standard","hentry","category-pregao-eletronico-2022"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/saude\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/pregao-eletronico-2022\/\" rel=\"category tag\">Preg\u00e3o Eletr\u00f4nico 2022<\/a>","rttpg_excerpt":"A SECRETARIA DE ESTADO DA SA&Uacute;DE-SES\/GO, torna p&uacute;blico aos interessados, que a data do certame em quest&atilde;o, referente ao processo administrativo n&ordm; 202100010048853, cujo objeto &eacute; o Registro de pre&ccedil;o para eventuais aquisi&ccedil;&otilde;es de medicamentos, destinados ao Setor de Planejamento e Compras da Judicializa&ccedil;&atilde;o\/CMAC\/SCAGES\/SES, e demais &oacute;rg&atilde;os interessados, inicialmente marcada para o dia 01\/04\/2022 &agrave;s&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/27671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=27671"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/27671\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=27671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=27671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=27671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}