{"id":269716,"date":"2025-02-25T16:34:53","date_gmt":"2025-02-25T19:34:53","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=269716"},"modified":"2025-02-25T16:34:53","modified_gmt":"2025-02-25T19:34:53","slug":"extrato-do-contrato-no-16-2025-ses-go","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-do-contrato-no-16-2025-ses-go\/","title":{"rendered":"Extrato do Contrato n\u00ba 16\/2025 \u2013 SES\/GO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Processo n\u00ba: 202500010012667, vinculado ao de n\u00ba 202400005006665. Contratante: Estado de Goi\u00e1s, por interm\u00e9dio da Secretaria de Estado da Sa\u00fade. Contratado: Benzer Tecnologia LTDA. Objeto: C\u00e2mara Refrigerada Volume aproximado 2000 litros \u00fateis, quantidade 02 (duas), conforme especifica\u00e7\u00f5es e quantitativos estabelecidos no Termo de Refer\u00eancia e na Proposta de Pre\u00e7os. Valor do contrato: R$ 55.997,98. Dota\u00e7\u00e3o Or\u00e7ament\u00e1ria: 2850.10.305.1043.2512.04.26010233.90. Vig\u00eancia: A vig\u00eancia do Contrato ser\u00e1 de 12 (doze) meses, a partir da data da assinatura. Data da Assinatura: 25\/02\/2025. Signat\u00e1rios: Ras\u00edvel dos Reis Santos J\u00fanior \u2013 Secret\u00e1rio de Estado da Sa\u00fade; Isabel Regina Tararam Busato \u2013 Benzer Tecnologia LTDA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Processo n\u00ba: 202500010012667, vinculado ao de n\u00ba 202400005006665. Contratante: Estado de Goi\u00e1s, por interm\u00e9dio da Secretaria de Estado da Sa\u00fade. Contratado: Benzer Tecnologia LTDA. Objeto: C\u00e2mara Refrigerada Volume aproximado 2000 litros \u00fateis, quantidade 02 (duas), conforme especifica\u00e7\u00f5es e quantitativos estabelecidos no Termo de Refer\u00eancia e na Proposta de Pre\u00e7os. Valor do contrato: R$ 55.997,98. Dota\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[421],"tags":[],"class_list":["post-269716","post","type-post","status-publish","format-standard","hentry","category-contratos-e-termos-aditivos-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/contratos-e-termos-aditivos-2025\/\" rel=\"category tag\">Contratos e Termos Aditivos 2025<\/a>","rttpg_excerpt":"Processo n\u00ba: 202500010012667, vinculado ao de n\u00ba 202400005006665. Contratante: Estado de Goi\u00e1s, por interm\u00e9dio da Secretaria de Estado da Sa\u00fade. Contratado: Benzer Tecnologia LTDA. Objeto: C\u00e2mara Refrigerada Volume aproximado 2000 litros \u00fateis, quantidade 02 (duas), conforme especifica\u00e7\u00f5es e quantitativos estabelecidos no Termo de Refer\u00eancia e na Proposta de Pre\u00e7os. Valor do contrato: R$ 55.997,98. Dota\u00e7\u00e3o&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/269716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=269716"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/269716\/revisions"}],"predecessor-version":[{"id":269735,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/269716\/revisions\/269735"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=269716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=269716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=269716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}