{"id":223313,"date":"2025-01-23T16:26:40","date_gmt":"2025-01-23T19:26:40","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=223313"},"modified":"2025-01-23T16:26:40","modified_gmt":"2025-01-23T19:26:40","slug":"extrato-do-12o-apostilamento-ao-contrato-de-gestao-no-94-2023-ses-go-hslmb","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-do-12o-apostilamento-ao-contrato-de-gestao-no-94-2023-ses-go-hslmb\/","title":{"rendered":"Extrato do 12\u00ba Apostilamento ao Contrato de Gest\u00e3o n\u00ba 94\/2023 \u2013 SES\/GO (HSLMB)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Processo n\u00ba: 202500010002031. Parceiro P\u00fablico: Estado de Goi\u00e1s \u2013 Secretaria de Estado da Sa\u00fade. Parceiro Privado: Funda\u00e7\u00e3o Universit\u00e1ria Evang\u00e9lica &#8211; FUNEV. Objeto: Repasse referente assist\u00eancia financeira complementar da Uni\u00e3o (Piso de Enfermagem). Valor: R$ 142.021,92. Data da assinatura da Apostila: 22\/01\/2025. Signat\u00e1rio: Ras\u00edvel dos Reis Santos J\u00fanior \u2013 Secret\u00e1rio de Estado da Sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Processo n\u00ba: 202500010002031. Parceiro P\u00fablico: Estado de Goi\u00e1s \u2013 Secretaria de Estado da Sa\u00fade. Parceiro Privado: Funda\u00e7\u00e3o Universit\u00e1ria Evang\u00e9lica &#8211; FUNEV. Objeto: Repasse referente assist\u00eancia financeira complementar da Uni\u00e3o (Piso de Enfermagem). Valor: R$ 142.021,92. Data da assinatura da Apostila: 22\/01\/2025. Signat\u00e1rio: Ras\u00edvel dos Reis Santos J\u00fanior \u2013 Secret\u00e1rio de Estado da Sa\u00fade.<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[421],"tags":[],"class_list":["post-223313","post","type-post","status-publish","format-standard","hentry","category-contratos-e-termos-aditivos-2025"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/contratos-e-termos-aditivos-2025\/\" rel=\"category tag\">Contratos e Termos Aditivos 2025<\/a>","rttpg_excerpt":"Processo n\u00ba: 202500010002031. Parceiro P\u00fablico: Estado de Goi\u00e1s \u2013 Secretaria de Estado da Sa\u00fade. Parceiro Privado: Funda\u00e7\u00e3o Universit\u00e1ria Evang\u00e9lica &#8211; FUNEV. Objeto: Repasse referente assist\u00eancia financeira complementar da Uni\u00e3o (Piso de Enfermagem). Valor: R$ 142.021,92. Data da assinatura da Apostila: 22\/01\/2025. Signat\u00e1rio: Ras\u00edvel dos Reis Santos J\u00fanior \u2013 Secret\u00e1rio de Estado da Sa\u00fade.","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/223313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=223313"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/223313\/revisions"}],"predecessor-version":[{"id":223337,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/223313\/revisions\/223337"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=223313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=223313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=223313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}