

{"id":20728,"date":"2020-07-07T17:21:21","date_gmt":"2020-07-07T20:21:21","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/hugol-homenageia-colaboradores-no-cafe-com-elogios-virtual\/"},"modified":"2020-07-07T17:21:21","modified_gmt":"2020-07-07T20:21:21","slug":"hugol-homenageia-colaboradores-no-cafe-com-elogios-virtual","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/hugol-homenageia-colaboradores-no-cafe-com-elogios-virtual\/","title":{"rendered":"Hugol homenageia colaboradores no Caf\u00e9 com Elogios virtual"},"content":{"rendered":"<p>Profissionais da unidade do Governo de Goi&aacute;s s&atilde;o&nbsp;elogiados por usu&aacute;rios&nbsp;em registros no Servi&ccedil;o de Atendimento ao Usu&aacute;rio\/Ouvidoria<\/p>\n<p><!--more--><\/p>\n<figure class=\"image\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-20727\" alt=\"\" id=\"\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolINTERNA-83a.jpg\" style=\"\" title=\"\" width=\"1920\" height=\"1281\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolINTERNA-83a.jpg 1920w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolINTERNA-83a-300x200.jpg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolINTERNA-83a-1024x683.jpg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolINTERNA-83a-768x512.jpg 768w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolINTERNA-83a-1536x1025.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"text-center\"><em>Evento deste ano, realizado por meio de &lsquo;live&rsquo; no YouTube, &eacute; transmitida aos profissionais da unidade<\/em><\/figcaption><\/figure>\n<p>O Hospital Estadual de Urg&ecirc;ncias da Regi&atilde;o Noroeste de Goi&acirc;nia Governador Ot&aacute;vio Lage de Siqueira (Hugol), unidade do Governo de Goi&aacute;s, realiza desde 2016 o Caf&eacute; com Elogios, evento com o objetivo de valorizar os colaboradores do hospital elogiados pelos usu&aacute;rios em registros no Servi&ccedil;o de Atendimento ao Usu&aacute;rio\/Ouvidoria. Para que o evento continue de forma segura, homenageando os profissionais, ele foi empreendido em formato virtual, em uma &lsquo;live&rsquo; no YouTube e transmitida aos profissionais. Nesta edi&ccedil;&atilde;o 269 pessoas foram elogiadas.<\/p>\n<p>&ldquo;Essa &eacute; a forma que identificamos no Hugol para criar um ciclo virtuoso de gratid&atilde;o. As belas palavras de reconhecimento que os usu&aacute;rios concedem a cada profissional possibilitam o refor&ccedil;o do bom atendimento prestado, ocasionando em mais satisfa&ccedil;&atilde;o em quem trabalha e um melhor atendimento para quem &eacute; assistido&rdquo;, declarou H&eacute;lio Ponciano Trevenzol, diretor- geral da unidade.<\/p>\n<p>A ouvidora do Hugol, Viviane Oliveira, comentou sobre o evento e o formato em que foi realizada essa edi&ccedil;&atilde;o: &ldquo;Chegamos a 18&ordf; edi&ccedil;&atilde;o do Caf&eacute; com Elogios e n&atilde;o poder&iacute;amos estar mais satisfeitos com esse evento, que traz alegria, paz e for&ccedil;a para seguirmos com o nosso objetivo de salvar vidas com amor. Esse formato digital vem de encontro com um dos nossos valores, que &eacute; a inova&ccedil;&atilde;o, nos permitindo levar, nesse momento em que evitamos aglomera&ccedil;&otilde;es, o carinho dos usu&aacute;rios aos colaboradores atrav&eacute;s desses elogios&rdquo;.<\/p>\n<p><strong>Meio de avalia&ccedil;&atilde;o<\/strong><br \/>\nA Ouvidoria da unidade recebe os registros dos usu&aacute;rios sobre os servi&ccedil;os prestados como um meio de avalia&ccedil;&atilde;o, auxiliando nas tomadas de decis&otilde;es para poss&iacute;veis melhorias e adequa&ccedil;&otilde;es de processos, pessoas e estruturas. Entre esses registros, tamb&eacute;m existem os que enfocam no agradecimento &agrave; unidade e a equipes e colaboradores em espec&iacute;fico, opini&otilde;es que resultam nos &ldquo;cart&otilde;es elogio&rdquo; entregues no evento trimestral.<\/p>\n<p>Jos&eacute; Ferreira Neto (texto) e Edson Freitas (fotos)\/Agir<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profissionais da unidade do Governo de Goi&aacute;s s&atilde;o&nbsp;elogiados por usu&aacute;rios&nbsp;em registros no Servi&ccedil;o de Atendimento ao Usu&aacute;rio\/Ouvidoria<\/p>\n","protected":false},"author":694,"featured_media":20726,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-20728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolABRE-ee8.jpg",1920,1281,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolABRE-ee8.jpg",1920,1281,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolABRE-ee8.jpg",1920,1281,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolABRE-ee8-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolABRE-ee8-300x200.jpg",300,200,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolABRE-ee8-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolABRE-ee8-1536x1025.jpg",1536,1025,true],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/07\/0707-HugolABRE-ee8.jpg",1920,1281,false]},"rttpg_author":{"display_name":"fabiomachado","author_link":"https:\/\/goias.gov.br\/saude\/author\/fabiomachado\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Profissionais da unidade do Governo de Goi&aacute;s s&atilde;o&nbsp;elogiados por usu&aacute;rios&nbsp;em registros no Servi&ccedil;o de Atendimento ao Usu&aacute;rio\/Ouvidoria","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/20728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/694"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=20728"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/20728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/20726"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=20728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=20728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=20728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}