

{"id":20636,"date":"2020-06-24T11:06:30","date_gmt":"2020-06-24T14:06:30","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/hgg-apresenta-zabumba-beach-no-sarau-virtual-junino\/"},"modified":"2020-06-24T11:06:30","modified_gmt":"2020-06-24T14:06:30","slug":"hgg-apresenta-zabumba-beach-no-sarau-virtual-junino","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/hgg-apresenta-zabumba-beach-no-sarau-virtual-junino\/","title":{"rendered":"HGG apresenta Zabumba Beach no Sarau Virtual junino\u00a0"},"content":{"rendered":"<p>Apresenta&ccedil;&atilde;o desta quinta-feira faz parte das a&ccedil;&otilde;es em comemora&ccedil;&atilde;o &agrave;s festas de S&atilde;o Jo&atilde;o da unidade do Governo de Goi&aacute;s<\/p>\n<p><!--more--><\/p>\n<figure class=\"image\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-20635\" alt=\"\" id=\"\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZabumbaBeach-ed0.jpeg\" style=\"\" title=\"\" width=\"854\" height=\"620\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZabumbaBeach-ed0.jpeg 854w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZabumbaBeach-ed0-300x218.jpeg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZabumbaBeach-ed0-768x558.jpeg 768w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/><figcaption class=\"text-center\"><em>A banda &eacute; formada por Jader Couteiro (percuss&atilde;o), Gustavo Pompeu (vocal) e Mestre Non&ocirc; (acordeom)<\/em><\/figcaption><\/figure>\n<p>&quot;Este ano n&atilde;o tem arrai&aacute; no HGG&#8230; mas &eacute; mentira!&quot; N&atilde;o teve jeito, n&atilde;o poder&iacute;amos deixar que as festas juninas passassem em branco no Hospital Estadual Alberto Rassi (HGG). Nesta quinta-feira, 25, podem anotar na agenda, tem Sarau Virtual junino com a banda Zabumba Beach, a partir das 17 horas, no HGG.<\/p>\n<p>Com 20 anos de hist&oacute;ria, a banda tem na atual forma&ccedil;&atilde;o Jader Couteiro na percuss&atilde;o, Mestre Non&ocirc; no acordeom e no vocal Gustavo Pompeu. O grupo se apresentou pela primeira vez no hospital em 2017 e, de l&aacute; para c&aacute;, n&atilde;o parou mais.&nbsp;<\/p>\n<p>&quot;Mantemos uma parceria s&oacute;lida porque nos faz bem cantar para os pacientes do HGG. &Eacute; uma forma de levar alegria para quem precisa tanto dela em um momento dif&iacute;cil&quot;, afirma Jader. Para o sarau junino, a banda separou cl&aacute;ssicos como Xote do Zabumba, Tempo Perdido, Anuncia&ccedil;&atilde;o e Ainda Ontem Chorei de Saudade, para animar os pacientes.<\/p>\n<p>E t&aacute; pensando que &eacute; s&oacute; isso? N&atilde;o &eacute; n&atilde;o. A Quadrilha Arriba Saia, que h&aacute; cinco anos encanta pacientes e colaboradores do HGG com apresenta&ccedil;&otilde;es juninas, tamb&eacute;m fez quest&atilde;o de participar das comemora&ccedil;&otilde;es de S&atilde;o Jo&atilde;o. O grupo preparou um v&iacute;deo para pacientes terem uma quadrilha virtual tamb&eacute;m.&nbsp;<\/p>\n<p><strong>Comidas t&iacute;picas<\/strong><br \/>\nMas ainda est&aacute; faltando alguma coisa nesse arrai&aacute;, n&atilde;o t&aacute;, n&atilde;o? Cad&ecirc; as comidas t&iacute;picas, gente? Nossa equipe da nutri&ccedil;&atilde;o preparou um card&aacute;pio mais que especial para essa data. Do caf&eacute; da manh&atilde; ao jantar, tem man&eacute; pelado, amendoim torrado, leite caramelado, pipoca, broa, canjica, chica doida, claro, tudo conforme a dieta de cada paciente.<\/p>\n<p>E, para matar a saudade de quando a gente podia se abra&ccedil;ar, dan&ccedil;ar quadrilha e tirar muitas fotos, no hall de entrada do hospital estar&aacute; dispon&iacute;vel uma exposi&ccedil;&atilde;o de fotografias das festas juninas dos &uacute;ltimos cincos anos.<\/p>\n<p>SERVI&Ccedil;O<br \/>\nSarau Virtual Junino do HGG com a Banda Zabumba Beach e Quadrilha Arriba Saia<br \/>\nData: quinta-feira, 25<br \/>\nHor&aacute;rio: 17 horas<\/p>\n<p>&nbsp;<\/p>\n<p>Thalita Braga\/Idtech<br \/>\nFoto: divulga&ccedil;&atilde;o&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apresenta&ccedil;&atilde;o desta quinta-feira faz parte das a&ccedil;&otilde;es em comemora&ccedil;&atilde;o &agrave;s festas de S&atilde;o Jo&atilde;o da unidade do Governo de Goi&aacute;s<\/p>\n","protected":false},"author":694,"featured_media":20634,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-20636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZABUMBA-ABRE-af6.jpeg",1280,731,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZABUMBA-ABRE-af6.jpeg",1280,731,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZABUMBA-ABRE-af6.jpeg",1280,731,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZABUMBA-ABRE-af6-150x150.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZABUMBA-ABRE-af6-300x171.jpeg",300,171,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZABUMBA-ABRE-af6-1024x585.jpeg",1024,585,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZABUMBA-ABRE-af6.jpeg",1280,731,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2020\/06\/2406-ZABUMBA-ABRE-af6.jpeg",1280,731,false]},"rttpg_author":{"display_name":"fabiomachado","author_link":"https:\/\/goias.gov.br\/saude\/author\/fabiomachado\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Apresenta&ccedil;&atilde;o desta quinta-feira faz parte das a&ccedil;&otilde;es em comemora&ccedil;&atilde;o &agrave;s festas de S&atilde;o Jo&atilde;o da unidade do Governo de Goi&aacute;s","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/20636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/694"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=20636"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/20636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/20634"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=20636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=20636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=20636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}