

{"id":18647,"date":"2020-01-14T09:35:02","date_gmt":"2020-01-14T12:35:02","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/vacina-pentavalente-comeca-a-ser-distribuida-em-goias\/"},"modified":"2020-01-14T09:35:02","modified_gmt":"2020-01-14T12:35:02","slug":"vacina-pentavalente-comeca-a-ser-distribuida-em-goias","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/vacina-pentavalente-comeca-a-ser-distribuida-em-goias\/","title":{"rendered":"Vacina pentavalente come\u00e7a a ser distribu\u00edda em Goi\u00e1s"},"content":{"rendered":"<p><em><i>P<\/i><\/em><em><i>revis\u00e3o \u00e9 que at\u00e9 24 de janeiro todos os munic\u00edpios <\/i><\/em><em><i>do Estado <\/i><\/em><em><i>j\u00e1 estejam abastecidos<\/i><\/em><em><i>\u00a0com as 29 mil doses recebidas pela SES<\/i><\/em><\/p>\n<p>A Secretaria de Estado da Sa\u00fade de Goi\u00e1s (SES-GO) recebeu 29\u00a0mil doses da vacina pentavalente,\u00a0na semana\u00a0passada. A distribui\u00e7\u00e3o teve in\u00edcio pelas Regionais Central e Centro-Sul e pelos munic\u00edpios de Goi\u00e2nia e Aparecida de Goi\u00e2nia, que receberam, respectivamente, 6,5\u00a0mil e 2,3\u00a0mil doses. A previs\u00e3o \u00e9 que at\u00e9 sexta-feira, 17,\u00a0todas as 18 Regionais de Sa\u00fade do Estado j\u00e1 estejam abastecidas,\u00a0para iniciarem a distribui\u00e7\u00e3o aos munic\u00edpios.<\/p>\n<p>De acordo com a superintendente de Vigil\u00e2ncia em Sa\u00fade da SES-GO, Fl\u00favia Amorim, &#8220;a expectativa \u00e9 que at\u00e9 24 de janeiro todas as cidades goianas j\u00e1 tenham as doses dispon\u00edveis nos postos de sa\u00fade,\u00a0para atendimento da popula\u00e7\u00e3o&#8221;. Ela destaca ainda que a orienta\u00e7\u00e3o \u00e9 que os munic\u00edpios regularizem a caderneta de vacina\u00e7\u00e3o das crian\u00e7as assim que os estoques estiverem normalizados. Entre junho e dezembro de 2019, a oferta da pentavalente esteve irregular devido a problemas do Minist\u00e9rio da Sa\u00fade para aquisi\u00e7\u00e3o da vacina.<\/p>\n<p>A pentavalente\u00a0\u00e9 a combina\u00e7\u00e3o de cinco vacinas individuais em uma, garantindo\u00a0a prote\u00e7\u00e3o contra difteria, t\u00e9tano, coqueluche, hepatite B e contra a bact\u00e9ria <em><i>H<\/i><\/em><em><i>aemophilus influenza <\/i><\/em>tipo b, respons\u00e1vel por infec\u00e7\u00f5es no nariz, na meninge e garganta.\u00a0A vacina \u00e9 aplicada nas crian\u00e7as aos 2, 4 e 6 meses de idade.<\/p>\n<p>Os refor\u00e7os e complementa\u00e7\u00f5es s\u00e3o feitos em crian\u00e7as a partir de 1 ano com a vacina adsorvida difteria, t\u00e9tano e pert\u00fassis\/coqueluche (DTP). Goi\u00e1s j\u00e1 foi reabastecido com doses da DTP, que tamb\u00e9m apresentou irregularidades na distribui\u00e7\u00e3o no ano passado.<\/p>\n<p><strong><b>Log\u00edstica<\/p>\n<p><\/b><\/strong>No Brasil, a responsabilidade do Programa Nacional de Imuniza\u00e7\u00f5es (PNI), que trata da vacina\u00e7\u00e3o dos cidad\u00e3os, \u00e9 compartilhada entre o Governo Federal (por meio do Minist\u00e9rio da Sa\u00fade), os Estados e os munic\u00edpios, por meio das respectivas Secretarias de Sa\u00fade. O respons\u00e1vel pela produ\u00e7\u00e3o ou compra e distribui\u00e7\u00e3o das vacinas utilizadas no PNI para todos os Estados \u00e9 o Minist\u00e9rio da Sa\u00fade.<\/p>\n<p>Os Estados, ao receberem as doses do Minist\u00e9rio da Sa\u00fade, se encarregam de distribuir, de acordo com a estimativa populacional, as vacinas para os munic\u00edpios. Por fim, as prefeituras se encarregam de vacinar a popula\u00e7\u00e3o,\u00a0nos postos de sa\u00fade. O objetivo \u00e9 uma atua\u00e7\u00e3o conjunta,\u00a0para que a popula\u00e7\u00e3o fique protegida contra doen\u00e7as.<\/p>\n<p>Desde 2012, o PNI, do Minist\u00e9rio da Sa\u00fade, oferta a vacina pentavalente na rotina do Calend\u00e1rio Nacional de Vacina\u00e7\u00e3o.\u00a0As crian\u00e7as devem ser vacinadas com tr\u00eas doses da vacina: aos 2, aos 4 e aos 6 meses de vida. Segundo o site do Minist\u00e9rio da Sa\u00fade, para ofertar a pentavalente no calend\u00e1rio de vacina\u00e7\u00e3o do SUS, o Brasil compra a vacina via Fundo Estrat\u00e9gico da Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade (Opas), uma vez que n\u00e3o existe laborat\u00f3rio produtor no Pa\u00eds.<\/p>\n<p>Em julho de 2019, lotes do laborat\u00f3rio pr\u00e9-qualificado pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) foram reprovados no teste de qualidade do Instituto Nacional de Controle de Qualidade em Sa\u00fade (INCQS) e an\u00e1lise da Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa). Em agosto do ano passado, o Minist\u00e9rio da Sa\u00fade solicitou reposi\u00e7\u00e3o do produto, mas, naquele momento, n\u00e3o havia disponibilidade imediata no mundo.<\/p>\n<p><em>Pedro Ferreira\/Comunica\u00e7\u00e3o Setorial<\/em><\/p>\n<p><em><strong>Foto: <\/strong>Marcelo Camargo\/Ag\u00eancia Brasil<i><\/p>\n<p><\/i><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o \u00e9 que at\u00e9 24 de janeiro todos os munic\u00edpios do Estado j\u00e1 estejam abastecidos\u00a0com as 29 mil doses recebidas pela SES A Secretaria de Estado da Sa\u00fade de Goi\u00e1s (SES-GO) recebeu 29\u00a0mil doses da vacina pentavalente,\u00a0na semana\u00a0passada. A distribui\u00e7\u00e3o teve in\u00edcio pelas Regionais Central e Centro-Sul e pelos munic\u00edpios de Goi\u00e2nia e Aparecida de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-18647","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/saude\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Previs\u00e3o \u00e9 que at\u00e9 24 de janeiro todos os munic\u00edpios do Estado j\u00e1 estejam abastecidos\u00a0com as 29 mil doses recebidas pela SES A Secretaria de Estado da Sa\u00fade de Goi\u00e1s (SES-GO) recebeu 29\u00a0mil doses da vacina pentavalente,\u00a0na semana\u00a0passada. A distribui\u00e7\u00e3o teve in\u00edcio pelas Regionais Central e Centro-Sul e pelos munic\u00edpios de Goi\u00e2nia e Aparecida de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/18647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=18647"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/18647\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=18647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=18647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=18647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}