{"id":115200,"date":"2024-09-13T09:31:28","date_gmt":"2024-09-13T12:31:28","guid":{"rendered":"https:\/\/goias.gov.br\/saude\/?p=115200"},"modified":"2024-09-13T09:31:28","modified_gmt":"2024-09-13T12:31:28","slug":"extrato-do-5o-termo-aditivo-ao-contrato-de-gestao-n-o-37-2019-ses-go-hetrin","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/extrato-do-5o-termo-aditivo-ao-contrato-de-gestao-n-o-37-2019-ses-go-hetrin\/","title":{"rendered":"Extrato do 5\u00ba Termo Aditivo ao Contrato de Gest\u00e3o n.\u00ba 37\/2019 \u2013 SES\/GO (Hetrin)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Processo n\u00ba 202400010053312, vinculado ao processo original de n\u00ba 201900010008727. Parceiro P\u00fablico: Estado de Goi\u00e1s \u2013 Secretaria de Estado da Sa\u00fade. Parceiro Privado: IMED &#8211; Instituto de Medicina, Estudos e Desenvolvimento. Objeto: Constitui objeto do presente termo aditivo a efetiva\u00e7\u00e3o de procedimentos cir\u00fargicos do programa &#8220;Fila Zero de Cirurgias&#8221;. Vig\u00eancia: Os procedimentos relativos ao presente Termo Aditivo dever\u00e3o ser executados em conformidade com os Anexos T\u00e9cnicos. Valor: R$ 2.000.000,00. Dota\u00e7\u00e3o Or\u00e7ament\u00e1ria: 2850.10.302.1043.2516.03.16000232.50. Signat\u00e1rios: Ras\u00edvel dos Reis Santos J\u00fanior \u2013 Secret\u00e1rio de Estado da Sa\u00fade. Andr\u00e9 Fonseca Leme \u2013 IMED.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Processo n\u00ba 202400010053312, vinculado ao processo original de n\u00ba 201900010008727. Parceiro P\u00fablico: Estado de Goi\u00e1s \u2013 Secretaria de Estado da Sa\u00fade. Parceiro Privado: IMED &#8211; Instituto de Medicina, Estudos e Desenvolvimento. Objeto: Constitui objeto do presente termo aditivo a efetiva\u00e7\u00e3o de procedimentos cir\u00fargicos do programa &#8220;Fila Zero de Cirurgias&#8221;. Vig\u00eancia: Os procedimentos relativos ao presente [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[266],"tags":[],"class_list":["post-115200","post","type-post","status-publish","format-standard","hentry","category-contratos-e-termos-aditivos-2024"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"isabelamelo","author_link":"https:\/\/goias.gov.br\/saude\/author\/isabelamelo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/prestacao-de-contas\/licitacoes\/contratos-e-termos-aditivos-2024\/\" rel=\"category tag\">Contratos e Termos Aditivos 2024<\/a>","rttpg_excerpt":"Processo n\u00ba 202400010053312, vinculado ao processo original de n\u00ba 201900010008727. Parceiro P\u00fablico: Estado de Goi\u00e1s \u2013 Secretaria de Estado da Sa\u00fade. Parceiro Privado: IMED &#8211; Instituto de Medicina, Estudos e Desenvolvimento. Objeto: Constitui objeto do presente termo aditivo a efetiva\u00e7\u00e3o de procedimentos cir\u00fargicos do programa &#8220;Fila Zero de Cirurgias&#8221;. Vig\u00eancia: Os procedimentos relativos ao presente&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/115200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=115200"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/115200\/revisions"}],"predecessor-version":[{"id":115211,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/115200\/revisions\/115211"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=115200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=115200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=115200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}