{"id":10041,"date":"2017-03-20T10:03:44","date_gmt":"2017-03-20T13:03:44","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/presidente-do-ces-go-visita-materno-infantil-e-cobra-providencias\/"},"modified":"2017-03-20T10:03:44","modified_gmt":"2017-03-20T13:03:44","slug":"presidente-do-ces-go-visita-materno-infantil-e-cobra-providencias","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/saude\/presidente-do-ces-go-visita-materno-infantil-e-cobra-providencias\/","title":{"rendered":"Presidente do CES-GO visita Materno Infantil e cobra providencias"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-10040\" src=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597.jpeg\" alt=\"\" width=\"1040\" height=\"585\" srcset=\"https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597.jpeg 1040w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597-300x169.jpeg 300w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597-1024x576.jpeg 1024w, https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597-768x432.jpeg 768w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"https:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p>O presidente do Conselho de Sa&uacute;de de Goi&aacute;s (CES-GO ) , advogado Liorcino Mendes manifestou hoje (20 ) sua indigna&ccedil;&atilde;o com a morte de dois rec&eacute;m-nascidos no Hospital Materno Infantil (HMI), em Goi&acirc;nia, ap&oacute;s serem infectados pela superbact&eacute;ria Klebsiella pneumoniae Carbapenemase (KPC). Para o Conselheiro &eacute; inaceit&aacute;vel que a Unidade de Terapia Intensiva (UTI ) neonatal do hospital funcione com n&uacute;mero maior de sua capacidade. Liorcino j&aacute; oficiou ao Secret&aacute;rio Estadual de Sa&uacute;de (SES) , Leonardo Moura Vilela para que apresente na pr&oacute;xima assembl&eacute;ia do CES-GO, no dia 4 de abril, um relat&oacute;rio detalhado da situa&ccedil;&atilde;o e das medidas medidas de corre&ccedil;&atilde;o tomadas pela SES .<\/p>\n<p>O presidente do CES-GO lembra que de 27 a 29 de Setembro de 2017 ser&aacute; realizada a Conferencia Estadual da Vigil&acirc;ncia em Sa&uacute;de com delegados de usu&aacute;rios, trabalhadores, gestores e prestadores de servi&ccedil;os de todos munic&iacute;pios de Goi&aacute;s e que este tema vai estar em pauta. &Eacute; importante que a Gest&atilde;o estadual verifique se a Comiss&atilde;o de Controle de Infec&ccedil;&atilde;o Hospitalar (CCIH) do HMI est&aacute; funcionando com exames bacteriol&oacute;gicos per&iacute;odicos, acompanhamento de uso de antibi&oacute;ticos, se est&aacute; funcionando, se est&aacute; reunindo e se est&aacute; com os membros necess&aacute;rios. &Eacute; preciso acompanhar os relat&oacute;rios da Comiss&atilde;o . A presidencia do CES ir&aacute; ao HMI com uma comiss&atilde;o de conselheiros para averiguar se h&aacute; irregularidades e caso de positivo o Minist&eacute;rio P&uacute;blico dever&aacute; ser acionado.<\/p>\n<p>Segundo comunicado do Hospital os dois rec&eacute;m &ndash;nascidos estavam internados na Unidade de Cuidados Intermedi&aacute;rios Neonatal (Ucin), que foi isolada na &uacute;ltima sexta-feira (17) e n&atilde;o est&aacute; recebendo novos pacientes. N&atilde;o foram informadas as datas dos &oacute;bitos.O HMI destaca que investiga a situa&ccedil;&atilde;o de outros quatro rec&eacute;m-nascidos onde h&aacute; a suspeita de infec&ccedil;&atilde;o. Dois deles est&atilde;o internados na Ucin e outros dois na Unidade de Terapia Intensiva (UTI) Neonatal do hospital.<br \/> Transmitida em ambiente hospitalar, a KPC pode causar infec&ccedil;&otilde;es sangu&iacute;neas, urin&aacute;rias e generalizada, al&eacute;m de pneumonia. Os sintomas s&atilde;o febre, dor no corpo e dor na bexiga. Segundo a assessoria de imprensa do HMI a previs&atilde;o &eacute; que a Ucin permane&ccedil;a isolada at&eacute; quarta-feira (22).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span>Jornalista: Liorcino Mendes<\/span><\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente do Conselho de Sa&uacute;de de Goi&aacute;s (CES-GO ) , advogado Liorcino Mendes manifestou hoje (20 ) sua indigna&ccedil;&atilde;o com a morte de dois rec&eacute;m-nascidos no Hospital Materno Infantil (HMI), em Goi&acirc;nia, ap&oacute;s serem infectados pela superbact&eacute;ria Klebsiella pneumoniae Carbapenemase (KPC). Para o Conselheiro &eacute; inaceit&aacute;vel que a Unidade de Terapia Intensiva (UTI ) [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":10040,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-10041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-conselho"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597.jpeg",1040,585,false],"landscape":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597.jpeg",1040,585,false],"portraits":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597.jpeg",1040,585,false],"thumbnail":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597-150x150.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597-300x169.jpeg",300,169,true],"large":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597-1024x576.jpeg",1024,576,true],"1536x1536":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597.jpeg",1040,585,false],"2048x2048":["https:\/\/goias.gov.br\/saude\/wp-content\/uploads\/sites\/34\/2017\/03\/visita-ao-hmi1-597.jpeg",1040,585,false]},"rttpg_author":{"display_name":"cleybetsls","author_link":"https:\/\/goias.gov.br\/saude\/author\/cleybetsls\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/saude\/categoria\/conselho-estadual-de-saude\/noticias-conselho\/\" rel=\"category tag\">Not\u00edcias Conselho<\/a>","rttpg_excerpt":"O presidente do Conselho de Sa&uacute;de de Goi&aacute;s (CES-GO ) , advogado Liorcino Mendes manifestou hoje (20 ) sua indigna&ccedil;&atilde;o com a morte de dois rec&eacute;m-nascidos no Hospital Materno Infantil (HMI), em Goi&acirc;nia, ap&oacute;s serem infectados pela superbact&eacute;ria Klebsiella pneumoniae Carbapenemase (KPC). Para o Conselheiro &eacute; inaceit&aacute;vel que a Unidade de Terapia Intensiva (UTI )&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/10041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=10041"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/posts\/10041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media\/10040"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=10041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=10041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=10041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}