{"id":40311,"date":"2024-01-18T14:24:27","date_gmt":"2024-01-18T17:24:27","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/saude\/?page_id=40311"},"modified":"2025-12-02T11:52:39","modified_gmt":"2025-12-02T14:52:39","slug":"produtos-para-saude","status":"publish","type":"page","link":"https:\/\/goias.gov.br\/saude\/produtos-para-saude\/","title":{"rendered":"Produtos para Sa\u00fade"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"40311\" class=\"elementor elementor-40311\">\n\t\t\t\t<div class=\"elementor-element elementor-element-368e356 e-flex e-con-boxed e-con e-parent\" data-id=\"368e356\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25c09ee e-con-full e-flex e-con e-child\" data-id=\"25c09ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-395a0a5 elementor-widget elementor-widget-text-editor\" data-id=\"395a0a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Produtos para Sa\u00fade s\u00e3o produtos utilizados na realiza\u00e7\u00e3o de procedimentos m\u00e9dicos, odontol\u00f3gicos e fisioter\u00e1picos, bem como no diagn\u00f3stico, tratamento, reabilita\u00e7\u00e3o ou monitora\u00e7\u00e3o de pacientes.Compreendem tr\u00eas tipos de categorias: Equipamentos M\u00e9dicos, Materiais de Uso em Sa\u00fade e Produtos de Diagn\u00f3stico in vitro.<\/p><p>A RDC n\u00ba 185, de 22 de outubro de 2001 determina as seguintes defini\u00e7\u00f5es:<\/p><ul><li>Produto m\u00e9dico: Produto para a sa\u00fade, tal como equipamento, aparelho, material, artigo ou sistema de uso ou aplica\u00e7\u00e3o m\u00e9dica, odontol\u00f3gica ou laboratorial, destinado \u00e0 preven\u00e7\u00e3o, diagn\u00f3stico, tratamento, reabilita\u00e7\u00e3o ou anticoncep\u00e7\u00e3o e que n\u00e3o utiliza meio farmacol\u00f3gico, imunol\u00f3gico ou metab\u00f3lico para realizar sua principal fun\u00e7\u00e3o em seres humanos, podendo entretanto ser auxiliado em suas fun\u00e7\u00f5es por tais meios.<\/li><li>Produto m\u00e9dico ativo: Qualquer produto m\u00e9dico cujo funcionamento depende fonte de energia el\u00e9trica ou qualquer outra fonte de pot\u00eancia distinta da gerada pelo corpo humano ou gravidade e que funciona pela convers\u00e3o desta energia. N\u00e3o s\u00e3o considerados produtos m\u00e9dicos ativos, os produtos m\u00e9dicos destinados a transmitir energia, subst\u00e2ncias ou outros elementos entre um produto m\u00e9dico ativo e o paciente, sem provocar altera\u00e7\u00e3o significativa.<\/li><li>Produto m\u00e9dico ativo para diagn\u00f3stico: Qualquer produto m\u00e9dico ativo, utilizado isoladamente ou em combina\u00e7\u00e3o com outros produtos m\u00e9dicos, destinado a proporcionar informa\u00e7\u00f5es para a detec\u00e7\u00e3o, diagn\u00f3stico, monitora\u00e7\u00e3o ou tratamento das condi\u00e7\u00f5es fisiol\u00f3gicas ou de sa\u00fade, enfermidades ou deformidades cong\u00eanitas.<\/li><li>Produto m\u00e9dico ativo para terapia: Qualquer produto m\u00e9dico ativo, utilizado isoladamente ou em combina\u00e7\u00e3o com outros produtos m\u00e9dicos, destinado a sustentar, modificar, substituir ou restaurar fun\u00e7\u00f5es ou estruturas biol\u00f3gicas, no contexto de tratamento ou al\u00edvio de uma enfermidade, les\u00e3o ou defici\u00eancia.<\/li><li>Produto m\u00e9dico de uso \u00fanico: Qualquer produto m\u00e9dico destinado a ser usado na preven\u00e7\u00e3o, diagn\u00f3stico, terapia, reabilita\u00e7\u00e3o ou anticoncep\u00e7\u00e3o, utiliz\u00e1vel somente uma vez, segundo especificado pelo fabricante.<\/li><li>Produto m\u00e9dico implant\u00e1vel: Qualquer produto m\u00e9dico projetado para ser totalmente introduzido no corpo humano ou para substituir uma superf\u00edcie epitelial ou ocular, por meio de interven\u00e7\u00e3o cir\u00fargica, e destinado a permanecer no local ap\u00f3s a interven\u00e7\u00e3o. Tamb\u00e9m \u00e9 considerado um produto m\u00e9dico implant\u00e1vel, qualquer produto m\u00e9dico destinado a ser parcialmente introduzido no corpo humano atrav\u00e9s de interven\u00e7\u00e3o cir\u00fargica e permanecer ap\u00f3s esta interven\u00e7\u00e3o por longo prazo.<\/li><li>Produto m\u00e9dico invasivo: Produto m\u00e9dico que penetra total ou parcialmente dentro do corpo humano, seja atrav\u00e9s de um orif\u00edcio do corpo ou atrav\u00e9s da superf\u00edcie corporal.<\/li><li>Produto m\u00e9dico invasivo cirurgicamente: Produto m\u00e9dico invasivo que penetra no interior do corpo humano atrav\u00e9s da superf\u00edcie corporal por meio ou no contexto de uma interven\u00e7\u00e3o cir\u00fargica<\/li><\/ul><p>Os produtos m\u00e9dicos est\u00e3o enquadrados segundo o risco intensivo que representam \u00e0 sa\u00fade do consumidor, paciente, operador ou terceiros envolvidos, nas Classes I, II, III ou IV. Para enquadramento do produto m\u00e9dico em uma destas classes, devem ser aplicadas as regras de classifica\u00e7\u00e3o descritas no Anexo II da Resolu\u00e7\u00e3o n\u00ba 185 de 22\/10\/2001\/ANVISA \u2013 Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria.<\/p><p>Para fins do registro previsto na Lei no 6.360, de 23 de setembro de 1976 e Decreto n\u00ba 8.077, de 14 de agosto de 2013, a legisla\u00e7\u00e3o sanit\u00e1ria separa os produtos em:<\/p><ul><li>(a) produtos para sa\u00fade (correlatos) sujeitos a registro, os quais devem ser registrados na Anvisa na forma da Resolu\u00e7\u00e3o RDC n\u00ba 185\/2001;<\/li><li>(b) produtos para sa\u00fade dispensados de registro, referidos no \u00a7 1\u00ba do Art. 25 Lei no 6.360, de 23 de setembro de 1976, os quais devem ser cadastrados na Anvisa na forma da Resolu\u00e7\u00e3o RDC n\u00ba 40\/2015;<\/li><li>(c) produtos n\u00e3o considerados produtos para sa\u00fade, os quais n\u00e3o necessitam de qualquer autoriza\u00e7\u00e3o da Anvisa para sua fabrica\u00e7\u00e3o, importa\u00e7\u00e3o, exporta\u00e7\u00e3o, comercializa\u00e7\u00e3o, exposi\u00e7\u00e3o \u00e0 venda ou entrega ao consumo.<\/li><\/ul><p><a class=\"\" href=\"https:\/\/goias.gov.br\/saude\/legislacao-produtos-para-saude\/\" target=\"_blank\" rel=\"noopener\">Legisla\u00e7\u00f5es e normativas sobre Produtos para Sa\u00fade<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff84354 e-flex e-con-boxed e-con e-parent\" data-id=\"ff84354\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3176466 elementor-widget elementor-widget-heading\" data-id=\"3176466\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Outras Orienta\u00e7\u00f5es - Produtos para Sa\u00fade<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faec646 elementor-widget elementor-widget-n-accordion\" data-id=\"faec646\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2630\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2630\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Licenciamento Sanit\u00e1rio <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2630\" class=\"elementor-element elementor-element-2bad05c e-con-full e-flex e-con e-child\" data-id=\"2bad05c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07f40ba elementor-widget elementor-widget-text-editor\" data-id=\"07f40ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Conforme estabelecido na Lei Estadual 16.140 de 02 de outubro de 2007, em seu artido 117, os estabelecimentos sujeitos ao controle e \u00e0 fiscaliza\u00e7\u00e3o sanit\u00e1rios somente funcionar\u00e3o mediante alvar\u00e1 sanit\u00e1rio expedido pelo \u00f3rg\u00e3o competente estadual ou municipal, conforme habilita\u00e7\u00e3o e condi\u00e7\u00e3o de gest\u00e3o, com validade para o ano em que for concedido. Os artigos a seguir estabelecem ainda:<\/p><p>\u201cArt. 118. A exig\u00eancia de alvar\u00e1 sanit\u00e1rio, conforme o art. 117, obedecer\u00e1 \u00e0s seguintes normas:<\/p><p>I \u2013 a concess\u00e3o fica condicionada ao cumprimento de requisitos t\u00e9cnicos e \u00e0 inspe\u00e7\u00e3o da vigil\u00e2ncia sanit\u00e1ria;<\/p><p>II \u2013 no caso de simples renova\u00e7\u00e3o da licen\u00e7a sanit\u00e1ria, a inspe\u00e7\u00e3o poder\u00e1 ser realizada posteriormente, a crit\u00e9rio do \u00d3rg\u00e3o de Vigil\u00e2ncia Sanit\u00e1ria competente;<\/p><p>III \u2013 ser\u00e3o inspecionados os ambientes internos e externos dos estabelecimentos, produtos, equipamentos, das instala\u00e7\u00f5es, m\u00e1quinas, normas e suas rotinas t\u00e9cnicas;<\/p><p>IV \u2013 o alvar\u00e1 sanit\u00e1rio poder\u00e1, a qualquer tempo, ser suspenso, cassado ou cancelado, no interesse da sa\u00fade p\u00fablica, sendo assegurado ao propriet\u00e1rio do estabelecimento o direito de defesa em processo administrativo instaurado pelo \u00f3rg\u00e3o sanit\u00e1rio competente;<\/p><p>V \u2013 para abertura de novos estabelecimentos, o valor referente \u00e0 taxa de Licen\u00e7a Sanit\u00e1ria ser\u00e1 cobrado proporcionalmente ao n\u00famero de meses restantes do ano em curso;<\/p><p>VI \u2013 todo estabelecimento, ao encerrar suas atividades, deve comunicar formalmente o fato ao \u00f3rg\u00e3o que emitiu a respectiva licen\u00e7a sanit\u00e1ria;<\/p><p>VII \u2013 cada estabelecimento ter\u00e1 licen\u00e7a espec\u00edfica e independente, ainda que exista mais de um na mesma localidade, pertencente \u00e0 mesma empresa.<\/p><p>Art. 119. A compet\u00eancia para expedir licen\u00e7a sanit\u00e1ria para os hospitais, bancos de sangue, servi\u00e7os de terapia renal substitutiva e servi\u00e7os de radiodiagn\u00f3sticos m\u00e9dicos e odontol\u00f3gicos, radioterapia, quimioterapia, ind\u00fastria de medicamentos, ind\u00fastria de alimentos \u00e9 do \u00d3rg\u00e3o Sanit\u00e1rio Estadual, podendo ser delegada aos Munic\u00edpios por meio de ato do Secret\u00e1rio Estadual da Sa\u00fade.<\/p><p>Art. 120. O \u00f3rg\u00e3o sanit\u00e1rio estadual poder\u00e1 expedir, em car\u00e1ter suplementar, licen\u00e7a sanit\u00e1ria para os estabelecimentos industriais, comerciais e prestadores de servi\u00e7os, em face das defici\u00eancias dos Munic\u00edpios.<\/p><p>Art. 121. A emiss\u00e3o de licen\u00e7a para \u00e1rea de lazer fica condicionada \u00e0 vistoria pr\u00e9via e ao parecer favor\u00e1vel do \u00f3rg\u00e3o sanit\u00e1rio competente.<\/p><p>O alvar\u00e1 sanit\u00e1rio \u00e9 emitido pela Vigil\u00e2ncia Sanit\u00e1ria (VISA) local, seja ela municipal ou estadual, na qual a empresa esteja sediada. A emiss\u00e3o da licen\u00e7a pela SUVISA-GO ou pela VISA municipal ir\u00e1 depender da pactua\u00e7\u00e3o vigente para descentraliza\u00e7\u00e3o das a\u00e7\u00f5es de vigil\u00e2ncia sanit\u00e1ria direcionadas \u00e0 produtos para sa\u00fade.<\/p><p>Deferido peticionamento da Empresa de AFE junto \u00e0 ANVISA, ap\u00f3s a publica\u00e7\u00e3o da AFE no Di\u00e1rio Oficial da Uni\u00e3o &#8211; DOU, a Empresa, por meio de seu respons\u00e1vel legal e\/ou t\u00e9cnico dever\u00e1 se dirigir a Superintend\u00eancia de Vigil\u00e2ncia em Sa\u00fade &#8211; SUVISA\/GO com a documenta\u00e7\u00e3o necess\u00e1ria, protocola o pedido de libera\u00e7\u00e3o de Alvar\u00e1 Sanit\u00e1rio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2631\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2631\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Autoriza\u00e7\u00e3o de Funcionamento <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2631\" class=\"elementor-element elementor-element-f09d89b e-con-full e-flex e-con e-child\" data-id=\"f09d89b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ad23cf elementor-widget elementor-widget-text-editor\" data-id=\"8ad23cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Considerando a Lei Federal 6360 de 23 de setembro de 1976, que Disp\u00f5e sobre a Vigil\u00e2ncia Sanit\u00e1ria a que ficam sujeitos os Medicamentos, as Drogas, os Insumos Farmac\u00eauticos e Correlatos, Cosm\u00e9ticos, Saneantes e Outros Produtos, e d\u00e1 outras provid\u00eancias, em seus artigos 50, 51 e 52, reproduzidos integralmente abaixo:<\/p><p>&#8220;Art. 50. O funcionamento das empresas de que trata esta Lei depender\u00e1 de autoriza\u00e7\u00e3o da Anvisa, concedida mediante a solicita\u00e7\u00e3o de cadastramento de suas atividades, do pagamento da respectiva Taxa de Fiscaliza\u00e7\u00e3o de Vigil\u00e2ncia Sanit\u00e1ria e de outros requisitos definidos em regulamenta\u00e7\u00e3o espec\u00edfica da Anvisa. (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.097, de 2015)<\/p><p>Par\u00e1grafo \u00fanico. A autoriza\u00e7\u00e3o de que trata este artigo ser\u00e1 v\u00e1lida para todo o territ\u00f3rio nacional e dever\u00e1 ser renovada sempre que ocorrer altera\u00e7\u00e3o ou inclus\u00e3o de atividade ou mudan\u00e7a do s\u00f3cio ou diretor que tenha a seu cargo a representa\u00e7\u00e3o legal da empresa.<\/p><p>Par\u00e1grafo \u00fanico. A autoriza\u00e7\u00e3o de que trata este artigo ser\u00e1 v\u00e1lida para todo o territ\u00f3rio nacional e dever\u00e1 ser atualizada conforme regulamenta\u00e7\u00e3o espec\u00edfica da Anvisa. (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.097, de 2015)<\/p><p>Art. 51 \u2013 O licenciamento, pela autoridade local, dos estabelecimentos industriais ou comerciais que exer\u00e7am as atividades de que trata esta Lei, depender\u00e1 de haver sido autorizado o funcionamento da empresa pelo Minist\u00e9rio da Sa\u00fade e de serem atendidas, em cada estabelecimento, as exig\u00eancias de car\u00e1ter t\u00e9cnico e sanit\u00e1rio estabelecidas em regulamento e instru\u00e7\u00f5es do Minist\u00e9rio da Sa\u00fade, inclusive no tocante \u00e0 efetiva assist\u00eancia de respons\u00e1veis t\u00e9cnicos habilitados aos diversos setores de atividade.<\/p><p>Par\u00e1grafo \u00fanico. Cada estabelecimento ter\u00e1 licen\u00e7a espec\u00edfica e independente, ainda que exista mais de um na mesma localidade, pertencente \u00e0 mesma empresa.<\/p><p>Art. 52 \u2013 A legisla\u00e7\u00e3o local supletiva fixar\u00e1 as exig\u00eancias e condi\u00e7\u00f5es para o licenciamento dos estabelecimentos a que se refere esta Lei, observados os seguintes preceitos:<\/p><p>I \u2013 quando um s\u00f3 estabelecimento industrializar ou comercializar produtos de natureza ou finalidade diferentes, ser\u00e1 obrigat\u00f3ria a exist\u00eancia de instala\u00e7\u00f5es separadas para a fabrica\u00e7\u00e3o e o acondicionamento dos materiais, subst\u00e2ncias e produtos acabados;<\/p><p>II \u2013 localiza\u00e7\u00e3o adequada das depend\u00eancias e proibi\u00e7\u00e3o de resid\u00eancias ou moradia nos im\u00f3veis a elas destinados e nas \u00e1reas adjacentes;<\/p><p>III \u2013 aprova\u00e7\u00e3o pr\u00e9via, pelo \u00f3rg\u00e3o de sa\u00fade estadual dos projetos e das plantas dos edif\u00edcios e fiscaliza\u00e7\u00e3o da respectiva observ\u00e2ncia.&#8221;;<\/p><p>A AFE \u00e9 definida como ato de compet\u00eancia da Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria, contendo autoriza\u00e7\u00e3o para o funcionamento de empresas ou estabelecimentos, institui\u00e7\u00f5es e \u00f3rg\u00e3os, concedido mediante o cumprimento dos requisitos t\u00e9cnicos e administrativos constantes da RDC n\u00b016\/2014.<\/p><p>A RDC n\u00ba 16\/2014 tem o objetivo de estabelecer os crit\u00e9rios relativos \u00e0 concess\u00e3o, altera\u00e7\u00e3o, retifica\u00e7\u00e3o de publica\u00e7\u00e3o, cancelamento e interposi\u00e7\u00e3o de recurso administrativo contra o indeferimento de pedidos relacionados \u00e0 AFE e AE de empresas e estabelecimentos que realizam as atividades de armazenamento, distribui\u00e7\u00e3o, embalagem, expedi\u00e7\u00e3o, exporta\u00e7\u00e3o, extra\u00e7\u00e3o, fabrica\u00e7\u00e3o, fracionamento, importa\u00e7\u00e3o, produ\u00e7\u00e3o, purifica\u00e7\u00e3o, reembalagem, s\u00edntese, transforma\u00e7\u00e3o e transporte com medicamentos e insumos farmac\u00eauticos destinados a uso humano, subst\u00e2ncias sujeitas a controle especial, produtos para sa\u00fade, cosm\u00e9ticos, produtos de higiene pessoal, perfumes, saneantes e cultivo de plantas que possam originar subst\u00e2ncias sujeitas a controle especial.<\/p><p>Os crit\u00e9rios para peticionamento e recolhimento de taxa referentes a cada tipo de AFE na ANVISA est\u00e3o dispon\u00edveis em:<\/p><p>&#8211; RDC n\u00ba 222 \/ 2006, que disp\u00f5e sobre os procedimentos de peti\u00e7\u00e3o e arrecada\u00e7\u00e3o eletr\u00f4nica no \u00e2mbito da Anvisa e de suas Coordena\u00e7\u00f5es Estaduais e Municipais de Vigil\u00e2ncia Sanit\u00e1ria e d\u00e1 outras Provid\u00eancias.<\/p><p>&#8211; RDC n\u00b0 76 \/ 2008, que disp\u00f5e sobre altera\u00e7\u00e3o da RDC n\u00ba 222 \/ 2006.<\/p><p>&#8211; RDC n\u00b017 \/ 2012, que disp\u00f5es sobre altera\u00e7\u00e3o da RDC n\u00ba 222 \/ 2006.<\/p><p>Um dos documentos constantes no dossi\u00ea entregue \u00e0 ANVISA para peticionamento da AFE \u00e9 o Relat\u00f3rio T\u00e9cnico da Vigil\u00e2ncia Sanit\u00e1ria local, obedecendo a pactua\u00e7\u00e3o vigente para as a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o direcionadas a \u00e1rea de Produtos para Sa\u00fade em Goi\u00e1s, para verifica\u00e7\u00e3o do cumprimento das Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o, Armazenamento e\/ou Distribui\u00e7\u00e3o de produtos para sa\u00fade, conforme os requisitos estabelecidos pela RDC n\u00ba 16 de 28 de mar\u00e7o de 2013.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2632\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2632\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Registro ou Cadastramento de Produtos para Sa\u00fade <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2632\" class=\"elementor-element elementor-element-28a68aa e-con-full e-flex e-con e-child\" data-id=\"28a68aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a22cea0 elementor-widget elementor-widget-text-editor\" data-id=\"a22cea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Conforme determina o Art. 12 da Lei 6.360, de 23\/09\/76, \u201cnenhum dos produtos de que trata esta Lei (produtos sujeitos \u00e0 vigil\u00e2ncia sanit\u00e1ria), inclusive os importados, poder\u00e1 ser industrializado, exposto \u00e0 venda ou entregue ao consumo antes de registrado no Minist\u00e9rio da Sa\u00fade\u201d, exceto os produtos para sa\u00fade dispensados de registro, conforme o Art. 25 desta Lei. O Decreto 8077 de 14 de agosto de 2013, regulamenta as condi\u00e7\u00f5es para o funcionamento de empresas sujeitas ao licenciamento sanit\u00e1rio, e o registro, controle e monitoramento, no \u00e2mbito da vigil\u00e2ncia sanit\u00e1ria.<\/p><p>O ponto de partida para a solicita\u00e7\u00e3o de registro ou cadastramento de materiais de uso em sa\u00fade na ANVISA \u00e9 a regulariza\u00e7\u00e3o da empresa junto \u00e0 Vigil\u00e2ncia Sanit\u00e1ria, o que compreende a obten\u00e7\u00e3o da Autoriza\u00e7\u00e3o de Funcionamento da Empresa (AFE) e do Alvar\u00e1 de Licen\u00e7a Sanit\u00e1ria. A RDC n\u00ba 15, de 28 de mar\u00e7o de 2014, em seu artigo 2\u00ba, par\u00e1grafo \u00fanico determina ainda que o deferimento das solicita\u00e7\u00f5es de concess\u00e3o de registro fica condicionado \u00e0 publica\u00e7\u00e3o de Certificado de Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o &#8211; CBPF v\u00e1lido emitido pela ANVISA e ao cumprimento dos demais requisitos para registro de produtos para sa\u00fade.<\/p><p>Para os produtos m\u00e9dicos a resolu\u00e7\u00e3o destinada ao registro, altera\u00e7\u00e3o, revalida\u00e7\u00e3o e cancelamento do registro na Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria \u2013 ANVISA \u00e9 a Resolu\u00e7\u00e3o Anvisa RDC n\u00ba 185, de 22 de outubro de 2001, embora legisla\u00e7\u00f5es complementares tamb\u00e9m sejam utilizadas neste processo.<\/p><p>Em 26 de outubro de 2015 entrou em vigor as Resolu\u00e7\u00f5es 40\/2015 e 36\/2015, que definem requisitos para cadastro de produtos m\u00e9dicos (materiais de uso em sa\u00fade e equipamentos m\u00e9dicos) e de cadastro e registro de produtos para diagn\u00f3stico in vitro, respectivamente. Por conseguinte, alguns pontos relevantes foram alterados:<\/p><p>Produtos m\u00e9dicos<\/p><p>Todos os produtos enquadrados nas classes de risco I e II passam a ser sujeitos a cadastro;<\/p><p>Produtos sujeitos a cadastro n\u00e3o ser\u00e3o revalidados;<\/p><p>O vencimento do cadastro destes produtos ser\u00e1 identificado como \u201cvigente\u201d no banco de dados da Anvisa at\u00e9 que ocorra o seu cancelamento por qualquer motivo. Nessa situa\u00e7\u00e3o o vencimento do cadastro ser\u00e1 apontado como \u201ccancelado em dia\/m\u00eas\/ano\u201d.<\/p><p>Fabricantes nacionais e importadores dever\u00e3o manter atualizado o dossi\u00ea t\u00e9cnico dos produtos cadastrados;<\/p><p>O prazo para adequa\u00e7\u00e3o definido no regulamento (RDC 40\/2015) \u00e9 de 1 ano. Desta forma, todos os produtos de classes I e II devem ter o respectivo dossi\u00ea t\u00e9cnico dispon\u00edvel para o Sistema Nacional de Vigil\u00e2ncia Sanit\u00e1ria a partir de 26 de outubro de 2016;<\/p><p>Produtos para Diagn\u00f3stico in vitro<\/p><p>Fabricantes nacionais e importadores dever\u00e3o manter atualizado o dossi\u00ea t\u00e9cnico de todos os produtos, cadastrados e registrados;<\/p><p>O prazo para adequa\u00e7\u00e3o definido no regulamento (RDC 36\/2015) \u00e9 de 1 ano. Desta forma, todos os produtos (classes de risco I, II, III e IV) devem ter o dossi\u00ea t\u00e9cnico dispon\u00edvel para o SNVS a partir de 26 de outubro de 2016;<\/p><p>Crit\u00e9rios para registro de produtos auto teste, destinados ao p\u00fablico leigo;<\/p><p>Atualiza\u00e7\u00e3o e incorpora\u00e7\u00e3o das regras de classifica\u00e7\u00e3o de produtos no texto do regulamento;<\/p><p>Inclus\u00e3o de regras de agrupamento em fam\u00edlia de produtos para diagn\u00f3stico in vitro e vincula\u00e7\u00e3o a IN 3\/2015.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2633\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2633\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Certificado de Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o, Armazenamento e Distribui\u00e7\u00e3o <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2633\" class=\"elementor-element elementor-element-178d053 e-con-full e-flex e-con e-child\" data-id=\"178d053\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f62033 elementor-widget elementor-widget-text-editor\" data-id=\"2f62033\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>As Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o, normalmente conhecidas com BPF, s\u00e3o um conjunto de procedimentos estabelecidos que relacionam pr\u00e1ticas produtivas que compreendem desde o desenvolvimento dos produtos e a compra de insumos e componentes, passando pelo processo produtivo, armazenamento at\u00e9 a comercializa\u00e7\u00e3o dos produtos e posterior acompanhamento dos mesmos no mercado. Esses procedimentos s\u00e3o baseados em normas, nacionais e internacionais, espec\u00edficas para cada ramo de atividade industrial.<\/p><p>As Boas Pr\u00e1ticas referem-se \u00e0 fabrica\u00e7\u00e3o e importa\u00e7\u00e3o (incluindo armazenamento, distribui\u00e7\u00e3o e comercializa\u00e7\u00e3o) de produtos para a sa\u00fade, incluindo adequa\u00e7\u00e3o de suas instala\u00e7\u00f5es, organiza\u00e7\u00e3o gerencial e de qualidade, processos produtivos e de controle, conforme preconizado na RDC n\u00ba 16, de 28 de mar\u00e7o de 2013. O reconhecimento das Boas Pr\u00e1ticas \u00e9 feito atrav\u00e9s da emiss\u00e3o de um Certificado de Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o (CBPF) ou Certificado de Boas Pr\u00e1ticas de Armazenamento e Distribui\u00e7\u00e3o (CBPAD) pela Anvisa.<\/p><p>A Resolu\u00e7\u00e3o &#8211; RDC N\u00ba 39, de 14 de agosto de 2013 disp\u00f5e sobre os procedimentos administrativos para concess\u00e3o da Certifica\u00e7\u00e3o de Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o e da Certifica\u00e7\u00e3o de Boas Pr\u00e1ticas de Distribui\u00e7\u00e3o e\/ou Armazenagem. A RDC n\u00ba 15, de 28 de mar\u00e7o de 2015 define os requisitos relativos \u00e0 comprova\u00e7\u00e3o do cumprimento de Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o \u2013 BPF necess\u00e1rios para fins de registro de produtos para sa\u00fade.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bc0162 e-flex e-con-boxed e-con e-parent\" data-id=\"3bc0162\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b66a7b2 elementor-widget elementor-widget-text-editor\" data-id=\"b66a7b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"wppb-addon-title\"><strong>Vigil\u00e2ncia P\u00f3s-Comercializa\u00e7\u00e3o<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6be733c elementor-widget elementor-widget-html\" data-id=\"6be733c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!DOCTYPE html>\r\n<html lang=\"pt-br\" dir=\"ltr\">\r\n<head>\r\n  <meta http-equiv=\"Content-Type\" content=\"text\/html; charset=UTF-8\" \/>\r\n  <style>\r\n    \/* Estilos para desktop *\/\r\n    .container {\r\n      padding: 10px;\r\n    }\r\n\r\n    .section {\r\n      margin-bottom: 10px;\r\n    }\r\n\r\n    .title {\r\n      text-align: center;\r\n      margin: 0 0 24px;\r\n      color: #0c326f;\r\n      font-weight: 600;\r\n      font-size: 2.2rem;\r\n      line-height: 1.5;\r\n    }\r\n\r\n    .cards {\r\n      display: flex;\r\n      justify-content: space-evenly;\r\n      flex-wrap: wrap;\r\n      margin: 0;\r\n      padding: 0;\r\n      list-style: none;\r\n    }\r\n\r\n    .cards li {\r\n      background-color: #ededed;\r\n      box-shadow: 0 3px 6px 0 rgba(0, 0, 0, 0.16);\r\n      text-align: center;\r\n      flex-basis: 23%;\r\n      box-sizing: border-box;\r\n      min-height: 60px;\r\n      margin-bottom: 0.9em;\r\n      line-height: 1.2em;\r\n      display: list-item;\r\n    }\r\n\r\n    .cards li a {\r\n      display: flex;\r\n      justify-content: center;\r\n      align-items: center;\r\n      flex-direction: column;\r\n      width: 100%;\r\n      height: 100%;\r\n      color: #1351b4;\r\n      font-weight: 600;\r\n      text-decoration: none;\r\n    }\r\n\r\n    .cards li i,\r\n    .cards li span {\r\n      font-size: 10px;\r\n      margin-bottom: 30px;\r\n      color: #0c326f;\r\n      width: auto;\r\n      font-weight: 200;\r\n    }\r\n\r\n    .cards li .title {\r\n      font-size: 15px;\r\n      color: #0c326f;\r\n      font-weight: 500;\r\n      margin: 0;\r\n      text-transform: uppercase;\r\n    }\r\n\r\n    \/* Estilos para telas menores *\/\r\n    @media screen and (max-width: 768px) {\r\n      .cards {\r\n        gap: 20px; \/* Espa\u00e7amento entre os cards *\/\r\n        margin-top: 20px; \/* Margem superior para os cards *\/\r\n      }\r\n      .cards li {\r\n        flex-basis: calc(50% - 20px); \/* Tamanho dos cards com espa\u00e7amento *\/\r\n      }\r\n    }\r\n\r\n    @media screen and (max-width: 480px) {\r\n      .cards {\r\n        gap: 15px; \/* Espa\u00e7amento menor entre os cards *\/\r\n        margin-top: 15px; \/* Margem superior menor para os cards *\/\r\n      }\r\n      .cards li {\r\n        flex-basis: calc(100% - 30px); \/* Tamanho dos cards com espa\u00e7amento menor *\/\r\n      }\r\n    }\r\n  <\/style>\r\n<\/head>\r\n<body>\r\n  <div class=\"container\">\r\n    <div class=\"section\">\r\n      <div class=\"suvisa\">\r\n        \r\n        <ul class=\"cards\">\r\n          <li>\r\n                    <a href=\"https:\/\/goias.gov.br\/saude\/farmacovigilancia\/\">\r\n\r\n                        <div class=\"title\">farmacovigil\u00e2ncia<\/div>\r\n                    <\/a>\r\n                <\/li>\r\n                <li>\r\n                    <a href=\"https:\/\/goias.gov.br\/saude\/hemovigilancia\/\">\r\n\r\n                        <div class=\"title\">hemovigil\u00e2ncia<\/div>\r\n                    <\/a>\r\n                <\/li>\r\n                <li>\r\n                    <a href=\"https:\/\/goias.gov.br\/saude\/tecnovigilancia\/\">\r\n     \r\n                        <div class=\"title\">tecnovigil\u00e2ncia<\/div>\r\n                    <\/a>\r\n                <\/li>\r\n\r\n\r\n  \r\n        <\/ul>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/body>\r\n<\/html>\r\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Produtos para Sa\u00fade s\u00e3o produtos utilizados na realiza\u00e7\u00e3o de procedimentos m\u00e9dicos, odontol\u00f3gicos e fisioter\u00e1picos, bem como no diagn\u00f3stico, tratamento, reabilita\u00e7\u00e3o ou monitora\u00e7\u00e3o de pacientes.Compreendem tr\u00eas tipos de categorias: Equipamentos M\u00e9dicos, Materiais de Uso em Sa\u00fade e Produtos de Diagn\u00f3stico in vitro. A RDC n\u00ba 185, de 22 de outubro de 2001 determina as seguintes defini\u00e7\u00f5es: [&hellip;]<\/p>\n","protected":false},"author":693,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-40311","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"elzenubiamoreira","author_link":"https:\/\/goias.gov.br\/saude\/author\/elzenubiamoreira\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"Produtos para Sa\u00fade s\u00e3o produtos utilizados na realiza\u00e7\u00e3o de procedimentos m\u00e9dicos, odontol\u00f3gicos e fisioter\u00e1picos, bem como no diagn\u00f3stico, tratamento, reabilita\u00e7\u00e3o ou monitora\u00e7\u00e3o de pacientes.Compreendem tr\u00eas tipos de categorias: Equipamentos M\u00e9dicos, Materiais de Uso em Sa\u00fade e Produtos de Diagn\u00f3stico in vitro. A RDC n\u00ba 185, de 22 de outubro de 2001 determina as seguintes defini\u00e7\u00f5es:&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/pages\/40311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/users\/693"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=40311"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/pages\/40311\/revisions"}],"predecessor-version":[{"id":623975,"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/pages\/40311\/revisions\/623975"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=40311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}