
{"id":6627,"date":"2012-11-23T10:57:03","date_gmt":"2012-11-23T12:57:03","guid":{"rendered":"http:\/\/www.procon.go.gov.br\/?p=6627"},"modified":"2016-01-21T12:37:57","modified_gmt":"2016-01-21T14:37:57","slug":"procon-goias-da-dicas-ao-consumidor-que-participa-da-black-friday","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/procon\/procon-goias-da-dicas-ao-consumidor-que-participa-da-black-friday\/","title":{"rendered":"Procon Goi\u00e1s d\u00e1 dicas ao consumidor que participa da Black Friday"},"content":{"rendered":"<p style=\"text-align: justify;\">Desde a<img decoding=\"async\" class=\"alignleft size-medium wp-image-6628\" title=\"Black Friday\" src=\"\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday-200x200.jpg\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday-200x200.jpg 200w, https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday-350x350.jpg 350w, https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday-130x130.jpg 130w, https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday.jpg 400w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/> 0h01 desta sexta-feira (23\/11) est\u00e1 acontecendo a terceira edi\u00e7\u00e3o da <strong><em>Black<\/em> <em>Friday<\/em><\/strong> (Sexta-Feira Negra), evento varejista que oferece produtos e servi\u00e7os com grandes descontos em sites. Algumas lojas f\u00edsicas tamb\u00e9m participam da promo\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de pesquisar os pre\u00e7os antes da compra, para verificar se a oferta \u00e9 realmente vantajosa como o prometido e evitar as compras por impulso \u00e9 importante que o consumidor procure refer\u00eancias sobre o site acessado e veja se h\u00e1 requisitos de seguran\u00e7a para senhas e dados.<\/p>\n<p style=\"text-align: justify;\">A comercializa\u00e7\u00e3o de produtos e servi\u00e7os em loja f\u00edsica ou online deve seguir as determina\u00e7\u00f5es do C\u00f3digo de Defesa do Consumidor (CDC). Nas compras pela internet o consumidor tem o prazo de sete dias, do recebimento da mercadoria, para o <strong><em>arrependimento,<\/em><\/strong> ou seja, pode cancelar o neg\u00f3cio, sem que qualquer valor lhe seja cobrado.<\/p>\n<p style=\"text-align: justify;\">Se o produto for entregue com defeito, a loja virtual tem 30 dias para solucionar o problema. Caso contr\u00e1rio, o consumidor pode escolher entre receber uma mercadoria nova ou receber seu dinheiro de volta.<\/p>\n<p style=\"text-align: justify;\"><strong>Dicas do Procon:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Compras<\/strong> <strong>por<\/strong> <strong>impulso<\/strong>: n\u00e3o se deixe levar pelo apelo emocional da oferta e comprar itens dos quais n\u00e3o tem necessidade no momento, mas aparece na promo\u00e7\u00e3o como pre\u00e7o &#8220;tentador&#8221;. O valor pode se somar ao ac\u00famulo de outras d\u00edvidas e tornar dif\u00edcil o pagamento.<\/p>\n<p style=\"text-align: justify;\"><strong>Pesquisa:<\/strong> verifique os pre\u00e7os cobrados pelos servi\u00e7os e produtos pelos quais se interessa nos sites das empresas que participam da <em>Black<\/em> <em>Friday<\/em> e de outros fornecedores, inclusive na data da liquida\u00e7\u00e3o. Assim \u00e9 menor o risco de cair na armadilha de promo\u00e7\u00f5es que n\u00e3o s\u00e3o t\u00e3o vantajosas como o anunciado.<\/p>\n<p style=\"text-align: justify;\"><strong>Aten\u00e7\u00e3o:<\/strong> leia a pol\u00edtica de privacidade da loja virtual para saber quais compromissos ela assume quanto ao armazenamento e manipula\u00e7\u00e3o de senhas e dados.<\/p>\n<p style=\"text-align: justify;\"><strong>Documento:<\/strong> imprima ou salve todos os documentos que demonstrem a compra e confirma\u00e7\u00e3o do pedido, como comprovante de pagamento, contrato e an\u00fancios.<\/p>\n<p style=\"text-align: justify;\"><strong>Dicas<\/strong> <strong>de<\/strong> <strong>seguran\u00e7a:<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Comprar pela internet \u00e9 mais r\u00e1pido e c\u00f4modo, mas \u00e9 preciso tomar alguns cuidados.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Procure no site a identifica\u00e7\u00e3o da loja, como raz\u00e3o social, CNPJ, endere\u00e7o, telefone fixo e outras formas de contato, al\u00e9m do email.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Evite sites que exibem como forma de contato apenas um telefone celular.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Prefira fornecedores recomendados por amigos ou familiares ou que possuam tamb\u00e9m estabelecimento f\u00edsico, para facilitar a localiza\u00e7\u00e3o da empresa, caso ocorra algum problema.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Prefira sites que tenham Sistema de Atendimento ao Consumidor (SAC).<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Instale programa de antiv\u00edrus e o firewall, sistema que impede a transmiss\u00e3o e\/ou recep\u00e7\u00e3o de acessos nocivos ou n\u00e3o autorizados, e mantenha atualizados no computador.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Nunca realize transa\u00e7\u00f5es online em lan houses, cybercaf\u00e9s ou computadores p\u00fablicos, pois podem n\u00e3o estar adequadamente protegidos.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Direitos<\/strong> <strong>do<\/strong> <strong>consumidor<\/strong>:<\/p>\n<p style=\"text-align: justify;\">O fato da compra ser feita em uma liquida\u00e7\u00e3o n\u00e3o elimina os direitos do consumidor.<\/p>\n<p style=\"text-align: justify;\">Veja alguns deles:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Se o empresa prometeu desconto em determinado produto, a oferta deve ser cumprida conforme a veicula\u00e7\u00e3o.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>O CDC estabelece prazo de 30 dias para reclama\u00e7\u00f5es sobre v\u00edcios aparentes ou de f\u00e1cil constata\u00e7\u00e3o no caso de produtos n\u00e3o dur\u00e1veis e de 90 dias para itens dur\u00e1veis, contados a partir do recebimento da mercadoria. Tratando-se de v\u00edcio oculto a contagem do prazo \u00e9 feita a partir da constata\u00e7\u00e3o do problema.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Produtos importados adquiridos no Brasil em estabelecimentos devidamente legalizados seguem as mesmas regras dos nacionais.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>No caso de mercadorias que necessitem ser entregues em domicilio, solicite que o prazo de entrega seja registrado na nota fiscal ou recibo.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>No ato da entrega, o consumidor s\u00f3 deve assinar o documento de recebimento do produto, ap\u00f3s examinar o estado da mercadoria. Havendo irregularidades, estas devem ser relacionadas, justificando assim o n\u00e3o recebimento.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Fonte: Procon Goi\u00e1s\/Funda\u00e7\u00e3o Procon SP<\/p>\n<p>Mais informa\u00e7\u00f5es:<br \/>\nAssessoria de Imprensa \u2013 Procon Goi\u00e1s<br \/>\n<strong>3201-7134<\/strong><br \/>\nimprensa@procon.go.gov.br<br \/>\nEurico Rocha: 8447-1881 \/\/\/ 8529-1065<br \/>\nLucas Santos: 8116-6192 \/\/\/ 8210-2973<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde a 0h01 desta sexta-feira (23\/11) est\u00e1 acontecendo a terceira edi\u00e7\u00e3o da Black Friday (Sexta-Feira Negra), evento varejista que oferece produtos e servi\u00e7os com grandes descontos em sites. Algumas lojas f\u00edsicas tamb\u00e9m participam da promo\u00e7\u00e3o. Al\u00e9m de pesquisar os pre\u00e7os antes da compra, para verificar se a oferta \u00e9 realmente vantajosa como o prometido e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6628,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[1446,82,1449,708,1448,1447],"class_list":["post-6627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-black-friday","tag-cdc","tag-descontos","tag-liquidacao","tag-ofertas","tag-sexta-feira-negra"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday.jpg",400,400,false],"landscape":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday.jpg",400,400,false],"portraits":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday.jpg",400,400,false],"thumbnail":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday-140x120.jpg",140,120,true],"medium":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday-200x200.jpg",200,200,true],"large":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday-350x350.jpg",350,350,true],"1536x1536":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday.jpg",400,400,false],"2048x2048":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2012\/11\/Black-Friday.jpg",400,400,false]},"rttpg_author":{"display_name":"rogerioduarte","author_link":"https:\/\/goias.gov.br\/procon\/author\/rogerioduarte\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/procon\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Desde a 0h01 desta sexta-feira (23\/11) est\u00e1 acontecendo a terceira edi\u00e7\u00e3o da Black Friday (Sexta-Feira Negra), evento varejista que oferece produtos e servi\u00e7os com grandes descontos em sites. Algumas lojas f\u00edsicas tamb\u00e9m participam da promo\u00e7\u00e3o. Al\u00e9m de pesquisar os pre\u00e7os antes da compra, para verificar se a oferta \u00e9 realmente vantajosa como o prometido e&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts\/6627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/comments?post=6627"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts\/6627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/media\/6628"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/media?parent=6627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/categories?post=6627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/tags?post=6627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}