{"id":42273,"date":"2019-01-22T15:05:04","date_gmt":"2019-01-22T17:05:04","guid":{"rendered":"https:\/\/www.procon.go.gov.br\/?p=42273"},"modified":"2019-02-19T09:37:28","modified_gmt":"2019-02-19T12:37:28","slug":"procon-goias-ja-recebeu-184-reclamacoes-contra-enel-em-2019","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/procon\/procon-goias-ja-recebeu-184-reclamacoes-contra-enel-em-2019\/","title":{"rendered":"Procon Goi\u00e1s j\u00e1 recebeu 184 atendimentos em desfavor da Enel Distribui\u00e7\u00e3o Goi\u00e1s em 2019"},"content":{"rendered":"<figure id=\"attachment_42274\" aria-describedby=\"caption-attachment-42274\" style=\"width: 820px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-42274 size-full\" src=\"\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz.jpg\" alt=\"(Foto: Reprodu\u00e7\u00e3o)\" width=\"820\" height=\"547\" srcset=\"https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz.jpg 820w, https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz-220x147.jpg 220w, https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz-768x512.jpg 768w, https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz-450x300.jpg 450w, https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz-150x100.jpg 150w, https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz-400x267.jpg 400w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><figcaption id=\"caption-attachment-42274\" class=\"wp-caption-text\">(Foto: Reprodu\u00e7\u00e3o)<\/figcaption><\/figure>\n<h2><strong>Procon Goi\u00e1s j\u00e1 recebeu 184 atendimentos em desfavor da Enel Distribui\u00e7\u00e3o Goi\u00e1s em 2019<\/strong><\/h2>\n<h3><em>Maioria dos atendimentos est\u00e1 relacionada \u00e0 cobran\u00e7a indevida; Interrup\u00e7\u00e3o no fornecimento de energia tamb\u00e9m consta entre as principais reclama\u00e7\u00f5es<\/em><\/h3>\n<p><strong>Goi\u00e2nia, 22 de janeiro &#8211;<\/strong> O Procon Goi\u00e1s registrou, somente nos primeiros 21 dias deste ano, 184 atendimentos de consumidores em desfavor da Enel Distribui\u00e7\u00e3o. A maioria delas &#8211; 80 atendimentos &#8211; est\u00e1 relacionada \u00e0\u00a0 cobran\u00e7a indevida. Al\u00e9m disso, a interrup\u00e7\u00e3o no servi\u00e7o, que ocorreu em decorr\u00eancia a forte chuva do dia 12, resultou em reclama\u00e7\u00f5es de moradores e comerciantes de v\u00e1rias regi\u00f5es de Goi\u00e2nia.<\/p>\n<p>Entre os dias 16 a 18, fiscais do Procon Goi\u00e1s estiveram em diversos estabelecimentos comerciais e resid\u00eancias da capital.\u00a0 Foi constatada a m\u00e1 presta\u00e7\u00e3o do servi\u00e7o nos setores Cidade Jardim, Estrela Dalva e Parque Eldorado Oeste. Sendo que, neste \u00faltimo os usu\u00e1rios narraram que ficaram sem energia por aproximadamente quatro dias.<\/p>\n<p>Os fiscais tamb\u00e9m verificaram, in loco, v\u00e1rios preju\u00edzos causados pela queda do fornecimento de energia. Muitos consumidores tiveram danos em aparelhos de TV, geladeira, motores el\u00e9tricos de port\u00e3o, entre outros equipamentos.<\/p>\n<p>Os servi\u00e7os de atendimento ao consumidor (SAC-0800-620196) tamb\u00e9m foram monitorados. O Decreto Federal 6523 \/ 2008, que determina as normas gerais para o SAC e fixa tempo para o atendimento , est\u00e1 sendo descumprido. A Enel foi autuada e tem o prazo de 10 dias para apresentar defesa escrita.<\/p>\n<h2>Orienta\u00e7\u00f5es<\/h2>\n<p>O Procon Goi\u00e1s alerta aos usu\u00e1rios que tiveram algum tipo de preju\u00edzo\u00a0 com a interrup\u00e7\u00e3o dos servi\u00e7os de energia el\u00e9trica que entrem em contato com a concession\u00e1ria Enel, solicitem o ressarcimento e anotem o n\u00famero do protocolo de atendimento.<\/p>\n<p>A partir do contato, a empresa ter\u00e1 10 dias corridos para inspecionar o equipamento danificado. Em caso de aparelhos que acondicionam produtos aliment\u00edcios perec\u00edveis ou medicamentos, o prazo \u00e9 de um dia \u00fatil (Art. 206, da Resolu\u00e7\u00e3o Normativa n\u00ba 499, da Aneel).<\/p>\n<p>A resolu\u00e7\u00e3o estabelece que a distribuidora de energia el\u00e9trica deve informar ao consumidor, pelo meio de comunica\u00e7\u00e3o escolhido, o\u00a0 resultado da solicita\u00e7\u00e3o, atrav\u00e9s de documento padronizado, no prazo de\u00a0 15 dias, contados a partir da data da vistoria ou, na falta desta, a partir da solicita\u00e7\u00e3o de ressarcimento.<\/p>\n<p>No caso de deferimento, a distribuidora deve ressarcir, em at\u00e9 20 dias, por meio do pagamento em moeda corrente, realizar o\u00a0 conserto ou a substitui\u00e7\u00e3o do equipamento danificado.<\/p>\n<p>O consumidor deve registrar os fatos relativos aos danos com provas, tais como: fotografias, parecer por escrito de um t\u00e9cnico particular em rela\u00e7\u00e3o aos problemas nos equipamentos, not\u00edcias veiculadas na imprensa, entre outras.<\/p>\n<p>O usu\u00e1rio que decidir\u00a0 ingressar com a\u00e7\u00e3o judicial buscando indeniza\u00e7\u00e3o por danos materiais e morais pode protocolar a peti\u00e7\u00e3o nos Juizados Especiais C\u00edveis, munido do comprovante de endere\u00e7o, c\u00f3pias de documentos pessoais e prova documental do preju\u00edzo.<\/p>\n<h2><strong>Atendimento Procon Goi\u00e1s (D\u00favidas, reclama\u00e7\u00f5es e den\u00fancias)<\/strong><\/h2>\n<p>Os consumidores que se sentirem prejudicados podem entrar em contato com o\u00a0 Procon Goi\u00e1s atrav\u00e9s dos seguintes canais de atendimento:<\/p>\n<p><strong>Presencial:<\/strong> Realizado na sede do Procon Goi\u00e1s, localizada na Rua 8, n\u00ba 242, Setor Central, em Goi\u00e2nia; e tamb\u00e9m nas unidades de atendimento Vapt Vupt.<\/p>\n<p><strong>Internet<\/strong>: Dispon\u00edvel atrav\u00e9s da plataforma ProconWeb (https:\/\/proconweb.ssp.go.gov.br).<\/p>\n<p><strong>Telefone<\/strong>: Moradores do munic\u00edpio de Goi\u00e2nia podem entrar em contato atrav\u00e9s do Disque Den\u00fancia (151). J\u00e1 os moradores do interior devem\u00a0 ligar para o n\u00famero (62) 3201-7124<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Assessoria de Imprensa do Procon Goi\u00e1s<\/strong><\/p>\n<p>(62) 3201-7134<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Procon Goi\u00e1s j\u00e1 recebeu 184 atendimentos em desfavor da Enel Distribui\u00e7\u00e3o Goi\u00e1s em 2019 Maioria dos atendimentos est\u00e1 relacionada \u00e0 cobran\u00e7a indevida; Interrup\u00e7\u00e3o no fornecimento de energia tamb\u00e9m consta entre as principais reclama\u00e7\u00f5es Goi\u00e2nia, 22 de janeiro &#8211; O Procon Goi\u00e1s registrou, somente nos primeiros 21 dias deste ano, 184 atendimentos de consumidores em desfavor [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":42274,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[562,7526],"tags":[1115,8599,446,9446,5,341,9447,1247],"class_list":["post-42273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas-ao-consumidor","category-noticias-procon","tag-direitos-do-consumidor","tag-enel","tag-goiania","tag-luz","tag-procon","tag-procon-goias","tag-queda-de-energia","tag-reclamacao"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz.jpg",820,547,false],"landscape":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz.jpg",820,547,false],"portraits":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz.jpg",820,547,false],"thumbnail":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz-140x120.jpg",140,120,true],"medium":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz-220x147.jpg",220,147,true],"large":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz-450x300.jpg",450,300,true],"1536x1536":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz.jpg",820,547,false],"2048x2048":["https:\/\/goias.gov.br\/procon\/wp-content\/uploads\/sites\/19\/2019\/01\/luz.jpg",820,547,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/procon\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/procon\/categoria\/dicas-ao-consumidor\/\" rel=\"category tag\">Dicas ao Consumidor<\/a> <a href=\"https:\/\/goias.gov.br\/procon\/categoria\/noticias-procon\/\" rel=\"category tag\">Not\u00edcias Procon Goi\u00e1s<\/a>","rttpg_excerpt":"Procon Goi\u00e1s j\u00e1 recebeu 184 atendimentos em desfavor da Enel Distribui\u00e7\u00e3o Goi\u00e1s em 2019 Maioria dos atendimentos est\u00e1 relacionada \u00e0 cobran\u00e7a indevida; Interrup\u00e7\u00e3o no fornecimento de energia tamb\u00e9m consta entre as principais reclama\u00e7\u00f5es Goi\u00e2nia, 22 de janeiro &#8211; O Procon Goi\u00e1s registrou, somente nos primeiros 21 dias deste ano, 184 atendimentos de consumidores em desfavor&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts\/42273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/comments?post=42273"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts\/42273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/media\/42274"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/media?parent=42273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/categories?post=42273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/tags?post=42273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}