{"id":1524,"date":"2003-12-30T14:57:41","date_gmt":"2003-12-30T16:57:41","guid":{"rendered":"http:\/\/www.procon.go.gov.br\/?p=1524"},"modified":"2016-05-12T16:57:52","modified_gmt":"2016-05-12T19:57:52","slug":"lei-estadual-14-648-30-12-03-cadastro-de-consumidores-altera-lei-14-072","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/procon\/lei-estadual-14-648-30-12-03-cadastro-de-consumidores-altera-lei-14-072\/","title":{"rendered":"Lei n\u00ba 14.648 (30\/12\/2003) &#8211; D\u00e1 nova reda\u00e7\u00e3o ao par\u00e1grafo \u00fanico do art. 1o da Lei no 14.072, de 28 de dezembro de 2001"},"content":{"rendered":"<p style=\"text-align: justify;\">LEI No 14.648, DE 30 DE DEZEMBRO DE 2003.<\/p>\n<p style=\"text-align: justify;\">D\u00e1 nova reda\u00e7\u00e3o ao par\u00e1grafo \u00fanico do art. 1o da Lei no 14.072, de 28 de dezembro de 2001.<br \/>\nA ASSEMBL\u00c9IA LEGISLATIVA DO ESTADO DE GOI\u00c1S, nos termos do art. 10 da Constitui\u00e7\u00e3o Estadual, decreta e eu sanciono a seguinte Lei:<\/p>\n<p style=\"text-align: justify;\">Art. 1o O par\u00e1grafo \u00fanico do art. 1o da Lei no 14.072, de 28 de dezembro de 2001, passa a vigorar com a seguinte reda\u00e7\u00e3o:<\/p>\n<p style=\"text-align: justify;\">\u201cArt. 1o &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..<\/p>\n<p style=\"text-align: justify;\">Par\u00e1grafo \u00fanico. A comunica\u00e7\u00e3o referida no caput deste artigo ser\u00e1 efetivada por uma das seguintes formas, a crit\u00e9rio do credor:<\/p>\n<p style=\"text-align: justify;\">I &#8211; mediante correspond\u00eancia, via correio, com comprovante de envio, a ser encaminhada para o endere\u00e7o que o consumidor tiver declarado no ato da compra ou da aquisi\u00e7\u00e3o do servi\u00e7o, ou endere\u00e7o que venha a informar ao credor;<\/p>\n<p style=\"text-align: justify;\">II &#8211; pessoalmente ao devedor inadimplente ou ao seu representante, num e noutro caso provada com a assinatura do recebedor no livro ou em ficha de protocolo ou recibo. (NR)<\/p>\n<p style=\"text-align: justify;\">&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..\u201d<\/p>\n<p style=\"text-align: justify;\">Art. 2o Esta Lei entra em vigor na data de sua publica\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">PAL\u00c1CIO DO GOVERNO DO ESTADO DE GOI\u00c1S, em Goi\u00e2nia, 30 de dezembro de 2003, 115o da Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">MARCONI FERREIRA PERILLO J\u00daNIOR<br \/>\nWalter Jos\u00e9 Rodrigues<\/p>\n<p style=\"text-align: justify;\">(D.O de 30-12-2003)<\/p>\n<p style=\"text-align: justify;\">Este texto n\u00e3o substitui o publicado no D.O. de 30.12.2003.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e1 nova reda\u00e7\u00e3o ao par\u00e1grafo \u00fanico do art. 1o da Lei no 14.072, de 28 de dezembro de 2001. (Cadastro de consumidores)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[312,141,6,414,5],"class_list":["post-1524","post","type-post","status-publish","format-standard","hentry","category-legislacao-estadual","tag-cadastro","tag-consumidor","tag-goias","tag-lei-estadual","tag-procon"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"rogerioduarte","author_link":"https:\/\/goias.gov.br\/procon\/author\/rogerioduarte\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/procon\/categoria\/legislacao\/legislacao-estadual\/\" rel=\"category tag\">Legisla\u00e7\u00e3o Estadual<\/a>","rttpg_excerpt":"D\u00e1 nova reda\u00e7\u00e3o ao par\u00e1grafo \u00fanico do art. 1o da Lei no 14.072, de 28 de dezembro de 2001. (Cadastro de consumidores)","_links":{"self":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts\/1524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/comments?post=1524"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/posts\/1524\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/media?parent=1524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/categories?post=1524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/procon\/wp-json\/wp\/v2\/tags?post=1524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}