

{"id":58024,"date":"2023-03-31T12:06:03","date_gmt":"2023-03-31T15:06:03","guid":{"rendered":"https:\/\/goias.gov.br\/policiamilitar\/?p=58024"},"modified":"2023-03-31T12:06:34","modified_gmt":"2023-03-31T15:06:34","slug":"delivery-do-trafico-6o-bpm-detem-motociclista-com-drogas","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiamilitar\/delivery-do-trafico-6o-bpm-detem-motociclista-com-drogas\/","title":{"rendered":"Delivery do tr\u00e1fico: 6\u00ba BPM det\u00e9m motociclista com drogas"},"content":{"rendered":"<p style=\"text-align: justify\">Ap\u00f3s receber den\u00fancias de que um homem em uma moto CG preta, estaria traficando drogas na regi\u00e3o do Setor Marista, equipes do Batalh\u00e3o Anhanguera conseguiram abordar na tarde de quinta-feira (30\/03) pr\u00f3ximo a Av 85 no Setor Marista, indiv\u00edduo com as mesmas caracter\u00edsticas.<\/p>\n<p style=\"text-align: justify\">Ao ser realizada a abordagem nada foi encontrado no ba\u00fa da moto, contudo um odor forte e caracter\u00edstico da coca\u00edna chamou a aten\u00e7\u00e3o dos policiais, que ao seguirem seu tiroc\u00ednio policial encontraram um compartimento secreto no fundo do ba\u00fa, escondendo 50 por\u00e7\u00f5es de coca\u00edna, a quantia de R$ 100,00 e uma m\u00e1quina de cart\u00e3o.<\/p>\n<p style=\"text-align: justify\">O rapaz de 23 anos disse que comprou o ba\u00fa j\u00e1 com o compartimento de um conhecido e que j\u00e1 utilizava esse esconderijo h\u00e1 alguns meses. Cabe ressaltar que o entregador j\u00e1 possui 07 antecedentes criminais por tr\u00e1fico enquanto menor de idade e mais 02 pelo mesmo crime, ap\u00f3s atingir a maioridade.<\/p>\n<p style=\"text-align: justify\">Pol\u00edcia Militar de Goi\u00e1s: Patrim\u00f4nio dos Goianos!<\/p>\n<p style=\"text-align: justify\">Fonte: 6\u00ba BPM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s receber den\u00fancias de que um homem em uma moto CG preta, estaria traficando drogas na regi\u00e3o do Setor Marista, equipes do Batalh\u00e3o Anhanguera conseguiram abordar na tarde de quinta-feira (30\/03) pr\u00f3ximo a Av 85 no Setor Marista, indiv\u00edduo com as mesmas caracter\u00edsticas. Ao ser realizada a abordagem nada foi encontrado no ba\u00fa da moto, [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58024","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"adriano.vieira@goias.gov.br","author_link":"https:\/\/goias.gov.br\/policiamilitar\/author\/adriano-vieiragoias-gov-br\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiamilitar\/categoria\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Ap\u00f3s receber den\u00fancias de que um homem em uma moto CG preta, estaria traficando drogas na regi\u00e3o do Setor Marista, equipes do Batalh\u00e3o Anhanguera conseguiram abordar na tarde de quinta-feira (30\/03) pr\u00f3ximo a Av 85 no Setor Marista, indiv\u00edduo com as mesmas caracter\u00edsticas. Ao ser realizada a abordagem nada foi encontrado no ba\u00fa da moto,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/posts\/58024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/comments?post=58024"}],"version-history":[{"count":3,"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/posts\/58024\/revisions"}],"predecessor-version":[{"id":58033,"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/posts\/58024\/revisions\/58033"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/media?parent=58024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/categories?post=58024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiamilitar\/wp-json\/wp\/v2\/tags?post=58024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}