

{"id":82126,"date":"2020-07-22T08:00:14","date_gmt":"2020-07-22T11:00:14","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=82126"},"modified":"2020-07-22T10:30:27","modified_gmt":"2020-07-22T13:30:27","slug":"suspeito-de-tentativa-de-homicidio-e-preso-e-tambem-autuado-em-flagrante-por-posse-de-armas-em-ipameri","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/suspeito-de-tentativa-de-homicidio-e-preso-e-tambem-autuado-em-flagrante-por-posse-de-armas-em-ipameri\/","title":{"rendered":"Suspeito de tentativa de homic\u00eddio \u00e9 preso e tamb\u00e9m autuado em flagrante por posse de armas em Ipameri"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-82127 alignleft\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-500x375.jpeg\" alt=\"\" width=\"339\" height=\"254\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-500x375.jpeg 500w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-768x576.jpeg 768w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-80x60.jpeg 80w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-160x120.jpeg 160w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-265x198.jpeg 265w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-530x396.jpeg 530w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-696x522.jpeg 696w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00.jpeg 1032w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-560x420.jpeg 560w\" sizes=\"(max-width: 339px) 100vw, 339px\" \/>A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia de Pol\u00edcia (DP) de Ipameri, na segunda-feira 20, efetuou o cumprimento de mandados de pris\u00e3o preventiva e de busca domiciliar expedidos em desfavor de um investigado, de 40 anos de idade.<\/p>\n<p style=\"text-align: justify;\">Conforme consta de inqu\u00e9rito policial, no dia 12 de julho, o investigado praticou tentativa de homic\u00eddio, na sua resid\u00eancia, contra a v\u00edtima de 19 anos, a qual foi agredida com grande viol\u00eancia com um cabo de madeira. A v\u00edtima ficou com v\u00e1rias les\u00f5es, como um bra\u00e7o quebrado e traumatismo craniano, e foi hospitalizada na UTI por alguns dias. O motivo est\u00e1 ligado a um relacionamento da v\u00edtima com uma familiar do investigado que este n\u00e3o consentiu.<\/p>\n<p style=\"text-align: justify;\">Durante a investiga\u00e7\u00e3o, a Pol\u00edcia Civil representou pela pris\u00e3o e busca na resid\u00eancia do investigado. As buscas foram cumpridas ap\u00f3s o deferimento pelo Poder Judici\u00e1rio local, quando foram apreendidas 03 espingardas, muni\u00e7\u00f5es, o cabo de madeira utilizado na tentativa de homic\u00eddio e elevada quantidade de armas brancas.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m do mandado de pris\u00e3o cumprido, o investigado ainda foi autuado em flagrante delito pelo crime de posse ilegal de armas de fogo e muni\u00e7\u00f5es. Ele foi encaminhado ao sistema prisional \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a. Os inqu\u00e9ritos policiais ser\u00e3o finalizados no prazo legal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia de Pol\u00edcia (DP) de Ipameri, na segunda-feira 20, efetuou o cumprimento de mandados de pris\u00e3o preventiva e de busca domiciliar expedidos em desfavor de um investigado, de 40 anos de idade. Conforme consta de inqu\u00e9rito policial, no dia 12 de julho, o investigado praticou tentativa de [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":82127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3196,2538,6069],"tags":[143,1697,6549,4143],"class_list":["post-82126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-9a-regional","category-delegacias","category-noticias-da-policia-civil","tag-investigacao","tag-ipameri","tag-posse-de-armas","tag-tentativa-de-homicidio"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00.jpeg",1032,774,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00.jpeg",1032,774,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00.jpeg",1032,774,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-300x300.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00-500x375.jpeg",300,225,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00.jpeg",1024,768,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00.jpeg",1032,774,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2020\/07\/whatsapp-image-2020-07-21-at-15.00.00.jpeg",1032,774,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/9a-regional\/\" rel=\"category tag\">9\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/noticias\/noticias-da-policia-civil\/\" rel=\"category tag\">Not\u00edcias da Pol\u00edcia Civil<\/a>","rttpg_excerpt":"A Pol\u00edcia Civil de Goi\u00e1s, por meio da Delegacia de Pol\u00edcia (DP) de Ipameri, na segunda-feira 20, efetuou o cumprimento de mandados de pris\u00e3o preventiva e de busca domiciliar expedidos em desfavor de um investigado, de 40 anos de idade. Conforme consta de inqu\u00e9rito policial, no dia 12 de julho, o investigado praticou tentativa de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/82126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=82126"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/82126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/82127"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=82126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=82126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=82126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}