{"id":78358,"date":"2019-11-20T17:47:00","date_gmt":"2019-11-20T20:47:00","guid":{"rendered":" https:\/\/goias.gov.br\/policiacivil\/?p=78358"},"modified":"2019-11-20T17:47:00","modified_gmt":"2019-11-20T20:47:00","slug":"5a-ddp-de-aparecida-de-goiania-prende-suspeito-de-assaltos-a-comercio","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/policiacivil\/5a-ddp-de-aparecida-de-goiania-prende-suspeito-de-assaltos-a-comercio\/","title":{"rendered":"5\u00aa DDP de Aparecida de Goi\u00e2nia prende suspeito de assaltos a com\u00e9rcio"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-78359 alignright\" src=\" https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf-389x500.jpg\" alt=\"\" width=\"217\" height=\"279\" srcset=\"https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf-389x500.jpg 389w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf-327x420.jpg 327w, https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf.jpg 629w\" sizes=\"(max-width: 217px) 100vw, 217px\" \/>A Pol\u00edcia Civil do Estado de Goi\u00e1s, por meio da equipe da 5\u00aa Delegacia Distrital de Pol\u00edcia (DDP) de Aparecida de Goi\u00e2nia, coordenada pelo Delegado Carlos Levergger, cumpriu mandando de pris\u00e3o preventiva contra L. R. F., 43 anos. Ele \u00e9 investigado por diversos assaltos a estabelecimentos, como restaurantes e lanchonetes, com uso de arma de fogo. A pris\u00e3o foi cumprida nessa ter\u00e7a-feira (19), no Recanto dos Emboabas, em Aparecida de Goi\u00e2nia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil do Estado de Goi\u00e1s, por meio da equipe da 5\u00aa Delegacia Distrital de Pol\u00edcia (DDP) de Aparecida de Goi\u00e2nia, coordenada pelo Delegado Carlos Levergger, cumpriu mandando de pris\u00e3o preventiva contra L. R. F., 43 anos. Ele \u00e9 investigado por diversos assaltos a estabelecimentos, como restaurantes e lanchonetes, com uso de arma de [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":78359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3189,2538,94,537],"tags":[234,3481,3227,6456],"class_list":["post-78358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2a-regional","category-delegacias","category-distritais","category-ultimo-segundo","tag-aparecida-de-goiania","tag-assaltante","tag-comercio","tag-prisao-preventiva"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf.jpg",629,808,false],"landscape":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf.jpg",629,808,false],"portraits":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf.jpg",629,808,false],"thumbnail":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf-300x300.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf-389x500.jpg",233,300,true],"large":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf.jpg",629,808,false],"1536x1536":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf.jpg",629,808,false],"2048x2048":["https:\/\/goias.gov.br\/policiacivil\/wp-content\/uploads\/sites\/71\/2019\/11\/lrf.jpg",629,808,false]},"rttpg_author":{"display_name":"celsoassis","author_link":"https:\/\/goias.gov.br\/policiacivil\/author\/celsoassis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/drp\/2a-regional\/\" rel=\"category tag\">2\u00aa Regional<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/\" rel=\"category tag\">Delegacias<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/delegacias\/distritais\/\" rel=\"category tag\">Distritais<\/a> <a href=\"https:\/\/goias.gov.br\/policiacivil\/categoria\/ultimo-segundo\/\" rel=\"category tag\">\u00daltimo Segundo<\/a>","rttpg_excerpt":"A Pol\u00edcia Civil do Estado de Goi\u00e1s, por meio da equipe da 5\u00aa Delegacia Distrital de Pol\u00edcia (DDP) de Aparecida de Goi\u00e2nia, coordenada pelo Delegado Carlos Levergger, cumpriu mandando de pris\u00e3o preventiva contra L. R. F., 43 anos. Ele \u00e9 investigado por diversos assaltos a estabelecimentos, como restaurantes e lanchonetes, com uso de arma de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/78358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/comments?post=78358"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/posts\/78358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media\/78359"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/media?parent=78358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/categories?post=78358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/policiacivil\/wp-json\/wp\/v2\/tags?post=78358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}